{"id":97569,"date":"2023-12-26T09:00:54","date_gmt":"2023-12-26T14:00:54","guid":{"rendered":"https:\/\/wfh.org\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/"},"modified":"2024-04-03T12:22:28","modified_gmt":"2024-04-03T16:22:28","slug":"des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables","status":"publish","type":"post","link":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/","title":{"rendered":"Des vid\u00e9os du Programme d\u2019aide humanitaire de la FMH montrent la mise en place de soins durables"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"97569\" class=\"elementor elementor-97569 elementor-97460\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df29307 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df29307\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-700d80f\" data-id=\"700d80f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66ab3b9 elementor-widget elementor-widget-text-editor\" data-id=\"66ab3b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alors que 2023 s\u2019ach\u00e8ve, nous avons rassembl\u00e9 ici 11 vid\u00e9os du <a href=\"https:\/\/wfh.org\/fr\/article\/constater-la-difference-sur-le-terrain-le-programme-daide-humanitaire-et-son-action-en-indonesie\/\" target=\"_blank\" rel=\"noopener\">Programme d\u2019aide humanitaire<\/a>. Si vous ne les avez pas d\u00e9j\u00e0 vues, ou si vous souhaitez les visionner \u00e0 nouveau, nous vous encourageons \u00e0 y jeter un \u0153il\u00a0; vous constaterez que les efforts de la FMH pour aider les pays \u00e0 rendre les soins durables pour les personnes atteints d\u2019un trouble de la coagulation portent leurs fruits.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08ba9c3 elementor-widget elementor-widget-heading\" data-id=\"08ba9c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Indon\u00e9sie<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa9a760 elementor-widget elementor-widget-video\" data-id=\"fa9a760\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/bS79v4xBFyk&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-945da16 elementor-widget elementor-widget-heading\" data-id=\"945da16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">S\u00e9n\u00e9gal<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1e38fe elementor-widget elementor-widget-video\" data-id=\"b1e38fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/Fuh0mN6Fhvo&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc9b794 elementor-widget elementor-widget-video\" data-id=\"dc9b794\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/ditu_60WB3o&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d3a3dc elementor-widget elementor-widget-heading\" data-id=\"7d3a3dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00e9publique dominicaine<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb3793f elementor-widget elementor-widget-video\" data-id=\"cb3793f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/UL4soDeZ3y0&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea6f3b6 elementor-widget elementor-widget-video\" data-id=\"ea6f3b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/YPnd-_kiHQ8&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b57ff3 elementor-widget elementor-widget-heading\" data-id=\"9b57ff3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sri Lanka<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7941ab3 elementor-widget elementor-widget-video\" data-id=\"7941ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/Q-SDOPVe6_I&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b67d7ec elementor-widget elementor-widget-video\" data-id=\"b67d7ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/I6XDHbKMu8I&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d3df5e elementor-widget elementor-widget-heading\" data-id=\"7d3df5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Inde<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8c835b elementor-widget elementor-widget-video\" data-id=\"e8c835b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/ILAeoSrceu0&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0feac4b elementor-widget elementor-widget-heading\" data-id=\"0feac4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Liban<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f86bbf elementor-widget elementor-widget-video\" data-id=\"7f86bbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/RVK6ihRBnYQ&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96fb2a0 elementor-widget elementor-widget-video\" data-id=\"96fb2a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/6k4VYlUmZlc&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-041c020 elementor-widget elementor-widget-text-editor\" data-id=\"041c020\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Depuis 2015, plus de 1,6 million d\u2019UI de facteur (et des millions d\u2019UI de traitements de substitution) ont \u00e9t\u00e9 donn\u00e9s \u00e0 des pays dans le monde entier. Pour en savoir plus sur le Programme d\u2019aide humanitaire de la FMH, <a href=\"https:\/\/wfh.org\/fr\/aide-humanitaire\/\" target=\"_blank\" rel=\"noopener\">cliquez ici<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b96da2 elementor-widget elementor-widget-heading\" data-id=\"8b96da2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c0 propos du Programme d\u2019aide humanitaire de la FMH<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d990ed9 elementor-widget elementor-widget-text-editor\" data-id=\"d990ed9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le Programme d\u2019aide humanitaire de la FMH am\u00e9liore l\u2019acc\u00e8s aux soins et aux traitements en fournissant un soutien essentiel aux personnes atteintes de troubles h\u00e9r\u00e9ditaires de la coagulation dans les pays en d\u00e9veloppement. En apportant aux patient\u00b7es un flux plus r\u00e9gulier et plus pr\u00e9visible de dons humanitaires, le Programme d\u2019aide humanitaire de la FMH leur permet un acc\u00e8s constant et fiable aux traitements et aux soins. Rien de tout cela ne serait possible sans le g\u00e9n\u00e9reux soutien de Sanofi et Sobi, nos Donateurs visionnaires fondateurs ; de Bayer, CSL Behring et Roche, nos Donateurs visionnaires ; de Grifols, notre Donateur encadrant, et de Takeda et la Japan Blood Product Organization, nos Donateurs contributeurs. Pour plus d\u2019informations sur le Programme d\u2019aide humanitaire de la FMH, consultez le site\u00a0<a href=\"http:\/\/www.treatmentforall.org\/\" target=\"_blank\" rel=\"noopener\">www.treatmentforall.org<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-391c7ad elementor-widget elementor-widget-image\" data-id=\"391c7ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wfh.org\/fr\/aide-humanitaire\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"786\" height=\"343\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png\" class=\"attachment-full size-full wp-image-28201\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png 786w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-192x84.png 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-768x335.png 768w\" sizes=\"(max-width: 786px) 100vw, 786px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie (FMH) fournit des soins aux personnes atteintes d\u2019un trouble de la coagulation dans le monde entier. L\u2019an dernier, elle a publi\u00e9 11 vid\u00e9os montrant l\u2019impact du Programme d\u2019aide humanitaire sur la vie des gens. Chacune de ces vid\u00e9os raconte l\u2019histoire de personnes atteintes d\u2019un trouble de la coagulation, de leurs familles, de professionnel\u00b7les de sant\u00e9, de membres des \u00e9quipes des organisations nationales membres (ONM) et d\u2019autres parties prenantes. Chacun de ces r\u00e9cits nous encourage et nous inspire.<\/p>\n","protected":false},"author":13,"featured_media":49119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[184],"tags":[],"search-category":[85],"class_list":["post-97569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programme-daide-humanitaire-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Des vid\u00e9os du Programme d\u2019aide humanitaire de la FMH montrent la mise en place de soins durables | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des vid\u00e9os du Programme d\u2019aide humanitaire de la FMH montrent la mise en place de soins durables\" \/>\n<meta property=\"og:description\" content=\"La F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie (FMH) fournit des soins aux personnes atteintes d\u2019un trouble de la coagulation dans le monde entier. L\u2019an dernier, elle a publi\u00e9 11 vid\u00e9os montrant l\u2019impact du Programme d\u2019aide humanitaire sur la vie des gens. Chacune de ces vid\u00e9os raconte l\u2019histoire de personnes atteintes d\u2019un trouble de la coagulation, de leurs familles, de professionnel\u00b7les de sant\u00e9, de membres des \u00e9quipes des organisations nationales membres (ONM) et d\u2019autres parties prenantes. Chacun de ces r\u00e9cits nous encourage et nous inspire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-26T14:00:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-03T16:22:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/HA-stock-image-2-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Des vid\u00e9os du Programme d\u2019aide humanitaire de la FMH montrent la mise en place de soins durables\",\"datePublished\":\"2023-12-26T14:00:54+00:00\",\"dateModified\":\"2024-04-03T16:22:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/\"},\"wordCount\":344,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/HA-stock-image-2-header.jpg\",\"articleSection\":[\"Programme d\u2019aide humanitaire de la FMH\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/\",\"name\":\"Des vid\u00e9os du Programme d\u2019aide humanitaire de la FMH montrent la mise en place de soins durables | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/HA-stock-image-2-header.jpg\",\"datePublished\":\"2023-12-26T14:00:54+00:00\",\"dateModified\":\"2024-04-03T16:22:28+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/HA-stock-image-2-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/HA-stock-image-2-header.jpg\",\"width\":1200,\"height\":627,\"caption\":\"WFH Humanitarian Aid Program\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"name\":\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Des vid\u00e9os du Programme d\u2019aide humanitaire de la FMH montrent la mise en place de soins durables | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/","og_locale":"fr_FR","og_type":"article","og_title":"Des vid\u00e9os du Programme d\u2019aide humanitaire de la FMH montrent la mise en place de soins durables","og_description":"La F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie (FMH) fournit des soins aux personnes atteintes d\u2019un trouble de la coagulation dans le monde entier. L\u2019an dernier, elle a publi\u00e9 11 vid\u00e9os montrant l\u2019impact du Programme d\u2019aide humanitaire sur la vie des gens. Chacune de ces vid\u00e9os raconte l\u2019histoire de personnes atteintes d\u2019un trouble de la coagulation, de leurs familles, de professionnel\u00b7les de sant\u00e9, de membres des \u00e9quipes des organisations nationales membres (ONM) et d\u2019autres parties prenantes. Chacun de ces r\u00e9cits nous encourage et nous inspire.","og_url":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/","og_site_name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2023-12-26T14:00:54+00:00","article_modified_time":"2024-04-03T16:22:28+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/HA-stock-image-2-header.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mitch Semienchuk","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Des vid\u00e9os du Programme d\u2019aide humanitaire de la FMH montrent la mise en place de soins durables","datePublished":"2023-12-26T14:00:54+00:00","dateModified":"2024-04-03T16:22:28+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/"},"wordCount":344,"publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/HA-stock-image-2-header.jpg","articleSection":["Programme d\u2019aide humanitaire de la FMH"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/","url":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/","name":"Des vid\u00e9os du Programme d\u2019aide humanitaire de la FMH montrent la mise en place de soins durables | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/HA-stock-image-2-header.jpg","datePublished":"2023-12-26T14:00:54+00:00","dateModified":"2024-04-03T16:22:28+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/article\/des-videos-du-programme-daide-humanitaire-de-la-fmh-montrent-la-mise-en-place-de-soins-durables\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/HA-stock-image-2-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/HA-stock-image-2-header.jpg","width":1200,"height":627,"caption":"WFH Humanitarian Aid Program"},{"@type":"WebSite","@id":"https:\/\/wfh.org\/fr\/#website","url":"https:\/\/wfh.org\/fr\/","name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wfh.org\/fr\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/97569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/comments?post=97569"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/97569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media\/49119"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media?parent=97569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/categories?post=97569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/tags?post=97569"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/search-category?post=97569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}