{"id":56781,"date":"2023-02-14T04:00:45","date_gmt":"2023-02-14T09:00:45","guid":{"rendered":"https:\/\/wfh.org\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/"},"modified":"2026-03-12T10:00:34","modified_gmt":"2026-03-12T14:00:34","slug":"journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles","status":"publish","type":"post","link":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/","title":{"rendered":"Journ\u00e9e mondiale de l\u2019h\u00e9mophilie : des ressources pour les r\u00e9seaux sociaux d\u00e9j\u00e0 disponibles !"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"56781\" class=\"elementor elementor-56781 elementor-56155\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8cd4ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8cd4ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de090d5\" data-id=\"de090d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b37ae5 elementor-widget elementor-widget-text-editor\" data-id=\"2b37ae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour vous aider \u00e0 attirer l\u2019attention au sein de la communaut\u00e9 locale et mondiale sur l\u2019h\u00e9mophilie et les troubles h\u00e9r\u00e9ditaires de la coagulation en cette <a href=\"https:\/\/wfh.org\/fr\/journee-mondiale-de-lhemophilie\/\" target=\"_blank\" rel=\"noopener\">Journ\u00e9e mondiale de l\u2019h\u00e9mophilie<\/a>, la FMH vous propose des ressources gratuites \u00e0 t\u00e9l\u00e9charger pour partager les actualit\u00e9s de cette journ\u00e9e avec vos ami\u00b7es, votre famille et les personnes de votre r\u00e9gion. Ces ressources comprennent notamment un kit de plaidoyer pour les r\u00e9seaux sociaux, qui vous aidera \u00e0 entrer en contact avec les autorit\u00e9s locales, un mod\u00e8le de p\u00e9tition \u00e0 adresser \u00e0 un ou une responsable politique et vous permettre de faire des demandes \u00e9crites aupr\u00e8s d\u2019un ou une repr\u00e9sentante locale, et bien d\u2019autres outils \u00e0 utiliser sur les r\u00e9seaux sociaux.<\/p>\n<p>Voici la liste compl\u00e8te <a href=\"https:\/\/wfh.org\/fr\/journee-mondiale-de-lhemophilie\/\" target=\"_blank\" rel=\"noopener\">des \u00e9l\u00e9ments t\u00e9l\u00e9chargeables<\/a> pour vous aider \u00e0 augmenter l\u2019impact de cette journ\u00e9e du 17 avril. Tous les contenus sont disponibles en anglais, espagnol et fran\u00e7ais. Beaucoup d\u2019entre eux sont d\u00e9j\u00e0 en ligne.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a6df5d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1a6df5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Affiche<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Prospectus<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Logo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kit de plaidoyer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Images pour les r\u00e9seaux sociaux<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cadres pour photo de profil sur les r\u00e9seaux sociaux<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Arri\u00e8re-plan Zoom<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Banni\u00e8res<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lettre \u00c9clairez tout en rouge<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mod\u00e8le de p\u00e9tition \u00e0 adresser \u00e0 un\u00b7e responsable politique<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Communiqu\u00e9 de presse (\u00e0 venir le1er avril)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7958349 elementor-widget elementor-widget-text-editor\" data-id=\"7958349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour en savoir plus sur la Journ\u00e9e mondiale de l\u2019h\u00e9mophilie 2023, <a href=\"https:\/\/wfh.org\/fr\/journee-mondiale-de-lhemophilie\/\" target=\"_blank\" rel=\"noopener\">cliquez ici<\/a>.<\/p>\n<p>Rejoignez le combat pour un acc\u00e8s \u00e9quitable aux soins pour les personnes atteintes d\u2019h\u00e9mophilie et d\u2019autres troubles h\u00e9r\u00e9ditaires de la coagulation\u00a0: montrez votre soutien \u00e0 l\u2019occasion de la Journ\u00e9e mondiale de l\u2019h\u00e9mophilie. Votre contribution permettra de financer la cr\u00e9ation de ressources gratuites pour sensibiliser les responsables politiques \u00e0 ces maladies, tout comme la communaut\u00e9 mondiale. Rendez-vous sur <a href=\"https:\/\/give.wfh.org\/fr\/\" target=\"_blank\" rel=\"noopener\">give.wfh.org<\/a> pour faire une don d\u00e8s maintenant et nous aider \u00e0 construire un avenir meilleur pour toutes les personnes touch\u00e9es par les troubles de la coagulation.<\/p>\n<p><em>a FMH tient \u00e0 remercier les sponsors de la Journ\u00e9e mondiale de l\u2019h\u00e9mophilie 2023 pour leur soutien :\u00a0<i>Bayer, BioMarin Pharmaceutical Inc., Biotest, CSL Behring, F. Hoffman-La Roche Ltd., Freeline Therapeutics, GC Pharma, Grifols, Kedrion, LFB S.A, Novo Nordisk, Octapharma, Pfizer, Sanofi, Sobi, Spark Therapeutics, et Takeda.<\/i><\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u2019ici quelques mois, le monde entier c\u00e9l\u00e8brera la Journ\u00e9e mondiale de l\u2019h\u00e9mophilie. Le th\u00e8me cette ann\u00e9e est \u00ab Acc\u00e8s pour tous : la pr\u00e9vention des saignements comme standard mondial de soins \u00bb. En poursuivant la r\u00e9flexion \u00e0 partir du th\u00e8me de l\u2019an dernier, nous lan\u00e7ons pour 2023 l\u2019appel \u00e0 l\u2019action suivant pour la communaut\u00e9 : se rassembler et mener des actions de plaidoyer aupr\u00e8s des responsables politiques et des gouvernements locaux pour am\u00e9liorer l\u2019acc\u00e8s aux traitements et aux soins, en mettant l\u2019accent sur un meilleur contr\u00f4le et une meilleure pr\u00e9vention des saignements chez toutes les personnes atteintes d\u2019un trouble de la coagulation. Cela passe par la mise en place de traitements \u00e0 domicile ainsi que par des traitements prophylactiques, pour aider les personnes concern\u00e9es \u00e0 am\u00e9liorer leur qualit\u00e9 de vie.<\/p>\n","protected":false},"author":13,"featured_media":56146,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[169,150],"tags":[],"search-category":[85],"class_list":["post-56781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-2","category-world-hemophilia-day","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Journ\u00e9e mondiale de l\u2019h\u00e9mophilie : des ressources pour les r\u00e9seaux sociaux d\u00e9j\u00e0 disponibles ! | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journ\u00e9e mondiale de l\u2019h\u00e9mophilie : des ressources pour les r\u00e9seaux sociaux d\u00e9j\u00e0 disponibles !\" \/>\n<meta property=\"og:description\" content=\"D\u2019ici quelques mois, le monde entier c\u00e9l\u00e8brera la Journ\u00e9e mondiale de l\u2019h\u00e9mophilie. Le th\u00e8me cette ann\u00e9e est \u00ab Acc\u00e8s pour tous : la pr\u00e9vention des saignements comme standard mondial de soins \u00bb. En poursuivant la r\u00e9flexion \u00e0 partir du th\u00e8me de l\u2019an dernier, nous lan\u00e7ons pour 2023 l\u2019appel \u00e0 l\u2019action suivant pour la communaut\u00e9 : se rassembler et mener des actions de plaidoyer aupr\u00e8s des responsables politiques et des gouvernements locaux pour am\u00e9liorer l\u2019acc\u00e8s aux traitements et aux soins, en mettant l\u2019accent sur un meilleur contr\u00f4le et une meilleure pr\u00e9vention des saignements chez toutes les personnes atteintes d\u2019un trouble de la coagulation. Cela passe par la mise en place de traitements \u00e0 domicile ainsi que par des traitements prophylactiques, pour aider les personnes concern\u00e9es \u00e0 am\u00e9liorer leur qualit\u00e9 de vie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-14T09:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T14:00:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2023\/02\/WHD-SM-toolkit-header-FR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Journ\u00e9e mondiale de l\u2019h\u00e9mophilie : des ressources pour les r\u00e9seaux sociaux d\u00e9j\u00e0 disponibles !\",\"datePublished\":\"2023-02-14T09:00:45+00:00\",\"dateModified\":\"2026-03-12T14:00:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/\"},\"wordCount\":399,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/WHD-SM-toolkit-header-FR.jpg\",\"articleSection\":[\"Events\",\"World Hemophilia Day\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/\",\"name\":\"Journ\u00e9e mondiale de l\u2019h\u00e9mophilie : des ressources pour les r\u00e9seaux sociaux d\u00e9j\u00e0 disponibles ! | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/WHD-SM-toolkit-header-FR.jpg\",\"datePublished\":\"2023-02-14T09:00:45+00:00\",\"dateModified\":\"2026-03-12T14:00:34+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/WHD-SM-toolkit-header-FR.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/WHD-SM-toolkit-header-FR.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"name\":\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Journ\u00e9e mondiale de l\u2019h\u00e9mophilie : des ressources pour les r\u00e9seaux sociaux d\u00e9j\u00e0 disponibles ! | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/","og_locale":"fr_FR","og_type":"article","og_title":"Journ\u00e9e mondiale de l\u2019h\u00e9mophilie : des ressources pour les r\u00e9seaux sociaux d\u00e9j\u00e0 disponibles !","og_description":"D\u2019ici quelques mois, le monde entier c\u00e9l\u00e8brera la Journ\u00e9e mondiale de l\u2019h\u00e9mophilie. Le th\u00e8me cette ann\u00e9e est \u00ab Acc\u00e8s pour tous : la pr\u00e9vention des saignements comme standard mondial de soins \u00bb. En poursuivant la r\u00e9flexion \u00e0 partir du th\u00e8me de l\u2019an dernier, nous lan\u00e7ons pour 2023 l\u2019appel \u00e0 l\u2019action suivant pour la communaut\u00e9 : se rassembler et mener des actions de plaidoyer aupr\u00e8s des responsables politiques et des gouvernements locaux pour am\u00e9liorer l\u2019acc\u00e8s aux traitements et aux soins, en mettant l\u2019accent sur un meilleur contr\u00f4le et une meilleure pr\u00e9vention des saignements chez toutes les personnes atteintes d\u2019un trouble de la coagulation. Cela passe par la mise en place de traitements \u00e0 domicile ainsi que par des traitements prophylactiques, pour aider les personnes concern\u00e9es \u00e0 am\u00e9liorer leur qualit\u00e9 de vie.","og_url":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/","og_site_name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2023-02-14T09:00:45+00:00","article_modified_time":"2026-03-12T14:00:34+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/02\/WHD-SM-toolkit-header-FR.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mitch Semienchuk","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Journ\u00e9e mondiale de l\u2019h\u00e9mophilie : des ressources pour les r\u00e9seaux sociaux d\u00e9j\u00e0 disponibles !","datePublished":"2023-02-14T09:00:45+00:00","dateModified":"2026-03-12T14:00:34+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/"},"wordCount":399,"publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/02\/WHD-SM-toolkit-header-FR.jpg","articleSection":["Events","World Hemophilia Day"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/","url":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/","name":"Journ\u00e9e mondiale de l\u2019h\u00e9mophilie : des ressources pour les r\u00e9seaux sociaux d\u00e9j\u00e0 disponibles ! | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/02\/WHD-SM-toolkit-header-FR.jpg","datePublished":"2023-02-14T09:00:45+00:00","dateModified":"2026-03-12T14:00:34+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/article\/journee-mondiale-de-lhemophilie-des-ressources-pour-les-reseaux-sociaux-deja-disponibles\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/02\/WHD-SM-toolkit-header-FR.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/02\/WHD-SM-toolkit-header-FR.jpg","width":1200,"height":627},{"@type":"WebSite","@id":"https:\/\/wfh.org\/fr\/#website","url":"https:\/\/wfh.org\/fr\/","name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wfh.org\/fr\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/56781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/comments?post=56781"}],"version-history":[{"count":1,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/56781\/revisions"}],"predecessor-version":[{"id":173292,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/56781\/revisions\/173292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media\/56146"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media?parent=56781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/categories?post=56781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/tags?post=56781"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/search-category?post=56781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}