{"id":50516,"date":"2022-11-24T09:00:00","date_gmt":"2022-11-24T14:00:00","guid":{"rendered":"https:\/\/wfh.org\/?p=50516"},"modified":"2026-03-18T11:06:30","modified_gmt":"2026-03-18T15:06:30","slug":"prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre","status":"publish","type":"post","link":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/","title":{"rendered":"Prochain webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en d\u00e9cembre"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"50516\" class=\"elementor elementor-50516 elementor-50503\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7c517e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7c517e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b01ccf\" data-id=\"7b01ccf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-947ce03 elementor-widget elementor-widget-text-editor\" data-id=\"947ce03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/1116600722874\/WN_hwUJQ9UcQkaKLvzbV5Xcmg\">L\u2019\u00e9v\u00e9nement<\/a> se tiendra le jeudi 15 d\u00e9cembr 2022 de 8h \u00e0 10h (heure normale de l\u2019Est), et sera pour les participant\u00b7es l\u2019occasion d\u2019avoir des informations concr\u00e8tes sur les troubles de la coagulation\u00a0: r\u00e9silience et m\u00e9ditation, gestion d\u2019articulations trop raides, vieillissement et sport, grossesse chez les femmes atteintes d\u2019un trouble de la coagulation, diagnostic des troubles plaquettaires et derni\u00e8res information sur les modalit\u00e9s de traitement. Les pr\u00e9sentations seront suivies d\u2019une session de questions-r\u00e9ponses.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4e13b34 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e13b34\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9303889\" data-id=\"9303889\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e05a58 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1e05a58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-quote-left\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 256h-80v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8c-88.4 0-160 71.6-160 160v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48zm-288 0H96v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8C71.6 32 0 103.6 0 192v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0a573d0\" data-id=\"0a573d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdb8fbb elementor-widget elementor-widget-heading\" data-id=\"cdb8fbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ce webinaire donnera aux personnes atteintes d\u2019un trouble de la coagulation comme aux professionnel\u00b7les de sant\u00e9 de nouvelles perspectives sur les approches de pointe des soins aujourd\u2019hui. Venez y participer pour en savoir plus et partager vos connaissances avec vos coll\u00e8gues. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e5adbf elementor-widget elementor-widget-heading\" data-id=\"3e5adbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr Glenn Pierce (PhD), vice-pr\u00e9sident m\u00e9dical de la FMH<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e4ebad elementor-widget elementor-widget-text-editor\" data-id=\"9e4ebad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les pr\u00e9sentations se feront en anglais, avec une interpr\u00e9tation simultan\u00e9e en arabe, espagnol, fran\u00e7ais et russe.<\/p>\n<p>Pour vous inscrire, <a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/1116600722874\/WN_hwUJQ9UcQkaKLvzbV5Xcmg\" target=\"_blank\" rel=\"noopener\">cliquez ici<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf81bad elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cf81bad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb03433 elementor-widget elementor-widget-text-editor\" data-id=\"cb03433\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour \u00e9couter les enregistrements des pr\u00e9c\u00e9dentes sessions (disponibles en anglais, fran\u00e7ais, espagnol, arabe et russe), rendez-vous ci-dessous\u00a0:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c501158 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c501158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elearning.wfh.org\/fr\/resource\/formation-pratique-aux-troubles-de-la-coagulation-le-savoir-pour-tous-serie-de-webinaires-de-la-fmh-22-avril-2021\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Webinaire du 22 avril 2021<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elearning.wfh.org\/fr\/resource\/formation-pratique-aux-troubles-de-la-coagulation-le-savoir-pour-tous-serie-de-webinaires-de-la-fmh-27-juillet-2021\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Webinaire du 27 juillet 2021<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elearning.wfh.org\/resource\/formation-pratique-aux-troubles-de-la-coagulation-le-savoir-pour-tous-serie-de-webinaires-de-la-fmh-12-octobre-2021\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Webinaire du 12 octobre 2021<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elearning.wfh.org\/fr\/resource\/formation-pratique-aux-troubles-de-la-coagulation-le-savoir-pour-tous-serie-de-webinaires-de-la-fmh-16-decembre-2021\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Webinaire du 16 d\u00e9cembre 2021<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elearning.wfh.org\/fr\/resource\/formation-pratique-aux-troubles-de-la-coagulation-serie-de-webinaires-de-la-fmh-13-octobre-2022\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Webinaire du 13 octobre 2022<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rejoignez-nous en d\u00e9cembre pour la suite de notre webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en lien avec les troubles de la coagulation. Cet \u00e9v\u00e9nement, le dernier cette ann\u00e9e, donnera aux participant\u00b7es l\u2019opportunit\u00e9 d\u2019acqu\u00e9rir des informations concr\u00e8tes sur les troubles de la coagulation.<\/p>\n","protected":false},"author":13,"featured_media":50505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[49,169,43],"tags":[],"search-category":[85],"class_list":["post-50516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education","category-events-2","category-medical-workshops","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prochain webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en d\u00e9cembre | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prochain webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en d\u00e9cembre\" \/>\n<meta property=\"og:description\" content=\"Rejoignez-nous en d\u00e9cembre pour la suite de notre webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en lien avec les troubles de la coagulation. Cet \u00e9v\u00e9nement, le dernier cette ann\u00e9e, donnera aux participant\u00b7es l\u2019opportunit\u00e9 d\u2019acqu\u00e9rir des informations concr\u00e8tes sur les troubles de la coagulation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-24T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-18T15:06:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/State-of-the-art_Dec-15-webinar-header-FR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Prochain webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en d\u00e9cembre\",\"datePublished\":\"2022-11-24T14:00:00+00:00\",\"dateModified\":\"2026-03-18T15:06:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/\"},\"wordCount\":217,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/State-of-the-art_Dec-15-webinar-header-FR.jpg\",\"articleSection\":[\"Education\",\"Events\",\"Medical workshops\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/\",\"name\":\"Prochain webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en d\u00e9cembre | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/State-of-the-art_Dec-15-webinar-header-FR.jpg\",\"datePublished\":\"2022-11-24T14:00:00+00:00\",\"dateModified\":\"2026-03-18T15:06:30+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/State-of-the-art_Dec-15-webinar-header-FR.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/State-of-the-art_Dec-15-webinar-header-FR.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"name\":\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prochain webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en d\u00e9cembre | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/","og_locale":"fr_FR","og_type":"article","og_title":"Prochain webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en d\u00e9cembre","og_description":"Rejoignez-nous en d\u00e9cembre pour la suite de notre webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en lien avec les troubles de la coagulation. Cet \u00e9v\u00e9nement, le dernier cette ann\u00e9e, donnera aux participant\u00b7es l\u2019opportunit\u00e9 d\u2019acqu\u00e9rir des informations concr\u00e8tes sur les troubles de la coagulation.","og_url":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/","og_site_name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2022-11-24T14:00:00+00:00","article_modified_time":"2026-03-18T15:06:30+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/State-of-the-art_Dec-15-webinar-header-FR.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mitch Semienchuk","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Prochain webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en d\u00e9cembre","datePublished":"2022-11-24T14:00:00+00:00","dateModified":"2026-03-18T15:06:30+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/"},"wordCount":217,"publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/State-of-the-art_Dec-15-webinar-header-FR.jpg","articleSection":["Education","Events","Medical workshops"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/","url":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/","name":"Prochain webinaire p\u00e9dagogique sur l\u2019\u00e9tat des connaissances m\u00e9dicales en d\u00e9cembre | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/State-of-the-art_Dec-15-webinar-header-FR.jpg","datePublished":"2022-11-24T14:00:00+00:00","dateModified":"2026-03-18T15:06:30+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/article\/prochain-webinaire-pedagogique-sur-letat-des-connaissances-medicales-en-decembre\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/State-of-the-art_Dec-15-webinar-header-FR.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/State-of-the-art_Dec-15-webinar-header-FR.jpg","width":1200,"height":627},{"@type":"WebSite","@id":"https:\/\/wfh.org\/fr\/#website","url":"https:\/\/wfh.org\/fr\/","name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wfh.org\/fr\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/50516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/comments?post=50516"}],"version-history":[{"count":2,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/50516\/revisions"}],"predecessor-version":[{"id":174005,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/50516\/revisions\/174005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media\/50505"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media?parent=50516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/categories?post=50516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/tags?post=50516"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/search-category?post=50516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}