{"id":46407,"date":"2020-10-17T09:00:31","date_gmt":"2020-10-17T13:00:31","guid":{"rendered":"https:\/\/wfh.org\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/"},"modified":"2024-04-22T09:46:34","modified_gmt":"2024-04-22T13:46:34","slug":"un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020","status":"publish","type":"post","link":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/","title":{"rendered":"Un nouveau pr\u00e9sident \u00e9lu lors de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"46407\" class=\"elementor elementor-46407 elementor-46386\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49bcd39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49bcd39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-888d616\" data-id=\"888d616\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d753b3 elementor-widget elementor-widget-text-editor\" data-id=\"5d753b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLe scrutin et l\u2019\u00e9v\u00e9nement lui-m\u00eame ont d\u00fb pour la premi\u00e8re fois se tenir \u00e0 distance, \u00e0 cause des restrictions impos\u00e9es par la pand\u00e9mie de COVID-19. Au lieu de donner un discours lors de la r\u00e9union, les candidats et candidates ont post\u00e9 leur biographie, leur CV ainsi que des vid\u00e9os sur une plateforme virtuelle qui a permis aux votant\u00b7es de prendre leur d\u00e9cision. Le vote s\u2019est ensuite tenu en ligne. Bien que le processus soit nouveau, l\u2019esprit de coop\u00e9ration au nom de la communaut\u00e9 des troubles de la coagulation a comme toujours \u00e9t\u00e9 le mot d\u2019ordre de cet \u00e9v\u00e9nement.\r\n<p class=\"\">L\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle a marqu\u00e9 la fin du deuxi\u00e8me mandat d\u2019Alain Weill en tant que pr\u00e9sident de la FMH. C\u2019est Cesar Garrido qui a \u00e9t\u00e9 \u00e9lu pour lui succ\u00e9der. Son mandat commence d\u00e8s aujourd\u2019hui, et Hemophilia World vous donnera dans les jours qui viennent plus d\u2019informations sur l\u2019exp\u00e9rience de M. Garrido et sur ses objectifs en tant que pr\u00e9sident.<\/p>\r\n<p class=\"\">Quelques changements ont \u00e9galement \u00e9t\u00e9 apport\u00e9s au sein du conseil d\u2019administration : deux postes de membres m\u00e9dicaux et trois postes de membres profanes \u00e9taient \u00e0 renouveler. Voici la liste des nouveaux membres qui ont rejoint le conseil d\u2019administration de la FMH lors de cette Assembl\u00e9e g\u00e9n\u00e9rale 2020 :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c968fc elementor-widget elementor-widget-text-editor\" data-id=\"0c968fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table>\r\n<tbody>\r\n<tr>\r\n<th>Poste<\/th>\r\n<th>Nom<\/th>\r\n<th>Dur\u00e9e du mandat<\/th>\r\n<\/tr>\r\n<tr>\r\n<td><strong>President<\/strong><\/td>\r\n<td>Cesar Garrido, (Am\u00e9rique du Sud)<\/td>\r\n<td nowrap=\"nowrap\">Quatre ans<\/td>\r\n<\/tr>\r\n<tr>\r\n<td rowspan=\"2\" nowrap=\"nowrap\"><strong>Membres m\u00e9dicaux<\/strong><\/td>\r\n<td>Miguel Escobar, (Am\u00e9rique du Nord)<\/td>\r\n<td nowrap=\"nowrap\">Quatre ans<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Cedric Hermans, (Europe occidentale)<\/td>\r\n<td nowrap=\"nowrap\">Quatre ans<\/td>\r\n<\/tr>\r\n<tr>\r\n<td rowspan=\"3\"><strong>Membres profanes<\/strong><\/td>\r\n<td>Carlos Safadi Marquez, (Am\u00e9rique du Sud)<\/td>\r\n<td nowrap=\"nowrap\">Quatre ans<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Clive Smith, (Europe occidentale)<\/td>\r\n<td nowrap=\"nowrap\">Deux ans<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Megan Adediran, (Afrique)<\/td>\r\n<td nowrap=\"nowrap\">Quatre ans<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edbac62 elementor-widget elementor-widget-text-editor\" data-id=\"edbac62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\">Douze organisations ont obtenu le statut d\u2019organisations nationales membres (ONM) ou ONM associ\u00e9es, portant le nombre total d\u2019ONM de la FMH \u00e0 147. Les ONM associ\u00e9es \u00e0 la FMH repr\u00e9sentant El Salvador, les Maldives, le Mali, et la Zambie sont toutes devenues des ONM \u00e0 part enti\u00e8re. Des organisations d\u2019Angola, du Botswana, de Djibouti, des Fidji, du Kosovo, de Malte, de la R\u00e9publique d\u00e9mocratique du Congo et du Rwanda sont devenues ONM associ\u00e9es. La FMH est fi\u00e8re d\u2019accueillir ces nouvelles organisations en son sein.<\/p>\r\n<p class=\"\">La FMH tient \u00e0 remercier les membres du conseil d\u2019administration qui nous quittent, Alain Weill, Magdy El Ekiaby, Deon York, Ampaiwan Chuansumrit et Vincent Dumez, pour leur travail acharn\u00e9 et leur d\u00e9vouement en vue d\u2019atteindre le Traitement pour tous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hier a eu lieu l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020 de la F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie (FMH). L\u2019\u00e9v\u00e9nement a \u00e9t\u00e9 l\u2019occasion d\u2019apporter de nombreux changements au sein de la FMH, notamment avec l\u2019\u00e9lection d\u2019un nouveau pr\u00e9sident et de nouveaux membres du conseil d\u2019administration, ainsi qu\u2019avec l\u2019accueil de nouvelles organisations nationales membres (ONM) dans la grande famille de la FMH.<\/p>\n","protected":false},"author":3,"featured_media":15375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[171],"tags":[],"search-category":[85],"class_list":["post-46407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un nouveau pr\u00e9sident \u00e9lu lors de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020 | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un nouveau pr\u00e9sident \u00e9lu lors de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020\" \/>\n<meta property=\"og:description\" content=\"Hier a eu lieu l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020 de la F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie (FMH). L\u2019\u00e9v\u00e9nement a \u00e9t\u00e9 l\u2019occasion d\u2019apporter de nombreux changements au sein de la FMH, notamment avec l\u2019\u00e9lection d\u2019un nouveau pr\u00e9sident et de nouveaux membres du conseil d\u2019administration, ainsi qu\u2019avec l\u2019accueil de nouvelles organisations nationales membres (ONM) dans la grande famille de la FMH.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-17T13:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-22T13:46:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/09\/WFH_FR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Electra Rozakis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Electra Rozakis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/\"},\"author\":{\"name\":\"Electra Rozakis\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\"},\"headline\":\"Un nouveau pr\u00e9sident \u00e9lu lors de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020\",\"datePublished\":\"2020-10-17T13:00:31+00:00\",\"dateModified\":\"2024-04-22T13:46:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/\"},\"wordCount\":437,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WFH_FR.png\",\"articleSection\":[\"Actualit\u00e9s de la FMH\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/\",\"name\":\"Un nouveau pr\u00e9sident \u00e9lu lors de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020 | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WFH_FR.png\",\"datePublished\":\"2020-10-17T13:00:31+00:00\",\"dateModified\":\"2024-04-22T13:46:34+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WFH_FR.png\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WFH_FR.png\",\"width\":620,\"height\":400},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"name\":\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\",\"name\":\"Electra Rozakis\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un nouveau pr\u00e9sident \u00e9lu lors de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020 | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/","og_locale":"fr_FR","og_type":"article","og_title":"Un nouveau pr\u00e9sident \u00e9lu lors de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020","og_description":"Hier a eu lieu l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020 de la F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie (FMH). L\u2019\u00e9v\u00e9nement a \u00e9t\u00e9 l\u2019occasion d\u2019apporter de nombreux changements au sein de la FMH, notamment avec l\u2019\u00e9lection d\u2019un nouveau pr\u00e9sident et de nouveaux membres du conseil d\u2019administration, ainsi qu\u2019avec l\u2019accueil de nouvelles organisations nationales membres (ONM) dans la grande famille de la FMH.","og_url":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/","og_site_name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2020-10-17T13:00:31+00:00","article_modified_time":"2024-04-22T13:46:34+00:00","og_image":[{"width":620,"height":400,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/09\/WFH_FR.png","type":"image\/png"}],"author":"Electra Rozakis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Electra Rozakis","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/"},"author":{"name":"Electra Rozakis","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887"},"headline":"Un nouveau pr\u00e9sident \u00e9lu lors de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020","datePublished":"2020-10-17T13:00:31+00:00","dateModified":"2024-04-22T13:46:34+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/"},"wordCount":437,"publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/09\/WFH_FR.png","articleSection":["Actualit\u00e9s de la FMH"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/","url":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/","name":"Un nouveau pr\u00e9sident \u00e9lu lors de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale annuelle 2020 | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/09\/WFH_FR.png","datePublished":"2020-10-17T13:00:31+00:00","dateModified":"2024-04-22T13:46:34+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/article\/un-nouveau-president-elu-lors-de-lassemblee-generale-annuelle-2020\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/09\/WFH_FR.png","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/09\/WFH_FR.png","width":620,"height":400},{"@type":"WebSite","@id":"https:\/\/wfh.org\/fr\/#website","url":"https:\/\/wfh.org\/fr\/","name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wfh.org\/fr\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887","name":"Electra Rozakis"}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/46407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/comments?post=46407"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/46407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media\/15375"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media?parent=46407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/categories?post=46407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/tags?post=46407"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/search-category?post=46407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}