{"id":3503,"date":"2021-11-09T09:00:00","date_gmt":"2021-11-09T14:00:00","guid":{"rendered":"https:\/\/wfh.org\/wfh-humanitarian-aid-program-helps-18-year-old-in-mali\/"},"modified":"2024-04-18T08:49:33","modified_gmt":"2024-04-18T12:49:33","slug":"le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans","status":"publish","type":"post","link":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/","title":{"rendered":"Le Programme d\u2019aide humanitaire vient en aide \u00e0 un jeune Malien de 18 ans"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3503\" class=\"elementor elementor-3503 elementor-2049\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a54dd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a54dd5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90d2085\" data-id=\"90d2085\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cc8a3e elementor-widget elementor-widget-text-editor\" data-id=\"6cc8a3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Makan Magassa est un jeune homme de 18 ans atteint d\u2019h\u00e9mophilie A s\u00e9v\u00e8re. Il vit \u00e0 environ 235 km de Bamako, la capitale du Mali. En 2017, il s\u2019est bless\u00e9 et a d\u00e9velopp\u00e9 un h\u00e9matome au niveau de sa jambe droite, qui s\u2019est gravement infect\u00e9. Sans un don de facteur de la part du\u00a0<a href=\"https:\/\/wfh.org\/fr\/aide-humanitaire\/\" target=\"_blank\" rel=\"noopener noreferrer\">Programme d\u2019aide humanitaire de la FMH<\/a>, il aurait perdu sa jambe.<\/p>\n<p>L\u2019h\u00e9matome de ce jeune Malien est d\u00fb \u00e0 un accident. Au d\u00e9part, Makan a \u00e9t\u00e9 soign\u00e9 par un gu\u00e9risseur traditionnel de son village, ce qui a notamment requis une incision sur sa jambe. Comme le saignement ne s\u2019arr\u00eatait pas, des poudres et des onguents traditionnels ont \u00e9t\u00e9 appliqu\u00e9s, ce qui a caus\u00e9 une surinfection de l\u2019h\u00e9matome. Lorsqu\u2019il est devenu clair que le jeune homme avait besoin de soins d\u2019urgence, il a \u00e9t\u00e9 transport\u00e9 \u00e0 l\u2019h\u00f4pital, o\u00f9 des chirurgiens ont recommand\u00e9 l\u2019amputation de sa jambe, car ils pensaient que l\u2019h\u00e9morragie avait provoqu\u00e9 la formation d\u2019une tumeur maligne.<\/p>\n<p>Heureusement, les m\u00e9decins ont plut\u00f4t d\u00e9cid\u00e9 d\u2019envoyer Makan dans un centre de traitement de l\u2019h\u00e9mophilie (CTH) pour un test sanguin, et c\u2019est alors qu\u2019on lui a diagnostiqu\u00e9 une h\u00e9mophilie A s\u00e9v\u00e8re. On lui a imm\u00e9diatement administr\u00e9 un don de facteur fourni par le Programme d\u2019aide humanitaire de la FMH. En un mois, son \u0153d\u00e8me s\u2019est r\u00e9sorb\u00e9, et le dosage de facteur a pu \u00eatre r\u00e9duit. Quatre mois plus tard, l\u2019\u0153d\u00e8me \u00e9tait totalement gu\u00e9ri, et Makan a pu rentrer chez lui. Il est actuellement suivi par le CTH et n\u2019a pas d\u00e9velopp\u00e9 d\u2019inhibiteurs.<\/p>\n<p>Le Programme d\u2019aide humanitaire fournit des dons de facteur dans le monde entier. En 2020, les CTH du Mali ont ainsi re\u00e7u plus de 2,3 millions d\u2019UI de facteur. Depuis 2015, c\u2019est plus de 7,6 millions d\u2019UI qui ont \u00e9t\u00e9 livr\u00e9es dans ce pays d\u2019Afrique. Pour en savoir plus sur le Programme d\u2019aide humanitaire de la FMH,\u00a0<a href=\"https:\/\/wfh.org\/fr\/aide-humanitaire\/\" target=\"_blank\" rel=\"noopener noreferrer\">cliquez ici<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2690d46 elementor-widget elementor-widget-heading\" data-id=\"2690d46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c0 propos du Programme d\u2019aide humanitaire de la FMH<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8a59b2 elementor-widget elementor-widget-text-editor\" data-id=\"a8a59b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le Programme d\u2019aide humanitaire de la FMH am\u00e9liore l\u2019acc\u00e8s aux soins et aux traitements en fournissant un soutien essentiel aux personnes atteintes de troubles h\u00e9r\u00e9ditaires de la coagulation dans les pays en d\u00e9veloppement. En apportant aux patients un flux plus r\u00e9gulier et plus pr\u00e9visible de dons humanitaires, le Programme d\u2019aide humanitaire de la FMH leur permet un acc\u00e8s constant et fiable aux traitements et aux soins. Rien de tout cela ne serait possible sans le g\u00e9n\u00e9reux soutien de Sanofi Genzyme et Sobi, nos Donateurs visionnaires fondateurs\u00a0; de Roche et Bayer, nos Donateurs visionnaires\u00a0; de Grifols, notre Donateur encadrant, et de nos Donateurs contributeurs CSL Behring et Takeda. Pour plus d\u2019informations sur le Programme d\u2019aide humanitaire de la FMH, consultez le site\u00a0<a href=\"http:\/\/www.treatmentforall.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.treatmentforall.org<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a345bc5 elementor-widget elementor-widget-image\" data-id=\"a345bc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"786\" height=\"343\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png\" class=\"attachment-full size-full wp-image-28201\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png 786w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-192x84.png 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-768x335.png 768w\" sizes=\"(max-width: 786px) 100vw, 786px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Makan Magassa est un jeune homme de 18 ans atteint d\u2019h\u00e9mophilie A s\u00e9v\u00e8re. Il vit \u00e0 environ 235 km de Bamako, la capitale du Mali. En 2017, il s\u2019est bless\u00e9 et a d\u00e9velopp\u00e9 un h\u00e9matome au niveau de sa jambe droite, qui s\u2019est gravement infect\u00e9.<\/p>\n","protected":false},"author":3,"featured_media":2051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[171,184],"tags":[],"search-category":[85],"class_list":["post-3503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-de-la-fmh","category-programme-daide-humanitaire-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Programme d\u2019aide humanitaire vient en aide \u00e0 un jeune Malien de 18 ans | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Programme d\u2019aide humanitaire vient en aide \u00e0 un jeune Malien de 18 ans\" \/>\n<meta property=\"og:description\" content=\"Makan Magassa est un jeune homme de 18 ans atteint d\u2019h\u00e9mophilie A s\u00e9v\u00e8re. Il vit \u00e0 environ 235 km de Bamako, la capitale du Mali. En 2017, il s\u2019est bless\u00e9 et a d\u00e9velopp\u00e9 un h\u00e9matome au niveau de sa jambe droite, qui s\u2019est gravement infect\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-09T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T12:49:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2021\/11\/Makan-header-620x400-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Electra Rozakis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Electra Rozakis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/\"},\"author\":{\"name\":\"Electra Rozakis\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\"},\"headline\":\"Le Programme d\u2019aide humanitaire vient en aide \u00e0 un jeune Malien de 18 ans\",\"datePublished\":\"2021-11-09T14:00:00+00:00\",\"dateModified\":\"2024-04-18T12:49:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/\"},\"wordCount\":520,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Makan-header-620x400-1.jpg\",\"articleSection\":[\"Actualit\u00e9s de la FMH\",\"Programme d\u2019aide humanitaire de la FMH\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/\",\"name\":\"Le Programme d\u2019aide humanitaire vient en aide \u00e0 un jeune Malien de 18 ans | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Makan-header-620x400-1.jpg\",\"datePublished\":\"2021-11-09T14:00:00+00:00\",\"dateModified\":\"2024-04-18T12:49:33+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Makan-header-620x400-1.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Makan-header-620x400-1.jpg\",\"width\":620,\"height\":400},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"name\":\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\",\"name\":\"Electra Rozakis\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Programme d\u2019aide humanitaire vient en aide \u00e0 un jeune Malien de 18 ans | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Programme d\u2019aide humanitaire vient en aide \u00e0 un jeune Malien de 18 ans","og_description":"Makan Magassa est un jeune homme de 18 ans atteint d\u2019h\u00e9mophilie A s\u00e9v\u00e8re. Il vit \u00e0 environ 235 km de Bamako, la capitale du Mali. En 2017, il s\u2019est bless\u00e9 et a d\u00e9velopp\u00e9 un h\u00e9matome au niveau de sa jambe droite, qui s\u2019est gravement infect\u00e9.","og_url":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/","og_site_name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2021-11-09T14:00:00+00:00","article_modified_time":"2024-04-18T12:49:33+00:00","og_image":[{"width":620,"height":400,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/11\/Makan-header-620x400-1.jpg","type":"image\/jpeg"}],"author":"Electra Rozakis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Electra Rozakis","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/"},"author":{"name":"Electra Rozakis","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887"},"headline":"Le Programme d\u2019aide humanitaire vient en aide \u00e0 un jeune Malien de 18 ans","datePublished":"2021-11-09T14:00:00+00:00","dateModified":"2024-04-18T12:49:33+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/"},"wordCount":520,"publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/11\/Makan-header-620x400-1.jpg","articleSection":["Actualit\u00e9s de la FMH","Programme d\u2019aide humanitaire de la FMH"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/","url":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/","name":"Le Programme d\u2019aide humanitaire vient en aide \u00e0 un jeune Malien de 18 ans | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/11\/Makan-header-620x400-1.jpg","datePublished":"2021-11-09T14:00:00+00:00","dateModified":"2024-04-18T12:49:33+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/article\/le-programme-daide-humanitaire-vient-en-aide-a-un-jeune-malien-de-18-ans\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/11\/Makan-header-620x400-1.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/11\/Makan-header-620x400-1.jpg","width":620,"height":400},{"@type":"WebSite","@id":"https:\/\/wfh.org\/fr\/#website","url":"https:\/\/wfh.org\/fr\/","name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wfh.org\/fr\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887","name":"Electra Rozakis"}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/3503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/comments?post=3503"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/3503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media\/2051"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media?parent=3503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/categories?post=3503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/tags?post=3503"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/search-category?post=3503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}