{"id":111695,"date":"2024-06-10T13:01:20","date_gmt":"2024-06-10T17:01:20","guid":{"rendered":"https:\/\/wfh.org\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/"},"modified":"2024-06-25T09:11:41","modified_gmt":"2024-06-25T13:11:41","slug":"les-jumeaux-de-lannee-2023-sont-annonces","status":"publish","type":"post","link":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/","title":{"rendered":"Les Jumeaux de l\u2019ann\u00e9e 2023 sont annonc\u00e9s !"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"111695\" class=\"elementor elementor-111695 elementor-111326\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16422ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16422ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f6340e\" data-id=\"8f6340e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-430911b elementor-widget elementor-widget-text-editor\" data-id=\"430911b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le <a href=\"https:\/\/wfh.org\/fr\/demander-une-bourse-ou-une-subvention\/programme-de-jumelage\/\" target=\"_blank\" rel=\"noopener\">Programme de jumelage de la FMH<\/a> soutient des partenariats \u00e0 court terme entre des professionnel\u00b7les de sant\u00e9, ainsi qu\u2019entre des associations de patient\u00b7es ou de jeunes repr\u00e9sentant\u00b7es d\u2019associations dans le monde entier. Les laur\u00e9ats des prix des Jumeaux de l\u2019ann\u00e9e ont \u00e9t\u00e9 annonc\u00e9s lors du Congr\u00e8s mondial 2024 de la FMH, qui s\u2019est tenu \u00e0 Madrid (Espagne), o\u00f9 les partenaires se sont vu remettre des plaques officielles aux c\u00f4t\u00e9s des Jumeaux 2022. L\u2019\u00e9v\u00e9nement a rendu hommage aux jumeaux pass\u00e9s et pr\u00e9sents, mais aussi aux nouveaux jumelages, et la FMH a exprim\u00e9 sa reconnaissance envers Pfizer, partenaire du Programme de jumelage depuis de nombreuses ann\u00e9es. Le Programme a eu un fort impact au niveau mondial, avec un total de 275 partenariats cr\u00e9\u00e9s dans 119 pays.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fffd246 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fffd246\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eacecea\" data-id=\"eacecea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d962d59 elementor-widget elementor-widget-image\" data-id=\"d962d59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"222\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Serbia-Manitoba-receive-plaque.jpg\" class=\"attachment-full size-full wp-image-111343\" alt=\"Serbie \u2013 Manitoba (Canada) et Rwanda \u2013 umeaux de l\u2019ann\u00e9e France -\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Serbia-Manitoba-receive-plaque.jpg 600w, https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Serbia-Manitoba-receive-plaque-192x71.jpg 192w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f4833d8\" data-id=\"f4833d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9d6250 elementor-widget elementor-widget-image\" data-id=\"a9d6250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"319\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Rwanda-France-receive-plaque.jpg\" class=\"attachment-full size-full wp-image-111333\" alt=\"Rwanda - France 2023 prix des Jumeaux de l\u2019ann\u00e9e\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Rwanda-France-receive-plaque.jpg 600w, https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Rwanda-France-receive-plaque-192x102.jpg 192w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-919a579 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"919a579\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5a163ac\" data-id=\"5a163ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a5bf20 elementor-widget elementor-widget-text-editor\" data-id=\"2a5bf20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Dawn Rotellini, pr\u00e9sidente du Comit\u00e9 de jumelage des associations de patient\u00b7es, remet les prix des Jumeaux de l\u2019ann\u00e9e 2022 et 2023 aux couples Serbie &#8211; Manitoba (Canada) et Rwanda &#8211; France (de gauche \u00e0 droite).<\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-704c197 elementor-widget elementor-widget-text-editor\" data-id=\"704c197\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019ann\u00e9e a \u00e9t\u00e9 tr\u00e8s productive pour le jumelage Rwanda-France. Ces deux jumeaux ont men\u00e9 des formations de sensibilisation et de renforcement des capacit\u00e9s aupr\u00e8s de 60 agent\u00b7es de sant\u00e9 communautaires, 104 parents, 150 enseignant\u00b7es et 2\u00a0000 \u00e9tudiant\u00b7es. Ils ont particip\u00e9 \u00e0 un dialogue efficace avec plusieurs institutions telles que le minist\u00e8re rwandais de la Sant\u00e9 et le Centre biom\u00e9dical du Rwanda afin de les sensibiliser et de demander un meilleur traitement et de meilleurs soins pour les personnes atteintes d\u2019un trouble de la coagulation. Ils ont \u00e9galement cr\u00e9\u00e9 le site internet de l\u2019ONM rwandaise.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a4445f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4445f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bd54d6c\" data-id=\"bd54d6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9caf7d0 elementor-widget elementor-widget-image\" data-id=\"9caf7d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"193\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Amman-Dublin-awarded-plaque.jpg\" class=\"attachment-full size-full wp-image-111328\" alt=\"Amman (Jordanie) - Dublin (Irlande) 2023 prix des Jumeaux de l\u2019ann\u00e9e\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Amman-Dublin-awarded-plaque.jpg 600w, https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Amman-Dublin-awarded-plaque-192x62.jpg 192w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ac518f1\" data-id=\"ac518f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d0706f elementor-widget elementor-widget-image\" data-id=\"4d0706f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"217\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Semarang-Utrecht-receive-plaque.jpg\" class=\"attachment-full size-full wp-image-111338\" alt=\"Semarang (Indon\u00e9sie) \u2013 Utrecht (Pays-Bas) Jumeaux de l\u2019ann\u00e9e\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Semarang-Utrecht-receive-plaque.jpg 600w, https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/Semarang-Utrecht-receive-plaque-192x69.jpg 192w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab4fe1f elementor-widget elementor-widget-text-editor\" data-id=\"ab4fe1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Catherine Lambert, pr\u00e9sidente du Comit\u00e9 de jumelage des CTH, remet les prix des Jumeaux de l\u2019ann\u00e9e 2022 et 2023 aux couples de CTH Amman (Jordanie) &#8211; Dublin (Irlande) et Semarang (Indon\u00e9sie) &#8211; Utrecht (Pays-Bas), de gauche \u00e0 droite.<\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63dfe4f elementor-widget elementor-widget-text-editor\" data-id=\"63dfe4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les jumeaux Semarang \u2013 Utrecht, dont le partenariat est dans sa troisi\u00e8me ann\u00e9e, ont poursuivi sur leur lanc\u00e9e en renfor\u00e7ant la sensibilisation et les connaissances chez les professionnel\u00b7les de sant\u00e9 sur la prise en charge clinique des troubles de la coagulation. Ils ont organis\u00e9 plusieurs activit\u00e9s pour am\u00e9liorer les soins pour les personnes atteintes d\u2019un trouble de la coagulation en Indon\u00e9sie. Parmi elles, le d\u00e9veloppement d\u2019un registre des patient\u00b7es, la cr\u00e9ation de plans de traitement personnalis\u00e9s et l\u2019\u00e9tablissement de protocoles de traitement. De plus, ils ont aussi organis\u00e9 des sessions de formation pour les kin\u00e9sith\u00e9rapeutes ainsi que deux symposiums pour le personnel m\u00e9dical et param\u00e9dical travaillant dans les soins de l\u2019h\u00e9mophilie et des autres troubles de la coagulation. Les deux jumeaux ont enfin facilit\u00e9 des sessions d\u2019hydroth\u00e9rapie dans le cadre de leurs programmes d\u2019\u00e9ducation des patient\u00b7es.<\/p>\n<p>Au nom de la FMH, bravo \u00e0 nos Jumeaux de l&rsquo;ann\u00e9e 2023 !<\/p>\n<p>Pour en savoir plus sur le Programme de jumelage de la FMH, <a href=\"https:\/\/wfh.org\/fr\/demander-une-bourse-ou-une-subvention\/programme-de-jumelage\/\" target=\"_blank\" rel=\"noopener\">cliquez ici<\/a>.<\/p>\n<p><em>Le Programme de jumelage b\u00e9n\u00e9ficie d\u2019un financement exclusif de Pfizer.<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie (FMH) a le grand plaisir d\u2019annoncer les Jumeaux de l\u2019ann\u00e9e 2023 ! Les Jumeaux de l\u2019ann\u00e9e 2023 du Programme de jumelage des associations de patient\u00b7es sont la Rwanda Fraternity Against Hemophilia (Rwanda) et l\u2019Association Fran\u00e7aise des H\u00e9mophiles (Pays de la Loire, France). Les Jumeaux de l\u2019ann\u00e9e du Programme de jumelage des centres de traitement de l\u2019h\u00e9mophilie (CTH) sont l\u2019H\u00f4pital central g\u00e9n\u00e9ral Dr. Kariadi Semarang (Indon\u00e9sie) et le D\u00e9partement d\u2019h\u00e9matologie b\u00e9nigne Van Creveldkliniek du centre m\u00e9dical universitaire d\u2019Utrecht (Pays-Bas).<\/p>\n","protected":false},"author":13,"featured_media":111348,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[334,115],"tags":[],"search-category":[85],"class_list":["post-111695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured-1-fr","category-programme-de-jumelage-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Jumeaux de l\u2019ann\u00e9e 2023 sont annonc\u00e9s ! | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Jumeaux de l\u2019ann\u00e9e 2023 sont annonc\u00e9s !\" \/>\n<meta property=\"og:description\" content=\"La F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie (FMH) a le grand plaisir d\u2019annoncer les Jumeaux de l\u2019ann\u00e9e 2023 ! Les Jumeaux de l\u2019ann\u00e9e 2023 du Programme de jumelage des associations de patient\u00b7es sont la Rwanda Fraternity Against Hemophilia (Rwanda) et l\u2019Association Fran\u00e7aise des H\u00e9mophiles (Pays de la Loire, France). Les Jumeaux de l\u2019ann\u00e9e du Programme de jumelage des centres de traitement de l\u2019h\u00e9mophilie (CTH) sont l\u2019H\u00f4pital central g\u00e9n\u00e9ral Dr. Kariadi Semarang (Indon\u00e9sie) et le D\u00e9partement d\u2019h\u00e9matologie b\u00e9nigne Van Creveldkliniek du centre m\u00e9dical universitaire d\u2019Utrecht (Pays-Bas).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T17:01:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-25T13:11:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/ToY-2023-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Les Jumeaux de l\u2019ann\u00e9e 2023 sont annonc\u00e9s !\",\"datePublished\":\"2024-06-10T17:01:20+00:00\",\"dateModified\":\"2024-06-25T13:11:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/\"},\"wordCount\":523,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/ToY-2023-header.jpg\",\"articleSection\":[\"Featured 1 - FR\",\"Programme de jumelage de la FMH\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/\",\"name\":\"Les Jumeaux de l\u2019ann\u00e9e 2023 sont annonc\u00e9s ! | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/ToY-2023-header.jpg\",\"datePublished\":\"2024-06-10T17:01:20+00:00\",\"dateModified\":\"2024-06-25T13:11:41+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/article\\\/les-jumeaux-de-lannee-2023-sont-annonces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/ToY-2023-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/ToY-2023-header.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Les Jumeaux de l\u2019ann\u00e9e 2023\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"name\":\"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/fr\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Jumeaux de l\u2019ann\u00e9e 2023 sont annonc\u00e9s ! | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Jumeaux de l\u2019ann\u00e9e 2023 sont annonc\u00e9s !","og_description":"La F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie (FMH) a le grand plaisir d\u2019annoncer les Jumeaux de l\u2019ann\u00e9e 2023 ! Les Jumeaux de l\u2019ann\u00e9e 2023 du Programme de jumelage des associations de patient\u00b7es sont la Rwanda Fraternity Against Hemophilia (Rwanda) et l\u2019Association Fran\u00e7aise des H\u00e9mophiles (Pays de la Loire, France). Les Jumeaux de l\u2019ann\u00e9e du Programme de jumelage des centres de traitement de l\u2019h\u00e9mophilie (CTH) sont l\u2019H\u00f4pital central g\u00e9n\u00e9ral Dr. Kariadi Semarang (Indon\u00e9sie) et le D\u00e9partement d\u2019h\u00e9matologie b\u00e9nigne Van Creveldkliniek du centre m\u00e9dical universitaire d\u2019Utrecht (Pays-Bas).","og_url":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/","og_site_name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2024-06-10T17:01:20+00:00","article_modified_time":"2024-06-25T13:11:41+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/ToY-2023-header.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mitch Semienchuk","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Les Jumeaux de l\u2019ann\u00e9e 2023 sont annonc\u00e9s !","datePublished":"2024-06-10T17:01:20+00:00","dateModified":"2024-06-25T13:11:41+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/"},"wordCount":523,"publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/ToY-2023-header.jpg","articleSection":["Featured 1 - FR","Programme de jumelage de la FMH"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/","url":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/","name":"Les Jumeaux de l\u2019ann\u00e9e 2023 sont annonc\u00e9s ! | FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","isPartOf":{"@id":"https:\/\/wfh.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/ToY-2023-header.jpg","datePublished":"2024-06-10T17:01:20+00:00","dateModified":"2024-06-25T13:11:41+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/article\/les-jumeaux-de-lannee-2023-sont-annonces\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/ToY-2023-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/06\/ToY-2023-header.jpg","width":1200,"height":627,"caption":"Les Jumeaux de l\u2019ann\u00e9e 2023"},{"@type":"WebSite","@id":"https:\/\/wfh.org\/fr\/#website","url":"https:\/\/wfh.org\/fr\/","name":"FMH - F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wfh.org\/fr\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/fr\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/111695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/comments?post=111695"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/posts\/111695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media\/111348"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/media?parent=111695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/categories?post=111695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/tags?post=111695"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/fr\/wp-json\/wp\/v2\/search-category?post=111695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}