{"id":95897,"date":"2023-12-19T09:00:36","date_gmt":"2023-12-19T14:00:36","guid":{"rendered":"https:\/\/wfh.org\/?p=95897"},"modified":"2024-04-04T10:43:08","modified_gmt":"2024-04-04T14:43:08","slug":"feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/","title":{"rendered":"\u00a1Feliz A\u00f1o Nuevo le desea la Federaci\u00f3n Mundial de Hemofilia!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"95897\" class=\"elementor elementor-95897 elementor-95890\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be12a30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be12a30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29b6b04\" data-id=\"29b6b04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1873dd1 elementor-widget elementor-widget-text-editor\" data-id=\"1873dd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sin ustedes no habr\u00edamos podido apoyar a la comunidad mundial de trastornos de la coagulaci\u00f3n de la manera en la que lo hemos hecho. Hay muchas cosas que esperar el a\u00f1o pr\u00f3ximo; una de ellas es el Congreso Mundial 2024 de la FMH, que tendr\u00e1 lugar en Madrid, Espa\u00f1a, del 21 al 24 de abril. \u00a1Esperamos verle all\u00ed en persona!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65f14c8 elementor-widget elementor-widget-video\" data-id=\"65f14c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/KiDWHiF5YEs?si=UPcAjOJ_GQuM-6sW&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcecf37 elementor-widget elementor-widget-text-editor\" data-id=\"dcecf37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para ver nuestro video de A\u00f1o Nuevo haga <a href=\"https:\/\/youtu.be\/KiDWHiF5YEs?si=UPcAjOJ_GQuM-6sW\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conforme el 2023 llega a su fin, en la Federaci\u00f3n Mundial de Hemofilia (FMH) deseamos celebrar a nuestros voluntarios, a los miembros del consejo de la FMH y de la FMH USA, a los integrantes de nuestras organizaciones nacionales miembros (ONM), a los profesionales m\u00e9dicos, a nuestro personal, y a nuestros aliados corporativos, aliados comunitarios y organizaciones colaboradoras de todo el mundo por su inquebrantable dedicaci\u00f3n a nuestra visi\u00f3n compartida de Tratamiento para todos. <\/p>\n","protected":false},"author":13,"featured_media":96477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[],"search-category":[85],"class_list":["post-95897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00a1Feliz A\u00f1o Nuevo le desea la Federaci\u00f3n Mundial de Hemofilia! | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Feliz A\u00f1o Nuevo le desea la Federaci\u00f3n Mundial de Hemofilia!\" \/>\n<meta property=\"og:description\" content=\"Conforme el 2023 llega a su fin, en la Federaci\u00f3n Mundial de Hemofilia (FMH) deseamos celebrar a nuestros voluntarios, a los miembros del consejo de la FMH y de la FMH USA, a los integrantes de nuestras organizaciones nacionales miembros (ONM), a los profesionales m\u00e9dicos, a nuestro personal, y a nuestros aliados corporativos, aliados comunitarios y organizaciones colaboradoras de todo el mundo por su inquebrantable dedicaci\u00f3n a nuestra visi\u00f3n compartida de Tratamiento para todos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T14:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T14:43:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2023\/12\/Year-end-video-header-2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"\u00a1Feliz A\u00f1o Nuevo le desea la Federaci\u00f3n Mundial de Hemofilia!\",\"datePublished\":\"2023-12-19T14:00:36+00:00\",\"dateModified\":\"2024-04-04T14:43:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/\"},\"wordCount\":93,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Year-end-video-header-2023.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/\",\"name\":\"\u00a1Feliz A\u00f1o Nuevo le desea la Federaci\u00f3n Mundial de Hemofilia! | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Year-end-video-header-2023.jpg\",\"datePublished\":\"2023-12-19T14:00:36+00:00\",\"dateModified\":\"2024-04-04T14:43:08+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Year-end-video-header-2023.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Year-end-video-header-2023.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00a1Feliz A\u00f1o Nuevo le desea la Federaci\u00f3n Mundial de Hemofilia! | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Feliz A\u00f1o Nuevo le desea la Federaci\u00f3n Mundial de Hemofilia!","og_description":"Conforme el 2023 llega a su fin, en la Federaci\u00f3n Mundial de Hemofilia (FMH) deseamos celebrar a nuestros voluntarios, a los miembros del consejo de la FMH y de la FMH USA, a los integrantes de nuestras organizaciones nacionales miembros (ONM), a los profesionales m\u00e9dicos, a nuestro personal, y a nuestros aliados corporativos, aliados comunitarios y organizaciones colaboradoras de todo el mundo por su inquebrantable dedicaci\u00f3n a nuestra visi\u00f3n compartida de Tratamiento para todos.","og_url":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2023-12-19T14:00:36+00:00","article_modified_time":"2024-04-04T14:43:08+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/12\/Year-end-video-header-2023.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"\u00a1Feliz A\u00f1o Nuevo le desea la Federaci\u00f3n Mundial de Hemofilia!","datePublished":"2023-12-19T14:00:36+00:00","dateModified":"2024-04-04T14:43:08+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/"},"wordCount":93,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/12\/Year-end-video-header-2023.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/","url":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/","name":"\u00a1Feliz A\u00f1o Nuevo le desea la Federaci\u00f3n Mundial de Hemofilia! | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/12\/Year-end-video-header-2023.jpg","datePublished":"2023-12-19T14:00:36+00:00","dateModified":"2024-04-04T14:43:08+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/feliz-ano-nuevo-le-desea-la-federacion-mundial-de-hemofilia-2\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/12\/Year-end-video-header-2023.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/12\/Year-end-video-header-2023.jpg","width":1200,"height":627},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/95897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=95897"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/95897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/96477"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=95897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=95897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=95897"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=95897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}