{"id":54445,"date":"2023-01-23T16:43:18","date_gmt":"2023-01-23T21:43:18","guid":{"rendered":"https:\/\/wfh.org\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/"},"modified":"2024-04-09T09:18:11","modified_gmt":"2024-04-09T13:18:11","slug":"preguntas-y-respuestas-con-una-onm-costa-rica","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/","title":{"rendered":"Preguntas y respuestas con una ONM: Costa Rica"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"54445\" class=\"elementor elementor-54445 elementor-54160\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e65dfc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e65dfc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6599df4\" data-id=\"6599df4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7ceb49f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ceb49f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4b6beea\" data-id=\"4b6beea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-338cfc0 elementor-widget elementor-widget-text-editor\" data-id=\"338cfc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table width=\"482\">\n<tbody>\n<tr>\n<td width=\"148\"><strong>Nombre de la ONM<\/strong><\/td>\n<td width=\"333\">Asociaci\u00f3n Costarricense de Hemofilia<\/td>\n<\/tr>\n<tr>\n<td width=\"148\"><strong>Ubicaci\u00f3n<\/strong><\/td>\n<td width=\"333\">San Jos\u00e9, Costa Rica<\/td>\n<\/tr>\n<tr>\n<td width=\"148\"><strong>Fecha de fundaci\u00f3n<\/strong><\/td>\n<td width=\"333\">1968<\/td>\n<\/tr>\n<tr>\n<td width=\"148\"><strong>Miembros activos<\/strong><\/td>\n<td width=\"333\">88<\/td>\n<\/tr>\n<tr>\n<td width=\"148\"><strong>PCTC atendidas<\/strong><\/td>\n<td width=\"333\">407<\/td>\n<\/tr>\n<tr>\n<td width=\"148\"><strong>P\u00e1gina internet*<\/strong><\/td>\n<td width=\"333\"><a href=\"http:\/\/www.asohemo.com\" target=\"_blank\" rel=\"noopener\">www.asohemo.com<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><em>Las siguientes respuestas se editaron para aportar una mayor claridad.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><strong>\u00bfCu\u00e1les son la visi\u00f3n y misi\u00f3n de su ONM?<\/strong><\/p>\n<p>Nuestra misi\u00f3n es garantizar mejor salud y calidad de vida para todas las personas que viven con un trastorno de la coagulaci\u00f3n en Costa Rica. Nuestra visi\u00f3n es que todos los costarricenses con trastornos de la coagulaci\u00f3n tengan acceso a atenci\u00f3n integral, y a tratamiento seguro y eficaz.<\/p>\n<p><strong>\u00bfCu\u00e1les son los desaf\u00edos que enfrentan?<\/strong><\/p>\n<p>Nuestro principal desaf\u00edo es hacer a los miembros de nuestra comunidad m\u00e1s conscientes de todas las diferentes facetas de su trastorno m\u00e9dico, y de sus derechos. Tambi\u00e9n enfrentamos el reto de capacitar a profesionales de la salud en todas las regiones, de manera que est\u00e9n conscientes sobre los trastornos de la coagulaci\u00f3n. Otro problema es una mejor integraci\u00f3n de los familiares de los pacientes a nuestra organizaci\u00f3n, de modo que podamos ser m\u00e1s integrales en t\u00e9rminos de atenci\u00f3n. Hemos podido superar algunos de estos desaf\u00edos ofreciendo talleres educativos y creando sesiones educativas para profesionales.<\/p>\n<p><strong>\u00bfCu\u00e1l fue su principal logro en 2022?<\/strong><\/p>\n<p>Nuestro principal logro fue establecer un di\u00e1logo con la Caja Costarricense del Seguro Social (CCSS), con el Centro Nacional del Hospital M\u00e9xico, y con el Hospital Nacional de Ni\u00f1os Carlos S\u00e1enz Herrera, a fin de abordar maneras de colaborar. Pudimos lograr esto entrevist\u00e1ndonos con los directores de las instituciones y conversando sobre nuestras necesidades y metas comunes. Aprendimos que al llevar estad\u00edsticas concretas a la mesa pudimos tener conversaciones productivas.<\/p>\n<p><strong>\u00bfC\u00f3mo les ha afectado la pandemia de COVID-19?<\/strong><\/p>\n<p>Nos vimos afectados de la misma forma que muchas otras organizaciones: nuestra comunidad estaba aislada y exist\u00eda el riesgo de que el tratamiento no llegara a las PCTC. Superamos esto manteni\u00e9ndonos en estrecho contacto con nuestros miembros y proporcion\u00e1ndoles informaci\u00f3n sobre la manera en la que la pandemia afectar\u00eda los procesos log\u00edsticos y la forma en la que saldr\u00edamos de la pandemia juntos.<\/p>\n<p><strong>\u00bfQu\u00e9 servicios ofrece su ONM a la comunidad de trastornos de la coagulaci\u00f3n?<\/strong><\/p>\n<p>Ofrecemos servicios educativos; asesor\u00eda antes de un procedimiento m\u00e9dico; apoyo para el diagn\u00f3stico; informaci\u00f3n a familiares nuevos en la comunidad; apoyo financiero para transporte a citas m\u00e9dicas; y capacitaci\u00f3n sobre la administraci\u00f3n de productos de tratamiento para la terapia profil\u00e1ctica en el hogar.<\/p>\n<p><strong>\u00bfCu\u00e1les son los principales desaf\u00edos que enfrenta la comunidad de trastornos de la coagulaci\u00f3n en su pa\u00eds?<\/strong><\/p>\n<p>Nuestros desaf\u00edos son el acceso a la atenci\u00f3n fuera del valle central de Costa Rica (alrededor de la ciudad capital de San Jos\u00e9); la falta de diagn\u00f3stico para la enfermedad de Von Willebrand (EVW); la instrucci\u00f3n en instituciones p\u00fablicas, y la falta de oportunidades de empleo para nuestra comunidad. Estamos tratando de superar estos retos implementando gu\u00edas de tratamiento a escala nacional e instruyendo a nuestra poblaci\u00f3n sobre el uso eficaz del tratamiento profil\u00e1ctico.<\/p>\n<p><strong>\u00bfCu\u00e1l ha sido su experiencia colaborando con la FMH?<\/strong><\/p>\n<p>Colaborar con la FMH ha sido muy provechoso para nuestra comunidad. Por ejemplo, estar afiliados con una organizaci\u00f3n internacional como la FMH nos brinda credibilidad cuando nos ponemos en contacto con organizaciones gubernamentales. Asimismo, haber sido anfitriones del Congreso Mundial de la FMH en Costa Rica, en 1981, realmente increment\u00f3 la visibilidad de los trastornos de la coagulaci\u00f3n ante el gobierno y entre los profesionales de la salud. Adem\u00e1s, las sesiones del congreso ayudaron a nuestra comunidad m\u00e9dica a incrementar sus conocimientos t\u00e9cnicos. En el futuro ser\u00eda provechoso si expertos de la FMH pudieran hacer m\u00e1s para instruir a nuestros m\u00e9dicos y miembros sobre el tratamiento de los trastornos de la coagulaci\u00f3n.<\/p>\n<p><strong>\u00bfHay iniciativas\/eventos futuros que deseen promocionar?<\/strong><\/p>\n<p>Actualmente estamos desarrollando el Programa \u201cHemos\u201d sobre datos y registros para ayudar a proporcionar m\u00e1s informaci\u00f3n sobre nuestra comunidad a los proveedores de atenci\u00f3n m\u00e9dica.<\/p>\n<p><strong>\u00bfTiene alg\u00fan otro comentario que compartir?<\/strong><\/p>\n<p>Gracias por la oportunidad de compartir con el mundo nuestros \u00e9xitos y desaf\u00edos. Gracias tambi\u00e9n por facilitar el intercambio de conocimientos entre pa\u00edses.<\/p>\n<p><em>Para conocer la manera en la que colaboran la FMH y sus ONM a fin de marcar la diferencia en las comunidades locales de trastornos de la coagulaci\u00f3n lea Organizaciones nacionales miembros: El coraz\u00f3n de la FMH <a href=\"https:\/\/wfh.org\/es\/article\/organizaciones-nacionales-miembros-el-corazon-de-la-fmh\/\">aqu\u00ed<\/a>.<\/em><\/p>\n<p><em>Para leer el primer art\u00edculo de esta serie sobre nuestra ONM mexicana haga <a href=\"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-entrevista-con-una-onm-mexico\/\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a>.<\/em><\/p>\n<p><em>* Descargo de responsabilidad: Esta es una p\u00e1gina internet externa y su contenido no ha sido creado ni respaldado por la FMH.<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Las organizaciones nacionales miembros (ONM) constituyen el coraz\u00f3n de la Federaci\u00f3n Mundial de Hemofilia (FMH). Trabajamos en estrecha colaboraci\u00f3n con nuestras ONM con el prop\u00f3sito de brindarles apoyo adaptado a sus realidades y ayudarlas a incrementar el nivel de atenci\u00f3n para las personas con trastornos de la coagulaci\u00f3n (PCTC) en sus respectivos pa\u00edses. Durante los pr\u00f3ximos meses presentaremos en la p\u00e1gina de noticias de la FMH los perfiles de varias ONM y mostraremos la labor que llevan a cabo, los desaf\u00edos que enfrentan, y la diferencia que marcan en sus pa\u00edses. Hoy entrevistamos a la ONM de Costa Rica: la Asociaci\u00f3n Costarricense de Hemofilia.<\/p>\n","protected":false},"author":13,"featured_media":54166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[],"search-category":[85],"class_list":["post-54445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Preguntas y respuestas con una ONM: Costa Rica | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preguntas y respuestas con una ONM: Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Las organizaciones nacionales miembros (ONM) constituyen el coraz\u00f3n de la Federaci\u00f3n Mundial de Hemofilia (FMH). Trabajamos en estrecha colaboraci\u00f3n con nuestras ONM con el prop\u00f3sito de brindarles apoyo adaptado a sus realidades y ayudarlas a incrementar el nivel de atenci\u00f3n para las personas con trastornos de la coagulaci\u00f3n (PCTC) en sus respectivos pa\u00edses. Durante los pr\u00f3ximos meses presentaremos en la p\u00e1gina de noticias de la FMH los perfiles de varias ONM y mostraremos la labor que llevan a cabo, los desaf\u00edos que enfrentan, y la diferencia que marcan en sus pa\u00edses. Hoy entrevistamos a la ONM de Costa Rica: la Asociaci\u00f3n Costarricense de Hemofilia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-23T21:43:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T13:18:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2023\/01\/Costa-Rica-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Preguntas y respuestas con una ONM: Costa Rica\",\"datePublished\":\"2023-01-23T21:43:18+00:00\",\"dateModified\":\"2024-04-09T13:18:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/\"},\"wordCount\":834,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Costa-Rica-header.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/\",\"name\":\"Preguntas y respuestas con una ONM: Costa Rica | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Costa-Rica-header.jpg\",\"datePublished\":\"2023-01-23T21:43:18+00:00\",\"dateModified\":\"2024-04-09T13:18:11+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/preguntas-y-respuestas-con-una-onm-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Costa-Rica-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Costa-Rica-header.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Preguntas y respuestas con una ONM: Costa Rica | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Preguntas y respuestas con una ONM: Costa Rica","og_description":"Las organizaciones nacionales miembros (ONM) constituyen el coraz\u00f3n de la Federaci\u00f3n Mundial de Hemofilia (FMH). Trabajamos en estrecha colaboraci\u00f3n con nuestras ONM con el prop\u00f3sito de brindarles apoyo adaptado a sus realidades y ayudarlas a incrementar el nivel de atenci\u00f3n para las personas con trastornos de la coagulaci\u00f3n (PCTC) en sus respectivos pa\u00edses. Durante los pr\u00f3ximos meses presentaremos en la p\u00e1gina de noticias de la FMH los perfiles de varias ONM y mostraremos la labor que llevan a cabo, los desaf\u00edos que enfrentan, y la diferencia que marcan en sus pa\u00edses. Hoy entrevistamos a la ONM de Costa Rica: la Asociaci\u00f3n Costarricense de Hemofilia.","og_url":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2023-01-23T21:43:18+00:00","article_modified_time":"2024-04-09T13:18:11+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/01\/Costa-Rica-header.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Preguntas y respuestas con una ONM: Costa Rica","datePublished":"2023-01-23T21:43:18+00:00","dateModified":"2024-04-09T13:18:11+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/"},"wordCount":834,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/01\/Costa-Rica-header.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/","url":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/","name":"Preguntas y respuestas con una ONM: Costa Rica | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/01\/Costa-Rica-header.jpg","datePublished":"2023-01-23T21:43:18+00:00","dateModified":"2024-04-09T13:18:11+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/preguntas-y-respuestas-con-una-onm-costa-rica\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/01\/Costa-Rica-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2023\/01\/Costa-Rica-header.jpg","width":1200,"height":627},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/54445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=54445"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/54445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/54166"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=54445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=54445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=54445"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=54445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}