{"id":52872,"date":"2022-12-19T12:38:07","date_gmt":"2022-12-19T17:38:07","guid":{"rendered":"https:\/\/wfh.org\/?p=52872"},"modified":"2024-04-10T09:42:32","modified_gmt":"2024-04-10T13:42:32","slug":"testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/","title":{"rendered":"Testigos presenciales del impacto del Programa de Ayuda Humanitaria de la FMH en Indonesia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"52872\" class=\"elementor elementor-52872 elementor-52863\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc16e57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc16e57\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-584dc4b\" data-id=\"584dc4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8dd669 elementor-widget elementor-widget-text-editor\" data-id=\"c8dd669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El mes pasado, miembros del equipo del <a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\" rel=\"noopener\">Programa de Ayuda Humanitaria de la FMH <\/a>y de la FMH USA visitaron a la familia Haikal en Indonesia a fin de observar la manera en la que las donaciones del Programa de Ayuda Humanitaria de la FMH est\u00e1n marcando la diferencia en la vida de Azreal, un ni\u00f1o de cinco a\u00f1os con hemofilia A grave. La visita estuvo a cargo de C\u00e9sar Garrido, presidente de la FMH; el doctor Glenn Pierce, PhD, vicepresidente m\u00e9dico de la FMH; Mark W. Skinner, miembro del consejo directivo de la FMH USA; y el doctor Assad Haffar, director m\u00e9dico y de ayuda humanitaria de la FMH.<\/p>\n<p>Las donaciones del Programa de Ayuda Humanitaria de la FMH han tenido un enorme impacto en la vida cotidiana de Azreal. Est\u00e1 recibiendo tratamiento profil\u00e1ctico, lo cual quiere decir que puede ir a la escuela, jugar con sus amigos y realizar otras actividades normales, como cualquier ni\u00f1o de su edad. Fue tal la diferencia en su vida que, al principio, su madre se comprometi\u00f3 a llevarlo a otro poblado cada 12 horas para que pudiera recibir tratamiento. Eventualmente le pidi\u00f3 al personal de enfermer\u00eda del centro de tratamiento de hemofilia (CTH) que le ense\u00f1aran c\u00f3mo infundirle el tratamiento a Azreal, de modo que ella misma pudiera hacerlo en casa. Eso tard\u00f3 dos meses, pero una vez que adquiri\u00f3 competencia, la posibilidad de la terapia en el hogar mitig\u00f3 considerablemente la carga de la hemofilia para la familia. Adem\u00e1s de ahorrar tiempo y dinero, tambi\u00e9n hace que sea m\u00e1s f\u00e1cil para ella y su esposo trabajar y mantener a la familia.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3de6855 elementor-widget elementor-widget-video\" data-id=\"3de6855\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/bS79v4xBFyk&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15f4f7c elementor-widget elementor-widget-text-editor\" data-id=\"15f4f7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aunque solamente tiene cinco a\u00f1os, Azreal est\u00e1 consciente de la diferencia que las donaciones est\u00e1n marcando en su vida. Sabe que lo hacen sentirse mejor, e incluso solicita las infusiones cuando no se siente bien. En t\u00e9rminos generales, el acceso al tratamiento es algo que \u00e9l considera positivo en su vida.<\/p>\n<p>La profilaxis significa que las hemorragias son algo poco com\u00fan para Azreal. Esto contrasta notablemente con su infancia m\u00e1s temprana, cuando sus hemorragias espont\u00e1neas agudas afectaban considerablemente a toda la familia, exigiendo atenci\u00f3n constante durante varios d\u00edas cada vez. En un momento dado, durante el punto m\u00e1s \u00e1lgido de la pandemia de COVID-19, Azreal tuvo un episodio hemorr\u00e1gico grave que requiri\u00f3 una estancia en el hospital que dur\u00f3 dos meses. Durante ese periodo sus padres ni siquiera pudieron estar cerca de \u00e9l debido a los protocolos de distanciamiento social. Afortunadamente se recuper\u00f3 y pudo volver a casa con sus padres y su hermana, todos los cuales participan en su cuidado. Para Azreal, la profilaxis significa que puede ir a la escuela diariamente y no perder ninguna clase.<\/p>\n<p>Para ver el video completo de Azreal haga <a href=\"https:\/\/youtu.be\/bS79v4xBFyk\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a> o v\u00e9alo arriba.<\/p>\n<p>En 2022, el Programa de Ayuda Humanitaria de la FMH don\u00f3 m\u00e1s de 4 millones de unidades internacionales de factor de coagulaci\u00f3n a Indonesia. Desde el 2015 se han entregado 16.5 millones de UI. Si desea obtener m\u00e1s informaci\u00f3n sobre el Programa de Ayuda Humanitaria de la FMH haga <a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-311d9c3 elementor-widget elementor-widget-heading\" data-id=\"311d9c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Acerca del Programa de Ayuda Humanitaria de la FMH<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57d0fce elementor-widget elementor-widget-text-editor\" data-id=\"57d0fce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Programa de Ayuda Humanitaria de la FMH combate la falta de acceso a la atenci\u00f3n y el tratamiento ofreciendo un apoyo muy necesario a personas con trastornos de la coagulaci\u00f3n hereditarios en pa\u00edses en v\u00edas de desarrollo. Al proporcionar un flujo m\u00e1s previsible y sustentable de donaciones de ayuda humanitaria, el Programa de Ayuda Humanitaria de la FMH hace posible que los pacientes tengan acceso consistente y confiable al tratamiento y la atenci\u00f3n. Nada de esto ser\u00eda posible sin el generoso apoyo de Sanofi y Sobi, nuestras contribuyentes visionarias fundadoras; de Bayer, CSL Behring y Roche, nuestras contribuyentes visionarias; de Grifols, nuestra contribuyente de liderazgo; y de nuestras contribuyentes, Takeda y la Organizaci\u00f3n de Hemoderivados de Jap\u00f3n. Para obtener m\u00e1s informaci\u00f3n sobre el Programa de Ayuda Humanitaria de la FMH visite\u00a0<a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\" rel=\"noopener\">www.treatmentforall.org<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79059a3 elementor-widget elementor-widget-image\" data-id=\"79059a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"786\" height=\"343\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png\" class=\"attachment-full size-full wp-image-28203\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png 786w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-192x84.png 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-768x335.png 768w\" sizes=\"(max-width: 786px) 100vw, 786px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cuando el Programa de Ayuda Humanitaria de la Federaci\u00f3n Mundial de Hemofilia (FMH) empieza a colaborar con partes interesadas en un pa\u00eds, no se trata del inicio de una labor de unos cuantos d\u00edas o semanas; es el principio de un profundo compromiso que dura a\u00f1os o incluso d\u00e9cadas. Esto se debe a que solamente cuando un pa\u00eds es totalmente autosustentable el Programa considerar\u00e1 su mandato completado. Como parte del proceso de monitorear los avances en un pa\u00eds, un equipo de l\u00edderes con frecuencia visitar\u00e1 a las familias que se benefician de la atenci\u00f3n, con el prop\u00f3sito de ser testigos presenciales de la manera en la que el apoyo de la FMH ha marcado la diferencia en sus vidas.<\/p>\n","protected":false},"author":13,"featured_media":52853,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[186],"tags":[],"search-category":[85],"class_list":["post-52872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programa-de-ayuda-humanitaria-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Testigos presenciales del impacto del Programa de Ayuda Humanitaria de la FMH en Indonesia | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Testigos presenciales del impacto del Programa de Ayuda Humanitaria de la FMH en Indonesia\" \/>\n<meta property=\"og:description\" content=\"Cuando el Programa de Ayuda Humanitaria de la Federaci\u00f3n Mundial de Hemofilia (FMH) empieza a colaborar con partes interesadas en un pa\u00eds, no se trata del inicio de una labor de unos cuantos d\u00edas o semanas; es el principio de un profundo compromiso que dura a\u00f1os o incluso d\u00e9cadas. Esto se debe a que solamente cuando un pa\u00eds es totalmente autosustentable el Programa considerar\u00e1 su mandato completado. Como parte del proceso de monitorear los avances en un pa\u00eds, un equipo de l\u00edderes con frecuencia visitar\u00e1 a las familias que se benefician de la atenci\u00f3n, con el prop\u00f3sito de ser testigos presenciales de la manera en la que el apoyo de la FMH ha marcado la diferencia en sus vidas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-19T17:38:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-10T13:42:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/12\/Azreal-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Testigos presenciales del impacto del Programa de Ayuda Humanitaria de la FMH en Indonesia\",\"datePublished\":\"2022-12-19T17:38:07+00:00\",\"dateModified\":\"2024-04-10T13:42:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/\"},\"wordCount\":711,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Azreal-header.jpg\",\"articleSection\":[\"Programa de Ayuda Humanitaria de la FMH\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/\",\"name\":\"Testigos presenciales del impacto del Programa de Ayuda Humanitaria de la FMH en Indonesia | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Azreal-header.jpg\",\"datePublished\":\"2022-12-19T17:38:07+00:00\",\"dateModified\":\"2024-04-10T13:42:32+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Azreal-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Azreal-header.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Testigos presenciales del impacto del Programa de Ayuda Humanitaria de la FMH en Indonesia | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/","og_locale":"es_ES","og_type":"article","og_title":"Testigos presenciales del impacto del Programa de Ayuda Humanitaria de la FMH en Indonesia","og_description":"Cuando el Programa de Ayuda Humanitaria de la Federaci\u00f3n Mundial de Hemofilia (FMH) empieza a colaborar con partes interesadas en un pa\u00eds, no se trata del inicio de una labor de unos cuantos d\u00edas o semanas; es el principio de un profundo compromiso que dura a\u00f1os o incluso d\u00e9cadas. Esto se debe a que solamente cuando un pa\u00eds es totalmente autosustentable el Programa considerar\u00e1 su mandato completado. Como parte del proceso de monitorear los avances en un pa\u00eds, un equipo de l\u00edderes con frecuencia visitar\u00e1 a las familias que se benefician de la atenci\u00f3n, con el prop\u00f3sito de ser testigos presenciales de la manera en la que el apoyo de la FMH ha marcado la diferencia en sus vidas.","og_url":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2022-12-19T17:38:07+00:00","article_modified_time":"2024-04-10T13:42:32+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/12\/Azreal-header.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Testigos presenciales del impacto del Programa de Ayuda Humanitaria de la FMH en Indonesia","datePublished":"2022-12-19T17:38:07+00:00","dateModified":"2024-04-10T13:42:32+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/"},"wordCount":711,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/12\/Azreal-header.jpg","articleSection":["Programa de Ayuda Humanitaria de la FMH"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/","url":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/","name":"Testigos presenciales del impacto del Programa de Ayuda Humanitaria de la FMH en Indonesia | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/12\/Azreal-header.jpg","datePublished":"2022-12-19T17:38:07+00:00","dateModified":"2024-04-10T13:42:32+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/testigos-presenciales-del-impacto-del-programa-de-ayuda-humanitaria-de-la-fmh-en-indonesia\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/12\/Azreal-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/12\/Azreal-header.jpg","width":1200,"height":627},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/52872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=52872"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/52872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/52853"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=52872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=52872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=52872"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=52872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}