{"id":50600,"date":"2022-11-23T09:37:46","date_gmt":"2022-11-23T14:37:46","guid":{"rendered":"https:\/\/wfh.org\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/"},"modified":"2024-04-10T09:44:50","modified_gmt":"2024-04-10T13:44:50","slug":"primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/","title":{"rendered":"Primer f\u00e1rmaco de terapia g\u00e9nica para la hemofilia B aprobado por la FDA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"50600\" class=\"elementor elementor-50600 elementor-50572\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abb97a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abb97a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df2695c\" data-id=\"df2695c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7284660 elementor-widget elementor-widget-text-editor\" data-id=\"7284660\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El <a href=\"https:\/\/www.fda.gov\/news-events\/press-announcements\/fda-approves-first-gene-therapy-treat-adults-hemophilia-b\" target=\"_blank\" rel=\"noopener\">etranacogene dezaparvovec-drlb<\/a> permite a los adultos con hemofilia B elegibles que recibieron tratamiento con la terapia g\u00e9nica producir su propio factor IX, lo que puede reducir el riesgo de hemorragias y reducir o eliminar la necesidad de tratamiento profil\u00e1ctico. En el ensayo cl\u00ednico en curso, el tratamiento redujo la tasa de hemorragias anuales y el 94 por ciento de los pacientes (51 de 54) suspendieron la profilaxis con factor IX y permanecieron sin recibir profilaxis. Los efectos secundarios m\u00e1s comunes (incidencia \u22655%) fueron aumento de las enzimas hep\u00e1ticas, dolor de cabeza, concentraciones elevadas de una enzima sangu\u00ednea determinada, s\u00edntomas similares a los de la influenza, reacciones relacionadas con la infusi\u00f3n, cansancio, n\u00e1usea y malestar.<\/p>\n<p>Para leer el comunicado de prensa de la FDA (en ingl\u00e9s) haga <a href=\"https:\/\/www.fda.gov\/news-events\/press-announcements\/fda-approves-first-gene-therapy-treat-adults-hemophilia-b\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA por su sigla en ingl\u00e9s) aprob\u00f3 el etranacogene dezaparvovec-drlb (HEMGENIX), la primera terapia g\u00e9nica de administraci\u00f3n \u00fanica para adultos con hemofilia B que re\u00fanen los requisitos para recibirla. La terapia fue aprobada para el tratamiento de adultos con hemofilia B que actualmente utilizan terapia profil\u00e1ctica con factor IX o que tienen un historial actual o previo de hemorragias que ponen en peligro la vida, o que han tenido episodios hemorr\u00e1gicos espont\u00e1neos graves y repetidos.<\/p>\n","protected":false},"author":13,"featured_media":30516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[174,196],"tags":[],"search-category":[85],"class_list":["post-50600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ultima-hora","category-noticias-medicas","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Primer f\u00e1rmaco de terapia g\u00e9nica para la hemofilia B aprobado por la FDA | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primer f\u00e1rmaco de terapia g\u00e9nica para la hemofilia B aprobado por la FDA\" \/>\n<meta property=\"og:description\" content=\"La Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA por su sigla en ingl\u00e9s) aprob\u00f3 el etranacogene dezaparvovec-drlb (HEMGENIX), la primera terapia g\u00e9nica de administraci\u00f3n \u00fanica para adultos con hemofilia B que re\u00fanen los requisitos para recibirla. La terapia fue aprobada para el tratamiento de adultos con hemofilia B que actualmente utilizan terapia profil\u00e1ctica con factor IX o que tienen un historial actual o previo de hemorragias que ponen en peligro la vida, o que han tenido episodios hemorr\u00e1gicos espont\u00e1neos graves y repetidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-23T14:37:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-10T13:44:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2501\" \/>\n\t<meta property=\"og:image:height\" content=\"1459\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Primer f\u00e1rmaco de terapia g\u00e9nica para la hemofilia B aprobado por la FDA\",\"datePublished\":\"2022-11-23T14:37:46+00:00\",\"dateModified\":\"2024-04-10T13:44:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/\"},\"wordCount\":150,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WFH-statement-News-SP.png\",\"articleSection\":[\"Noticias de \u00faltima hora\",\"Noticias m\u00e9dicas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/\",\"name\":\"Primer f\u00e1rmaco de terapia g\u00e9nica para la hemofilia B aprobado por la FDA | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WFH-statement-News-SP.png\",\"datePublished\":\"2022-11-23T14:37:46+00:00\",\"dateModified\":\"2024-04-10T13:44:50+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WFH-statement-News-SP.png\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WFH-statement-News-SP.png\",\"width\":2501,\"height\":1459,\"caption\":\"lgoo\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Primer f\u00e1rmaco de terapia g\u00e9nica para la hemofilia B aprobado por la FDA | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/","og_locale":"es_ES","og_type":"article","og_title":"Primer f\u00e1rmaco de terapia g\u00e9nica para la hemofilia B aprobado por la FDA","og_description":"La Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA por su sigla en ingl\u00e9s) aprob\u00f3 el etranacogene dezaparvovec-drlb (HEMGENIX), la primera terapia g\u00e9nica de administraci\u00f3n \u00fanica para adultos con hemofilia B que re\u00fanen los requisitos para recibirla. La terapia fue aprobada para el tratamiento de adultos con hemofilia B que actualmente utilizan terapia profil\u00e1ctica con factor IX o que tienen un historial actual o previo de hemorragias que ponen en peligro la vida, o que han tenido episodios hemorr\u00e1gicos espont\u00e1neos graves y repetidos.","og_url":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2022-11-23T14:37:46+00:00","article_modified_time":"2024-04-10T13:44:50+00:00","og_image":[{"width":2501,"height":1459,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","type":"image\/png"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Primer f\u00e1rmaco de terapia g\u00e9nica para la hemofilia B aprobado por la FDA","datePublished":"2022-11-23T14:37:46+00:00","dateModified":"2024-04-10T13:44:50+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/"},"wordCount":150,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","articleSection":["Noticias de \u00faltima hora","Noticias m\u00e9dicas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/","url":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/","name":"Primer f\u00e1rmaco de terapia g\u00e9nica para la hemofilia B aprobado por la FDA | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","datePublished":"2022-11-23T14:37:46+00:00","dateModified":"2024-04-10T13:44:50+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/primer-farmaco-de-terapia-genica-para-la-hemofilia-b-aprobado-por-la-fda\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","width":2501,"height":1459,"caption":"lgoo"},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/50600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=50600"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/50600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/30516"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=50600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=50600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=50600"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=50600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}