{"id":50384,"date":"2022-11-15T15:07:08","date_gmt":"2022-11-15T20:07:08","guid":{"rendered":"https:\/\/wfh.org\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/"},"modified":"2026-03-12T10:01:36","modified_gmt":"2026-03-12T14:01:36","slug":"cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/","title":{"rendered":"Cumbre mundial sobre atenci\u00f3n integral: Ya abierta la convocatoria para someter res\u00famenes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"50384\" class=\"elementor elementor-50384 elementor-50352\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eeec614 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eeec614\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41ad13d\" data-id=\"41ad13d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dd295e elementor-widget elementor-widget-text-editor\" data-id=\"5dd295e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La <a href=\"https:\/\/wfh.org\/es\/events-new\/cumbre-2023-de-la-fmh-sobre-atencion-integral-nuevos-avances-en-trastornos-de-la-coagulacion-y-temas-musculoesqueleticos-msk\/\" target=\"_blank\" rel=\"noopener\">Cumbre sobre atenci\u00f3n integral<\/a> ofrecer\u00e1 m\u00e1s de 40 horas de sesiones de educaci\u00f3n continua en tres segmentos: musculoesquel\u00e9tico, m\u00e9dico y multidisciplinario. Contar\u00e1 con ponentes de clase mundial para sus plenarias y sesiones, y los asistentes tendr\u00e1n la oportunidad de participar en sesiones interactivas, paneles de discusi\u00f3n e innovadores simposios de la industria.<\/p>\n<p>La FMH anima a las partes interesadas a someter a consideraci\u00f3n res\u00famenes que aborden soluciones e intervenciones relacionadas con los segmentos de la Cumbre (para obtener m\u00e1s informaci\u00f3n sobre el contenido consulte nuestro <a href=\"https:\/\/wfh.org\/es\/events-new\/cumbre-2023-de-la-fmh-sobre-atencion-integral-nuevos-avances-en-trastornos-de-la-coagulacion-y-temas-musculoesqueleticos-msk\/#glance\" target=\"_blank\" rel=\"noopener\">Programa de una ojeada<\/a>). Animamos a los siguientes miembros de la comunidad internacional de trastornos de la coagulaci\u00f3n a someter a consideraci\u00f3n sus trabajos: profesionales de la salud aliados en entornos acad\u00e9micos y comunitarios; proveedores y organizaciones dedicados a la atenci\u00f3n m\u00e9dica; y estudiantes que realicen trabajos nuevos e innovadores. Puede presentar su resumen en l\u00ednea f\u00e1cilmente haciendo <a href=\"https:\/\/www.abstractscorecard.com\/cfp\/submit\/login.asp?EventKey=VRNYEGLR\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a>. La convocatoria para someter res\u00famenes ya est\u00e1 abierta y se cerrar\u00e1 el 6 de febrero de 2023.<\/p>\n<p>La Cumbre mundial 2023 de la FMH sobre atenci\u00f3n integral: Nuevos avances en trastornos de la coagulaci\u00f3n y temas musculoesquel\u00e9ticos (MSK) ser\u00e1 coauspiciada por la Fundaci\u00f3n de la Hemofilia de Argentina. Esta cumbre mundial estar\u00e1 abierta a todos los miembros de la comunidad internacional de trastornos de la coagulaci\u00f3n y se realizar\u00e1 en persona, del 10 al 12 de mayo de 2023. Las sesiones se presentar\u00e1n en ingl\u00e9s. Para obtener m\u00e1s informaci\u00f3n haga <a href=\"https:\/\/wfh.org\/es\/events-new\/cumbre-2023-de-la-fmh-sobre-atencion-integral-nuevos-avances-en-trastornos-de-la-coagulacion-y-temas-musculoesqueleticos-msk\/\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a> o comun\u00edquese con la FMH a <a href=\"mailto:ccs2023@wfh.org\" target=\"_blank\" rel=\"noopener\">ccs2023@wfh.org<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d52f2 elementor-widget elementor-widget-image\" data-id=\"c2d52f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wfh.org\/events-new\/wfh-2023-comprehensive-care-summit-new-developments-in-bleeding-disorders-and-msk\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1400\" height=\"350\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/WFH-CCS-Registration-1400x350-f-ES.jpg\" class=\"attachment-full size-full wp-image-47685\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/WFH-CCS-Registration-1400x350-f-ES.jpg 1400w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/WFH-CCS-Registration-1400x350-f-ES-192x48.jpg 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/10\/WFH-CCS-Registration-1400x350-f-ES-768x192.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Cumbre mundial 2023 de la Federaci\u00f3n Mundial de Hemofilia (FMH) sobre atenci\u00f3n integral: Nuevos avances en trastornos de la coagulaci\u00f3n y temas musculoesquel\u00e9ticos (MSK) tendr\u00e1 lugar en persona el pr\u00f3ximo mes de mayo. Este evento internacional abarcar\u00e1 un segmento completo sobre temas musculoesquel\u00e9ticos dirigido a especialistas, y constituye una oportunidad \u00fanica para que los investigadores presenten su trabajo ante un p\u00fablico mundial de alto perfil. Ya est\u00e1 abierta la convocatoria a fin de someter a consideraci\u00f3n res\u00famenes para la Cumbre; si usted participa en actividades de investigaci\u00f3n, \u00a1presente su resumen!<\/p>\n","protected":false},"author":13,"featured_media":50381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[169,167,42],"tags":[],"search-category":[85],"class_list":["post-50384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-2","category-wfh-comprehensive-care-summit","category-wfh-msk-congress","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cumbre mundial sobre atenci\u00f3n integral: Ya abierta la convocatoria para someter res\u00famenes | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cumbre mundial sobre atenci\u00f3n integral: Ya abierta la convocatoria para someter res\u00famenes\" \/>\n<meta property=\"og:description\" content=\"La Cumbre mundial 2023 de la Federaci\u00f3n Mundial de Hemofilia (FMH) sobre atenci\u00f3n integral: Nuevos avances en trastornos de la coagulaci\u00f3n y temas musculoesquel\u00e9ticos (MSK) tendr\u00e1 lugar en persona el pr\u00f3ximo mes de mayo. Este evento internacional abarcar\u00e1 un segmento completo sobre temas musculoesquel\u00e9ticos dirigido a especialistas, y constituye una oportunidad \u00fanica para que los investigadores presenten su trabajo ante un p\u00fablico mundial de alto perfil. Ya est\u00e1 abierta la convocatoria a fin de someter a consideraci\u00f3n res\u00famenes para la Cumbre; si usted participa en actividades de investigaci\u00f3n, \u00a1presente su resumen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-15T20:07:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T14:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/CCS-Abscracts-header-SP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Cumbre mundial sobre atenci\u00f3n integral: Ya abierta la convocatoria para someter res\u00famenes\",\"datePublished\":\"2022-11-15T20:07:08+00:00\",\"dateModified\":\"2026-03-12T14:01:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/\"},\"wordCount\":283,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/CCS-Abscracts-header-SP.jpg\",\"articleSection\":[\"Events\",\"WFH Comprehensive Care Summit (CCS)\",\"WFH Musculoskeletal (MSK) Congress\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/\",\"name\":\"Cumbre mundial sobre atenci\u00f3n integral: Ya abierta la convocatoria para someter res\u00famenes | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/CCS-Abscracts-header-SP.jpg\",\"datePublished\":\"2022-11-15T20:07:08+00:00\",\"dateModified\":\"2026-03-12T14:01:36+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/CCS-Abscracts-header-SP.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/CCS-Abscracts-header-SP.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cumbre mundial sobre atenci\u00f3n integral: Ya abierta la convocatoria para someter res\u00famenes | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/","og_locale":"es_ES","og_type":"article","og_title":"Cumbre mundial sobre atenci\u00f3n integral: Ya abierta la convocatoria para someter res\u00famenes","og_description":"La Cumbre mundial 2023 de la Federaci\u00f3n Mundial de Hemofilia (FMH) sobre atenci\u00f3n integral: Nuevos avances en trastornos de la coagulaci\u00f3n y temas musculoesquel\u00e9ticos (MSK) tendr\u00e1 lugar en persona el pr\u00f3ximo mes de mayo. Este evento internacional abarcar\u00e1 un segmento completo sobre temas musculoesquel\u00e9ticos dirigido a especialistas, y constituye una oportunidad \u00fanica para que los investigadores presenten su trabajo ante un p\u00fablico mundial de alto perfil. Ya est\u00e1 abierta la convocatoria a fin de someter a consideraci\u00f3n res\u00famenes para la Cumbre; si usted participa en actividades de investigaci\u00f3n, \u00a1presente su resumen!","og_url":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2022-11-15T20:07:08+00:00","article_modified_time":"2026-03-12T14:01:36+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/CCS-Abscracts-header-SP.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Cumbre mundial sobre atenci\u00f3n integral: Ya abierta la convocatoria para someter res\u00famenes","datePublished":"2022-11-15T20:07:08+00:00","dateModified":"2026-03-12T14:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/"},"wordCount":283,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/CCS-Abscracts-header-SP.jpg","articleSection":["Events","WFH Comprehensive Care Summit (CCS)","WFH Musculoskeletal (MSK) Congress"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/","url":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/","name":"Cumbre mundial sobre atenci\u00f3n integral: Ya abierta la convocatoria para someter res\u00famenes | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/CCS-Abscracts-header-SP.jpg","datePublished":"2022-11-15T20:07:08+00:00","dateModified":"2026-03-12T14:01:36+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/cumbre-mundial-sobre-atencion-integral-ya-abierta-la-convocatoria-para-someter-resumenes\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/CCS-Abscracts-header-SP.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/11\/CCS-Abscracts-header-SP.jpg","width":1200,"height":627},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/50384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=50384"}],"version-history":[{"count":2,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/50384\/revisions"}],"predecessor-version":[{"id":173317,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/50384\/revisions\/173317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/50381"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=50384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=50384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=50384"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=50384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}