{"id":40678,"date":"2022-06-23T11:39:19","date_gmt":"2022-06-23T15:39:19","guid":{"rendered":"https:\/\/wfh.org\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/"},"modified":"2023-06-21T12:35:36","modified_gmt":"2023-06-21T16:35:36","slug":"la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/","title":{"rendered":"La FMH anunci\u00f3 los reconocimientos a los hermanamientos del a\u00f1o 2021"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"40678\" class=\"elementor elementor-40678 elementor-40592\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e3d91e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e3d91e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f6d0bf\" data-id=\"4f6d0bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f4878b elementor-widget elementor-widget-text-editor\" data-id=\"9f4878b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEl <a href=\"https:\/\/wfh.org\/es\/solicite-becas-y-subvenciones\/programa-de-hermanamiento\/\" target=\"_blank\" rel=\"noopener\">Programa de hermanamiento de la FMH<\/a> crea alianzas de colaboraci\u00f3n de corto plazo entre profesionales m\u00e9dicos o entre l\u00edderes juveniles y de pacientes, de pa\u00edses en v\u00edas de desarrollo con sus contrapartes de pa\u00edses mejor establecidos, durante un periodo de dos a cuatro a\u00f1os, con el prop\u00f3sito principal de mejorar las normas de atenci\u00f3n. El Programa de hermanamiento de la FMH facilita el conocimiento \u2018autosostenible\u2019 ayudando a las organizaciones a incrementar su aprendizaje para que ellas, a su vez, puedan compartir las mejores pr\u00e1cticas con otras personas en sus respectivos pa\u00edses y, en \u00faltima instancia, con otras organizaciones alrededor del mundo.\r\n\r\nLos premios a los hermanamientos del a\u00f1o 2021 se anunciaron durante el Congreso Mundial 2022 de la FMH realizado en Montreal, Canad\u00e1. Tres alianzas demostraron su resiliencia y capacidad de adaptaci\u00f3n durante un a\u00f1o m\u00e1s de pandemia, y refrendaron su compromiso constante a fin de mejorar la atenci\u00f3n y el tratamiento para personas con trastornos de la coagulaci\u00f3n en sus pa\u00edses.\r\n\r\nEl hermanamiento Palestina-Venezuela tuvo un a\u00f1o memorable, con una continua y estrecha colaboraci\u00f3n a nivel estrat\u00e9gico y operativo. Asimismo, las organizaciones trabajaron juntas en el desarrollo de la capacidad a fin de mejorar la estructura organizacional, la gobernanza y la recolecci\u00f3n de datos. Como parte del hermanamiento tambi\u00e9n realizaron actividades psicosociales y de creaci\u00f3n de conciencia entre m\u00e1s de 200 personas con trastornos de la coagulaci\u00f3n y sus familiares. Ahmed R. Al Kashif, de la Fundaci\u00f3n Palestina Porvenir para la Ni\u00f1ez, expres\u00f3 que \u201cmediante varios proyectos implementados de manera conjunta se refleja un impacto muy positivo en las vidas de los pacientes en Palestina.\u201d\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9e1229 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9e1229\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e039d46\" data-id=\"e039d46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3acd5b elementor-widget elementor-widget-image\" data-id=\"e3acd5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"400\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Palestine-Venezuela.jpg\" class=\"attachment-full size-full wp-image-40602\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Palestine-Venezuela.jpg 1200w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Palestine-Venezuela-192x64.jpg 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Palestine-Venezuela-768x256.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Hermanamiento Palestina-Venezuela<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75ef625 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75ef625\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31d9e04\" data-id=\"31d9e04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-532e582 elementor-widget elementor-widget-text-editor\" data-id=\"532e582\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEl hermanamiento Addis Abeba (Etiop\u00eda)-Mine\u00e1polis (EE. UU.) tambi\u00e9n demostr\u00f3 su habilidad para adaptarse a los desaf\u00edos presentados por la pandemia de COVID-19. Su dedicaci\u00f3n en Etiop\u00eda gener\u00f3 una maravillosa alianza, a pesar de muchos obst\u00e1culos imprevistos en ambos pa\u00edses. El equipo se mantuvo enfocado en la formaci\u00f3n de los profesionales de atenci\u00f3n m\u00e9dica, y en asegurarse de que los laboratorios estuvieran bien equipados para realizar pruebas diagn\u00f3sticas.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-554bf10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"554bf10\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f07d21e\" data-id=\"f07d21e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90619e6 elementor-widget elementor-widget-image\" data-id=\"90619e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"400\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Ethiopia-USA.jpg\" class=\"attachment-full size-full wp-image-40597\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Ethiopia-USA.jpg 1200w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Ethiopia-USA-192x64.jpg 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Ethiopia-USA-768x256.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Hermanamiento Addis Abeba (Etiop\u00eda)-Mine\u00e1polis (EE. UU.)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f20fb2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f20fb2e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a034b2\" data-id=\"2a034b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c46d14 elementor-widget elementor-widget-text-editor\" data-id=\"7c46d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa alianza Teher\u00e1n (Ir\u00e1n)-Mil\u00e1n (Italia) se ha enfocado en la adaptaci\u00f3n de materiales de capacitaci\u00f3n a las necesidades culturales, epidemiol\u00f3gicas y locales de Ir\u00e1n. En su \u00faltimo a\u00f1o, las \u00e1reas prioritarias fueron el desarrollo de la capacidad y el intercambio de experiencias sobre tratamiento de pacientes con hemofilia; inhibidores, y <a href=\"https:\/\/wfh.org\/es\/identificacion-y-diagnostico\/\">enfermedad de Von Willebrand (EVW)<\/a>. Gracias al hermanamiento fue posible lograr importantes avances en el diagn\u00f3stico preciso de personas con EVW mediante el uso de diferentes ensayos, todos ellos ahora disponibles en Teher\u00e1n. Los equipos en Teher\u00e1n y en Mil\u00e1n esperan continuar su relaci\u00f3n despu\u00e9s de concluido el hermanamiento.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd1210c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd1210c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c8706da\" data-id=\"c8706da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a46cc elementor-widget elementor-widget-image\" data-id=\"51a46cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"400\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Tehran-Milan.jpg\" class=\"attachment-full size-full wp-image-40612\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Tehran-Milan.jpg 1200w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Tehran-Milan-192x64.jpg 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Tehran-Milan-768x256.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Hermanamiento Teher\u00e1n (Ir\u00e1n)-Mil\u00e1n (Italia)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c407eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c407eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99fc266\" data-id=\"99fc266\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d25f5d elementor-widget elementor-widget-text-editor\" data-id=\"3d25f5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDurante el evento de hermanamiento, que se llev\u00f3 a cabo en el marco de su Congreso Mundial, la FMH tuvo el gusto de reconocer el apoyo continuo de Pfizer al Programa de hermanamiento, desde el 2001 hasta el 2022. El Programa ha tenido un impacto considerable a escala mundial, con 265 hermanamientos establecidos en 119 pa\u00edses.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab2aacd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab2aacd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce33c93\" data-id=\"ce33c93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8314cfc elementor-widget elementor-widget-image\" data-id=\"8314cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"400\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Pfizer.jpg\" class=\"attachment-full size-full wp-image-40607\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Pfizer.jpg 1200w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Pfizer-192x64.jpg 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Pfizer-768x256.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Durante el evento se reconoci\u00f3 el apoyo de Pfizer.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f1d1f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f1d1f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5bedc7\" data-id=\"c5bedc7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40a0d5b elementor-widget elementor-widget-text-editor\" data-id=\"40a0d5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tA nombre de la FMH, \u00a1felicitaciones a los ganadores de los Hermanamientos del a\u00f1o 2021!\r\n\r\nPara obtener m\u00e1s informaci\u00f3n sobre el Programa de hermanamiento de la FMH haga clic <a href=\"https:\/\/wfh.org\/es\/solicite-becas-y-subvenciones\/programa-de-hermanamiento\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.\r\n\r\n<em>El Programa de hermanamiento de la FMH recibe apoyo financiero exclusive de Pfizer.<\/em>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00a1La Federaci\u00f3n Mundial de Hemofilia (FMH) tiene el gusto de anunciar los premios a los hermanamientos del a\u00f1o 2021! El reconocimiento del Hermanamiento del a\u00f1o 2021 entre organizaciones de hemofilia corresponde a la alianza Palestina-Venezuela, y el premio al Hermanamiento del a\u00f1o 2021 entre centros de tratamiento de hemofilia lo comparten las alianzas Addis Abeba (Etiop\u00eda)-Mine\u00e1polis (EE. UU.) y Teher\u00e1n (Ir\u00e1n)-Mil\u00e1n (Italia).<\/p>\n","protected":false},"author":13,"featured_media":40617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[120],"tags":[],"search-category":[85],"class_list":["post-40678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programa-de-hermanamiento-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La FMH anunci\u00f3 los reconocimientos a los hermanamientos del a\u00f1o 2021 | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La FMH anunci\u00f3 los reconocimientos a los hermanamientos del a\u00f1o 2021\" \/>\n<meta property=\"og:description\" content=\"\u00a1La Federaci\u00f3n Mundial de Hemofilia (FMH) tiene el gusto de anunciar los premios a los hermanamientos del a\u00f1o 2021! El reconocimiento del Hermanamiento del a\u00f1o 2021 entre organizaciones de hemofilia corresponde a la alianza Palestina-Venezuela, y el premio al Hermanamiento del a\u00f1o 2021 entre centros de tratamiento de hemofilia lo comparten las alianzas Addis Abeba (Etiop\u00eda)-Mine\u00e1polis (EE. UU.) y Teher\u00e1n (Ir\u00e1n)-Mil\u00e1n (Italia).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-23T15:39:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-21T16:35:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Awards-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"La FMH anunci\u00f3 los reconocimientos a los hermanamientos del a\u00f1o 2021\",\"datePublished\":\"2022-06-23T15:39:19+00:00\",\"dateModified\":\"2023-06-21T16:35:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/\"},\"wordCount\":623,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/HWO-2021-Twins-of-the-Year-Awards-header.jpg\",\"articleSection\":[\"Programa de hermanamiento de la FMH\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/\",\"name\":\"La FMH anunci\u00f3 los reconocimientos a los hermanamientos del a\u00f1o 2021 | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/HWO-2021-Twins-of-the-Year-Awards-header.jpg\",\"datePublished\":\"2022-06-23T15:39:19+00:00\",\"dateModified\":\"2023-06-21T16:35:36+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/HWO-2021-Twins-of-the-Year-Awards-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/HWO-2021-Twins-of-the-Year-Awards-header.jpg\",\"width\":1200,\"height\":700},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La FMH anunci\u00f3 los reconocimientos a los hermanamientos del a\u00f1o 2021 | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/","og_locale":"es_ES","og_type":"article","og_title":"La FMH anunci\u00f3 los reconocimientos a los hermanamientos del a\u00f1o 2021","og_description":"\u00a1La Federaci\u00f3n Mundial de Hemofilia (FMH) tiene el gusto de anunciar los premios a los hermanamientos del a\u00f1o 2021! El reconocimiento del Hermanamiento del a\u00f1o 2021 entre organizaciones de hemofilia corresponde a la alianza Palestina-Venezuela, y el premio al Hermanamiento del a\u00f1o 2021 entre centros de tratamiento de hemofilia lo comparten las alianzas Addis Abeba (Etiop\u00eda)-Mine\u00e1polis (EE. UU.) y Teher\u00e1n (Ir\u00e1n)-Mil\u00e1n (Italia).","og_url":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2022-06-23T15:39:19+00:00","article_modified_time":"2023-06-21T16:35:36+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Awards-header.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"La FMH anunci\u00f3 los reconocimientos a los hermanamientos del a\u00f1o 2021","datePublished":"2022-06-23T15:39:19+00:00","dateModified":"2023-06-21T16:35:36+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/"},"wordCount":623,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Awards-header.jpg","articleSection":["Programa de hermanamiento de la FMH"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/","url":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/","name":"La FMH anunci\u00f3 los reconocimientos a los hermanamientos del a\u00f1o 2021 | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Awards-header.jpg","datePublished":"2022-06-23T15:39:19+00:00","dateModified":"2023-06-21T16:35:36+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/la-fmh-anuncio-los-reconocimientos-a-los-hermanamientos-del-ano-2021\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Awards-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/06\/HWO-2021-Twins-of-the-Year-Awards-header.jpg","width":1200,"height":700},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/40678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=40678"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/40678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/40617"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=40678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=40678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=40678"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=40678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}