{"id":27764,"date":"2020-08-04T19:30:40","date_gmt":"2020-08-04T23:30:40","guid":{"rendered":"https:\/\/wfh.org\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/"},"modified":"2024-04-21T12:41:36","modified_gmt":"2024-04-21T16:41:36","slug":"ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/","title":{"rendered":"Ya se public\u00f3 la 3a edici\u00f3n de las Gu\u00edas de la FMH para el tratamiento de la hemofilia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"27764\" class=\"elementor elementor-27764 elementor-16419\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e53cdd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e53cdd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec8db1f\" data-id=\"ec8db1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ca8461 elementor-widget elementor-widget-text-editor\" data-id=\"5ca8461\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\">Esta 3<sup>a<\/sup>\u00a0edici\u00f3n de las\u00a0<em>Gu\u00edas para el tratamiento de la hemofilia<\/em>, de la Federaci\u00f3n Mundial de Hemofilia (FMH), ofrece orientaci\u00f3n actualizada y recomendaciones pr\u00e1cticas sobre el diagn\u00f3stico y el tratamiento de la hemofilia, incluso el manejo de complicaciones musculoesquel\u00e9ticas e inhibidores, actualizaciones sobre diagn\u00f3stico de laboratorio y valoraciones gen\u00e9ticas, as\u00ed como nuevas recomendaciones sobre valoraci\u00f3n de resultados.<\/p>\r\n\r\n<p class=\"\">Documentadas con las mejores pruebas cient\u00edficas disponibles y complementadas con la opini\u00f3n de expertos y la preferencia de los pacientes, las m\u00e1s de 300 recomendaciones pr\u00e1cticas de estas gu\u00edas se elaboraron utilizando la metodolog\u00eda de\u00a0<em>Trustworthy Consensus-Based Statement\u00a0<\/em>(enunciados confiables acordados por consenso) a fin de garantizar orientaci\u00f3n fiable. El panel encargado de las gu\u00edas lo conformaron expertos en hemofilia de diversas especialidades cl\u00ednicas y regiones del mundo, as\u00ed como un 25% de personas con hemofilia y proveedores de cuidados.<\/p>\r\n\r\n<p class=\"\">Estas gu\u00edas de tratamiento de alta calidad, documentadas con pruebas cient\u00edficas y experiencia profesional, ofrecen un medio para cerrar la brecha que existe en las pr\u00e1cticas de tratamiento y atenci\u00f3n alrededor del mundo. Brindan un conjunto de recomendaciones pr\u00e1cticas cuyo objetivo es mejorar la calidad de la atenci\u00f3n a escala mundial, fomentar intervenciones m\u00e9dicas eficaces, y reducir las variaciones en el ejercicio de la medicina. En los casos en los que no se cuenta con pruebas adecuadas, estas gu\u00edas pueden estimular las investigaciones apropiadas.<\/p>\r\n\r\n<p class=\"\">La FMH agradece sinceramente a los cerca de 100 colaboradores que hicieron posible la elaboraci\u00f3n de estas gu\u00edas, todos bajo estrictas limitaciones de tiempo. Agradecemos particularmente a los expertos en la atenci\u00f3n de la hemofilia, a las personas con hemofilia y a los revisores que generosamente donaron su tiempo y experiencia a fin de garantizar que cada cap\u00edtulo alcanzara las m\u00e1ximas normas de calidad posibles. Como resultado de su generosidad podemos ofrecer a proveedores de atenci\u00f3n m\u00e9dica y pacientes de todo el mundo un valioso conjunto de recomendaciones sobre las cuales basar sus cuidados. Agradecemos igualmente a los revisores externos y a los colegas revisores del peri\u00f3dico\u00a0<em>Haemophilia<\/em>, quienes proporcionaron comentarios bajo las muy especiales circunstancias actuales de la crisis debida al COVID-19.<\/p>\r\n\r\n<p class=\"\">Si desea descargar las\u00a0<em>Gu\u00edas para el tratamiento de la hemofilia<\/em>, de la FMH, haga\u00a0<a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/hae.14046\" target=\"_blank\" rel=\"noopener noreferrer\">clic aqu\u00ed<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Esta 3a\u00a0edici\u00f3n de las\u00a0Gu\u00edas para el tratamiento de la hemofilia, de la Federaci\u00f3n Mundial de Hemofilia (FMH), ofrece orientaci\u00f3n actualizada y recomendaciones pr\u00e1cticas sobre el diagn\u00f3stico y el tratamiento de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":27759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[],"search-category":[],"class_list":["post-27764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ya se public\u00f3 la 3a edici\u00f3n de las Gu\u00edas de la FMH para el tratamiento de la hemofilia | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ya se public\u00f3 la 3a edici\u00f3n de las Gu\u00edas de la FMH para el tratamiento de la hemofilia\" \/>\n<meta property=\"og:description\" content=\"Esta 3a\u00a0edici\u00f3n de las\u00a0Gu\u00edas para el tratamiento de la hemofilia, de la Federaci\u00f3n Mundial de Hemofilia (FMH), ofrece orientaci\u00f3n actualizada y recomendaciones pr\u00e1cticas sobre el diagn\u00f3stico y el tratamiento de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-04T23:30:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-21T16:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/news-TG3ed-NowAvailable-Aug2020-ES.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Electra Rozakis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Electra Rozakis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/\"},\"author\":{\"name\":\"Electra Rozakis\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\"},\"headline\":\"Ya se public\u00f3 la 3a edici\u00f3n de las Gu\u00edas de la FMH para el tratamiento de la hemofilia\",\"datePublished\":\"2020-08-04T23:30:40+00:00\",\"dateModified\":\"2024-04-21T16:41:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/\"},\"wordCount\":415,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/news-TG3ed-NowAvailable-Aug2020-ES.png\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/\",\"name\":\"Ya se public\u00f3 la 3a edici\u00f3n de las Gu\u00edas de la FMH para el tratamiento de la hemofilia | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/news-TG3ed-NowAvailable-Aug2020-ES.png\",\"datePublished\":\"2020-08-04T23:30:40+00:00\",\"dateModified\":\"2024-04-21T16:41:36+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/news-TG3ed-NowAvailable-Aug2020-ES.png\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/news-TG3ed-NowAvailable-Aug2020-ES.png\",\"width\":768,\"height\":496},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\",\"name\":\"Electra Rozakis\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ya se public\u00f3 la 3a edici\u00f3n de las Gu\u00edas de la FMH para el tratamiento de la hemofilia | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/","og_locale":"es_ES","og_type":"article","og_title":"Ya se public\u00f3 la 3a edici\u00f3n de las Gu\u00edas de la FMH para el tratamiento de la hemofilia","og_description":"Esta 3a\u00a0edici\u00f3n de las\u00a0Gu\u00edas para el tratamiento de la hemofilia, de la Federaci\u00f3n Mundial de Hemofilia (FMH), ofrece orientaci\u00f3n actualizada y recomendaciones pr\u00e1cticas sobre el diagn\u00f3stico y el tratamiento de [&hellip;]","og_url":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2020-08-04T23:30:40+00:00","article_modified_time":"2024-04-21T16:41:36+00:00","og_image":[{"width":768,"height":496,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/news-TG3ed-NowAvailable-Aug2020-ES.png","type":"image\/png"}],"author":"Electra Rozakis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Electra Rozakis","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/"},"author":{"name":"Electra Rozakis","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887"},"headline":"Ya se public\u00f3 la 3a edici\u00f3n de las Gu\u00edas de la FMH para el tratamiento de la hemofilia","datePublished":"2020-08-04T23:30:40+00:00","dateModified":"2024-04-21T16:41:36+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/"},"wordCount":415,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/news-TG3ed-NowAvailable-Aug2020-ES.png","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/","url":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/","name":"Ya se public\u00f3 la 3a edici\u00f3n de las Gu\u00edas de la FMH para el tratamiento de la hemofilia | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/news-TG3ed-NowAvailable-Aug2020-ES.png","datePublished":"2020-08-04T23:30:40+00:00","dateModified":"2024-04-21T16:41:36+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/ya-se-publico-la-3a-edicion-de-las-guias-de-la-fmh-para-el-tratamiento-de-la-hemofilia\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/news-TG3ed-NowAvailable-Aug2020-ES.png","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/news-TG3ed-NowAvailable-Aug2020-ES.png","width":768,"height":496},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887","name":"Electra Rozakis"}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/27764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=27764"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/27764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/27759"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=27764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=27764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=27764"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=27764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}