{"id":26878,"date":"2022-02-10T10:16:09","date_gmt":"2022-02-10T15:16:09","guid":{"rendered":"https:\/\/wfh.org\/?p=26878"},"modified":"2024-04-15T08:45:45","modified_gmt":"2024-04-15T12:45:45","slug":"las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/","title":{"rendered":"Las sesiones de capacitaci\u00f3n del Programa de Ayuda Humanitaria de la FMH salvan vidas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"26878\" class=\"elementor elementor-26878 elementor-26580\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f5ef7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f5ef7f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f06de1\" data-id=\"6f06de1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6d7e12 elementor-widget elementor-widget-text-editor\" data-id=\"e6d7e12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La atenci\u00f3n sustentable es posible gracias a muchos factores, entre ellos la capacitaci\u00f3n. Se requiere un diagn\u00f3stico eficaz para que las personas con trastornos de la coagulaci\u00f3n (PCTC) puedan recibir la atenci\u00f3n que necesitan. La Federaci\u00f3n Mundial de Hemofilia (FMH) organiza sesiones de capacitaci\u00f3n peri\u00f3dicas en el marco de diferentes programas, entre ellos su <a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\" rel=\"noopener\">Programa de Ayuda Humanitaria<\/a>, con el prop\u00f3sito de ayudar a los proveedores de atenci\u00f3n m\u00e9dica a reconocer los signos de un trastorno de la coagulaci\u00f3n lo m\u00e1s temprano posible en la vida de una PCTC.<\/p>\n<p>En el caso de Ethan, un ni\u00f1o de tres a\u00f1os en Uganda, un diagn\u00f3stico precoz probablemente le ahorr\u00f3 una vida de discapacidad o incluso la muerte. Naci\u00f3 mediante parto instrumental e inmediatamente present\u00f3 s\u00edntomas relacionados con la hemofilia. El equipo de la cl\u00ednica obst\u00e9trica \u2013que hab\u00eda participado en un taller del Programa de Ayuda Humanitaria de la FMH, titulado <a href=\"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/\" target=\"_blank\" rel=\"noopener\">M\u00e9dicos comunitarios y proveedores de atenci\u00f3n especializada<\/a>\u2013 reconoci\u00f3 los signos y se puso en contacto con la Fundaci\u00f3n de Hemofilia de Uganda. Pronto se obtuvo un diagn\u00f3stico formal y Ethan empez\u00f3 a recibir factor donado proporcionado a trav\u00e9s del Programa de Ayuda Humanitaria de la FMH. Ahora recibe tratamiento profil\u00e1ctico y lleva una vida normal. Si bien el tratamiento r\u00e1pido es com\u00fan en casos en los que un(a) hermano(a) ya ha recibido un diagn\u00f3stico de trastorno de la coagulaci\u00f3n, es mucho menos frecuente en el caso de un primer hijo. La experiencia positiva de Ethan muestra la diferencia que la capacitaci\u00f3n puede marcar en la vida de una PCTC joven.<\/p>\n<p>Desde el 2015 se han donado a Uganda m\u00e1s de 10 millones de unidades internacionales (UI) de productos de tratamiento, a trav\u00e9s del Programa de Ayuda Humanitaria de la FMH. El a\u00f1o pasado se donaron cerca de 1.5 millones de UI de factor, y m\u00e1s de 34,000 mg de terapia sin factor de reemplazo. Para conocer m\u00e1s sobre el Programa de Ayuda Humanitaria de la FMH haga <a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23fb015 elementor-widget elementor-widget-heading\" data-id=\"23fb015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Acerca del Programa de Ayuda Humanitaria de la FMH<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bab117 elementor-widget elementor-widget-text-editor\" data-id=\"7bab117\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Programa de Ayuda Humanitaria de la FMH combate la falta de acceso a la atenci\u00f3n y el tratamiento ofreciendo un apoyo muy necesario a personas con trastornos de la coagulaci\u00f3n hereditarios en pa\u00edses en v\u00edas de desarrollo. Al proporcionar un flujo m\u00e1s previsible y sustentable de donaciones de ayuda humanitaria, el Programa de Ayuda Humanitaria de la FMH hace posible que los pacientes tengan acceso consistente y confiable al tratamiento y la atenci\u00f3n. Nada de esto ser\u00eda posible sin el generoso apoyo de Sanofi Genzyme y Sobi, nuestras Contribuyentes Visionarias Fundadoras; de Bayer y Roche, nuestras Contribuyentes Visionarias; de Grifols, nuestra Contribuyente de Liderazgo; y de nuestras Contribuyentes, CSL Behring y Takeda. Para obtener m\u00e1s informaci\u00f3n sobre el Programa de Ayuda Humanitaria de la FMH visite <a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\" rel=\"noopener\">www.treatmentforall.org<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-237af0f elementor-widget elementor-widget-image\" data-id=\"237af0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"786\" height=\"343\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png\" class=\"attachment-full size-full wp-image-28203\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png 786w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-192x84.png 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-768x335.png 768w\" sizes=\"(max-width: 786px) 100vw, 786px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La atenci\u00f3n sustentable es posible gracias a muchos factores, entre ellos la capacitaci\u00f3n. Se requiere un diagn\u00f3stico eficaz para que las personas con trastornos de la coagulaci\u00f3n (PCTC) puedan recibir la atenci\u00f3n que necesitan. La Federaci\u00f3n Mundial de Hemofilia (FMH) organiza sesiones de capacitaci\u00f3n peri\u00f3dicas en el marco de diferentes programas, entre ellos su Programa de Ayuda Humanitaria, con el prop\u00f3sito de ayudar a los proveedores de atenci\u00f3n m\u00e9dica a reconocer los signos de un trastorno de la coagulaci\u00f3n lo m\u00e1s temprano posible en la vida de una PCTC.<\/p>\n","protected":false},"author":13,"featured_media":26869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[186],"tags":[],"search-category":[85],"class_list":["post-26878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programa-de-ayuda-humanitaria-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Las sesiones de capacitaci\u00f3n del Programa de Ayuda Humanitaria de la FMH salvan vidas | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las sesiones de capacitaci\u00f3n del Programa de Ayuda Humanitaria de la FMH salvan vidas\" \/>\n<meta property=\"og:description\" content=\"La atenci\u00f3n sustentable es posible gracias a muchos factores, entre ellos la capacitaci\u00f3n. Se requiere un diagn\u00f3stico eficaz para que las personas con trastornos de la coagulaci\u00f3n (PCTC) puedan recibir la atenci\u00f3n que necesitan. La Federaci\u00f3n Mundial de Hemofilia (FMH) organiza sesiones de capacitaci\u00f3n peri\u00f3dicas en el marco de diferentes programas, entre ellos su Programa de Ayuda Humanitaria, con el prop\u00f3sito de ayudar a los proveedores de atenci\u00f3n m\u00e9dica a reconocer los signos de un trastorno de la coagulaci\u00f3n lo m\u00e1s temprano posible en la vida de una PCTC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-10T15:16:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-15T12:45:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/Ethan-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Las sesiones de capacitaci\u00f3n del Programa de Ayuda Humanitaria de la FMH salvan vidas\",\"datePublished\":\"2022-02-10T15:16:09+00:00\",\"dateModified\":\"2024-04-15T12:45:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/\"},\"wordCount\":524,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ethan-header.jpg\",\"articleSection\":[\"Programa de Ayuda Humanitaria de la FMH\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/\",\"name\":\"Las sesiones de capacitaci\u00f3n del Programa de Ayuda Humanitaria de la FMH salvan vidas | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ethan-header.jpg\",\"datePublished\":\"2022-02-10T15:16:09+00:00\",\"dateModified\":\"2024-04-15T12:45:45+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ethan-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ethan-header.jpg\",\"width\":640,\"height\":400},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las sesiones de capacitaci\u00f3n del Programa de Ayuda Humanitaria de la FMH salvan vidas | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/","og_locale":"es_ES","og_type":"article","og_title":"Las sesiones de capacitaci\u00f3n del Programa de Ayuda Humanitaria de la FMH salvan vidas","og_description":"La atenci\u00f3n sustentable es posible gracias a muchos factores, entre ellos la capacitaci\u00f3n. Se requiere un diagn\u00f3stico eficaz para que las personas con trastornos de la coagulaci\u00f3n (PCTC) puedan recibir la atenci\u00f3n que necesitan. La Federaci\u00f3n Mundial de Hemofilia (FMH) organiza sesiones de capacitaci\u00f3n peri\u00f3dicas en el marco de diferentes programas, entre ellos su Programa de Ayuda Humanitaria, con el prop\u00f3sito de ayudar a los proveedores de atenci\u00f3n m\u00e9dica a reconocer los signos de un trastorno de la coagulaci\u00f3n lo m\u00e1s temprano posible en la vida de una PCTC.","og_url":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2022-02-10T15:16:09+00:00","article_modified_time":"2024-04-15T12:45:45+00:00","og_image":[{"width":640,"height":400,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/Ethan-header.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Las sesiones de capacitaci\u00f3n del Programa de Ayuda Humanitaria de la FMH salvan vidas","datePublished":"2022-02-10T15:16:09+00:00","dateModified":"2024-04-15T12:45:45+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/"},"wordCount":524,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/Ethan-header.jpg","articleSection":["Programa de Ayuda Humanitaria de la FMH"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/","url":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/","name":"Las sesiones de capacitaci\u00f3n del Programa de Ayuda Humanitaria de la FMH salvan vidas | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/Ethan-header.jpg","datePublished":"2022-02-10T15:16:09+00:00","dateModified":"2024-04-15T12:45:45+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/las-sesiones-de-capacitacion-del-programa-de-ayuda-humanitaria-de-la-fmh-salvan-vidas\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/Ethan-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/02\/Ethan-header.jpg","width":640,"height":400},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/26878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=26878"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/26878\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/26869"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=26878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=26878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=26878"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=26878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}