{"id":15030,"date":"2021-02-19T09:00:00","date_gmt":"2021-02-19T14:00:00","guid":{"rendered":"https:\/\/wfh.org\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/"},"modified":"2024-04-22T09:36:43","modified_gmt":"2024-04-22T13:36:43","slug":"el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/","title":{"rendered":"El Programa de ayuda humanitaria de la FMH realiza sesi\u00f3n para m\u00e9dicos primarios y secundarios"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"15030\" class=\"elementor elementor-15030 elementor-4245\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10f0cb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10f0cb2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f447eb5\" data-id=\"f447eb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-392b3db elementor-widget elementor-widget-text-editor\" data-id=\"392b3db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En diciembre de 2020, el\u00a0<a href=\"https:\/\/www.wfh.org\/es\/programa-ayuda-humanitaria-fmh\" target=\"_blank\" rel=\"noopener noreferrer\">Programa de ayuda humanitaria de la FMH<\/a>\u00a0organiz\u00f3 una sesi\u00f3n cient\u00edfica para m\u00e9dicos primarios y secundarios, a fin de desarrollar la conciencia y los conocimientos sobre la hemofilia en Centro y Sudam\u00e9rica. El webinario forma parte de una serie de eventos en curso desarrollados por el Programa con el prop\u00f3sito de establecer contacto con m\u00e9dicos dedicados al tratamiento de trastornos de la coagulaci\u00f3n en pa\u00edses receptores de donaciones. El objetivo de esta serie es garantizar que la FMH entienda las necesidades de los m\u00e9dicos; que pueda proporcionarles las herramientas que necesitan para apoyar de la mejor manera a los pacientes identificados, y para la identificaci\u00f3n de nuevos pacientes; as\u00ed como para identificar a nuevos m\u00e9dicos que puedan apoyar en la atenci\u00f3n de la hemofilia.<\/p>\n<p>La \u201cSesi\u00f3n cient\u00edfica para m\u00e9dicos primarios y secundarios\u201d se realiz\u00f3 a fin de mejorar los conocimientos de la hemofilia relacionados con el diagn\u00f3stico cl\u00ednico mediante el historial y el examen f\u00edsico; reg\u00edmenes de tratamiento para hemorragias agudas y cr\u00f3nicas; y reconocimiento y tratamiento de complicaciones. Los temas de la agenda abarcaron la hemofilia como un diagn\u00f3stico diferencial en hemorragias prolongadas; diagn\u00f3stico cl\u00ednico y de laboratorio de la hemofilia; y tratamiento de la hemofilia con terapia de reemplazo de factor. El evento culmin\u00f3 con una sesi\u00f3n de preguntas y respuestas. Asistieron al webinario casi 80 participantes de 17 pa\u00edses.<\/p>\n<p>Los participantes fueron integrantes de dos grupos importantes de profesionales dedicados a la atenci\u00f3n de personas con hemofilia: M\u00e9dicos primarios que atienden a dichas personas en cl\u00ednicas y centros de salud locales, y m\u00e9dicos secundarios; este \u00faltimo grupo conformado por m\u00e9dicos que trabajan en hospitales, quienes no necesariamente son especialistas en hemofilia, sino m\u00e9dicos de admisiones, residentes y pasantes, pediatras, internistas y m\u00e9dicos de urgencias. La capacitaci\u00f3n de m\u00e9dicos secundarios, de manera que puedan reconocer los s\u00edntomas de la hemofilia, es totalmente indispensable para la comunidad de trastornos de la coagulaci\u00f3n, ya que el reconocimiento precoz del trastorno desemboca en el diagn\u00f3stico y el tratamiento proactivo, lo cual puede tener un enorme impacto en la calidad de vida de los pacientes.<\/p>\n<p>Las presentaciones estuvieron a cargo de los doctores Arlette Ru\u00edz-S\u00e1ez (Venezuela); Miguel Escobar (EE.\u00a0UU.); y Santiago Bonanad (Espa\u00f1a). Participaron igualmente\u00a0<a href=\"https:\/\/news.wfh.org\/es\/cesar-garrido-breve-biografia-del-nuevo-presidente-de-la-fmh\/\" target=\"_blank\" rel=\"noopener noreferrer\">Cesar Garrido<\/a>, presidente de la FMH; el doctor Glenn Pierce, PhD, vicepresidente m\u00e9dico de la FMH; y Barry Flynn, vicepresidente de finanzas de la FMH.<\/p>\n<p>El evento fue bien recibido por los asistentes, con una tasa de satisfacci\u00f3n general del 90%. Los comentarios se\u00f1alaron que la sesi\u00f3n cubri\u00f3 todos los temas relevantes para m\u00e9dicos primarios, reforz\u00f3 los conocimientos sobre la hemofilia, y se imparti\u00f3 con un lenguaje claro y sencillo. En general, los asistentes consideraron que los conocimientos que obtuvieron del webinario tendr\u00e1n un efecto inmediato en su capacidad para atender eficazmente a pacientes con trastornos de la coagulaci\u00f3n, ahora y en el futuro.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08735f8 elementor-widget elementor-widget-heading\" data-id=\"08735f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Acerca del Programa de Ayuda Humanitaria de la FMH<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59d976d elementor-widget elementor-widget-text-editor\" data-id=\"59d976d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Programa de ayuda humanitaria de la FMH mejora la falta de acceso a la atenci\u00f3n y el tratamiento ofreciendo un apoyo muy necesario a las personas con trastornos de la coagulaci\u00f3n hereditarios de pa\u00edses en v\u00edas de desarrollo. Al proporcionar un flujo m\u00e1s previsible y sustentable de donaciones de ayuda humanitaria, el Programa de ayuda humanitaria de la FMH hace posible que los pacientes tengan acceso al tratamiento y la atenci\u00f3n de manera consistente y confiable. Nada de esto habr\u00eda sido posible sin el generoso apoyo de Sanofi Genzyme y Sobi, nuestras contribuyentes visionarias fundadoras; de Bayer, nuestra contribuyente visionaria; de Grifols y Roche, nuestras contribuyentes l\u00edderes; y de nuestra contribuyente CSL Behring. Para obtener m\u00e1s informaci\u00f3n sobre el Programa de ayuda humanitaria de la FMH visite\u00a0<a href=\"http:\/\/www.treatmentforall.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.treatmentforall.org<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-372e2ac elementor-widget elementor-widget-image\" data-id=\"372e2ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"786\" height=\"343\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png\" class=\"attachment-full size-full wp-image-28203\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png 786w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-192x84.png 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-768x335.png 768w\" sizes=\"(max-width: 786px) 100vw, 786px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En diciembre de 2020, el Programa de ayuda humanitaria de la FMH organiz\u00f3 una sesi\u00f3n cient\u00edfica para m\u00e9dicos primarios y secundarios, a fin de desarrollar la conciencia y los conocimientos sobre la hemofilia en Centro y Sudam\u00e9rica. El webinario forma parte de una serie de eventos en curso desarrollados por el Programa con el prop\u00f3sito de establecer contacto con m\u00e9dicos dedicados al tratamiento de trastornos de la coagulaci\u00f3n en pa\u00edses receptores de donaciones. <\/p>\n","protected":false},"author":3,"featured_media":4253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[186],"tags":[],"search-category":[85],"class_list":["post-15030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programa-de-ayuda-humanitaria-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Programa de ayuda humanitaria de la FMH realiza sesi\u00f3n para m\u00e9dicos primarios y secundarios | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Programa de ayuda humanitaria de la FMH realiza sesi\u00f3n para m\u00e9dicos primarios y secundarios\" \/>\n<meta property=\"og:description\" content=\"En diciembre de 2020, el Programa de ayuda humanitaria de la FMH organiz\u00f3 una sesi\u00f3n cient\u00edfica para m\u00e9dicos primarios y secundarios, a fin de desarrollar la conciencia y los conocimientos sobre la hemofilia en Centro y Sudam\u00e9rica. El webinario forma parte de una serie de eventos en curso desarrollados por el Programa con el prop\u00f3sito de establecer contacto con m\u00e9dicos dedicados al tratamiento de trastornos de la coagulaci\u00f3n en pa\u00edses receptores de donaciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-19T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-22T13:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2021\/02\/HA-scientific-session-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Electra Rozakis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Electra Rozakis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/\"},\"author\":{\"name\":\"Electra Rozakis\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\"},\"headline\":\"El Programa de ayuda humanitaria de la FMH realiza sesi\u00f3n para m\u00e9dicos primarios y secundarios\",\"datePublished\":\"2021-02-19T14:00:00+00:00\",\"dateModified\":\"2024-04-22T13:36:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/\"},\"wordCount\":683,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/HA-scientific-session-header.jpg\",\"articleSection\":[\"Programa de Ayuda Humanitaria de la FMH\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/\",\"name\":\"El Programa de ayuda humanitaria de la FMH realiza sesi\u00f3n para m\u00e9dicos primarios y secundarios | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/HA-scientific-session-header.jpg\",\"datePublished\":\"2021-02-19T14:00:00+00:00\",\"dateModified\":\"2024-04-22T13:36:43+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/HA-scientific-session-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/HA-scientific-session-header.jpg\",\"width\":640,\"height\":400},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\",\"name\":\"Electra Rozakis\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Programa de ayuda humanitaria de la FMH realiza sesi\u00f3n para m\u00e9dicos primarios y secundarios | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/","og_locale":"es_ES","og_type":"article","og_title":"El Programa de ayuda humanitaria de la FMH realiza sesi\u00f3n para m\u00e9dicos primarios y secundarios","og_description":"En diciembre de 2020, el Programa de ayuda humanitaria de la FMH organiz\u00f3 una sesi\u00f3n cient\u00edfica para m\u00e9dicos primarios y secundarios, a fin de desarrollar la conciencia y los conocimientos sobre la hemofilia en Centro y Sudam\u00e9rica. El webinario forma parte de una serie de eventos en curso desarrollados por el Programa con el prop\u00f3sito de establecer contacto con m\u00e9dicos dedicados al tratamiento de trastornos de la coagulaci\u00f3n en pa\u00edses receptores de donaciones.","og_url":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2021-02-19T14:00:00+00:00","article_modified_time":"2024-04-22T13:36:43+00:00","og_image":[{"width":640,"height":400,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/02\/HA-scientific-session-header.jpg","type":"image\/jpeg"}],"author":"Electra Rozakis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Electra Rozakis","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/"},"author":{"name":"Electra Rozakis","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887"},"headline":"El Programa de ayuda humanitaria de la FMH realiza sesi\u00f3n para m\u00e9dicos primarios y secundarios","datePublished":"2021-02-19T14:00:00+00:00","dateModified":"2024-04-22T13:36:43+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/"},"wordCount":683,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/02\/HA-scientific-session-header.jpg","articleSection":["Programa de Ayuda Humanitaria de la FMH"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/","url":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/","name":"El Programa de ayuda humanitaria de la FMH realiza sesi\u00f3n para m\u00e9dicos primarios y secundarios | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/02\/HA-scientific-session-header.jpg","datePublished":"2021-02-19T14:00:00+00:00","dateModified":"2024-04-22T13:36:43+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/el-programa-de-ayuda-humanitaria-de-la-fmh-realiza-sesion-para-medicos-primarios-y-secundarios\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/02\/HA-scientific-session-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/02\/HA-scientific-session-header.jpg","width":640,"height":400},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887","name":"Electra Rozakis"}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/15030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=15030"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/15030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/4253"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=15030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=15030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=15030"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=15030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}