{"id":14865,"date":"2021-06-07T09:00:00","date_gmt":"2021-06-07T13:00:00","guid":{"rendered":"https:\/\/wfh.org\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/"},"modified":"2024-04-19T11:38:25","modified_gmt":"2024-04-19T15:38:25","slug":"el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/","title":{"rendered":"El 17o Congreso MSK de la FMH se realiza de manera virtual y rompe r\u00e9cord de asistencia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14865\" class=\"elementor elementor-14865 elementor-2847\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fbaedf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fbaedf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6eff967\" data-id=\"6eff967\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4178349 elementor-widget elementor-widget-text-editor\" data-id=\"4178349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El\u00a0<a href=\"https:\/\/www.wfh.org\/msk\/es\/inicio\" target=\"_blank\" rel=\"noopener noreferrer\">17<sup>o<\/sup>\u00a0Congreso internacional de la FMH sobre temas musculoesquel\u00e9ticos (MSK)<\/a>\u00a0\u2013que tuvo lugar del 3 al 7 de mayo de 2021\u2013 se realiz\u00f3 de manera virtual por primera vez. El evento reuni\u00f3 a un n\u00famero r\u00e9cord de 640 participantes de m\u00e1s de 80 pa\u00edses. Profesionales de los campos de cirug\u00eda ortop\u00e9dica, fisioterapia, hematolog\u00eda, enfermer\u00eda, psicolog\u00eda y trabajo social, as\u00ed como investigadores, pacientes y otros especialistas participaron de un s\u00f3lido programa que ofreci\u00f3 una mezcla de sesiones educativas, talleres interactivos, simposios de la industria, presentaci\u00f3n de art\u00edculos libres, sesiones de preguntas a expertos, y una galer\u00eda virtual de posters con autores de todo el mundo.<\/p>\n<p>El Congreso de este a\u00f1o fue singular de muchas maneras. El programa se inici\u00f3 en varios horarios, facilitando la participaci\u00f3n de asistentes de diversas zonas horarias mundiales. El Congreso tambi\u00e9n cont\u00f3 con cuatro talleres interactivos, cada uno con tres diferentes horarios para elegir. Asimismo, los participantes disfrutaron de otra primicia: interpretaci\u00f3n en vivo al \u00e1rabe, espa\u00f1ol, franc\u00e9s y ruso.<\/p>\n<p>El 17<sup>o<\/sup>\u00a0Congreso internacional de la FMH sobre temas MSK abri\u00f3 con las palabras de bienvenida de C\u00e9sar Garrido, presidente de la FMH; del doctor Glenn Pierce, PhD, vicepresidente m\u00e9dico de la FMH; y del doctor Gianluigi Pasta, presidente del Comit\u00e9 de la FMH sobre aspectos musculoesquel\u00e9ticos. Las participaciones incluyeron un emotivo tributo al doctor\u00a0<a href=\"https:\/\/news.wfh.org\/es\/la-fmh-lamenta-el-fallecimiento-del-doctor-axel-seuser\/\" target=\"_blank\" rel=\"noopener noreferrer\">Axel Seuser<\/a>, quien falleci\u00f3 repentinamente el a\u00f1o pasado.<\/p>\n<p>Las sesiones cient\u00edficas cubrieron varios acontecimientos importantes en el campo musculoesquel\u00e9tico. Una charla sobre sistemas de puntaje abord\u00f3, por primera vez durante un congreso MSK, las herramientas m\u00e1s utilizadas para la valoraci\u00f3n de pacientes con trastornos de la coagulaci\u00f3n. Se compararon y midieron cada una de las herramientas: im\u00e1genes de resonancia magn\u00e9tica, ultrasonido, an\u00e1lisis de movimiento en 3D y rayos X. La sesi\u00f3n sobre \u201cpre y poscirug\u00eda\u201d se aboc\u00f3 al importante papel que desempe\u00f1a cada miembro del equipo de atenci\u00f3n musculoesquel\u00e9tica: el fisioterapeuta, el cirujano ortopedista y, principalmente, el paciente.<\/p>\n<p>Dos sesiones educativas se dedicaron enteramente a cirujanos ortop\u00e9dicos y fisioterapeutas. La sesi\u00f3n\u00a0<em>Cirug\u00eda de reemplazo: Consejos y trucos<\/em>\u00a0se centr\u00f3 en articulaciones espec\u00edficas y fue presentada por l\u00edderes especialistas en codo, rodilla y tobillo. Una sesi\u00f3n sobre fisioterapia abord\u00f3 opciones que los especialistas pueden considerar antes de recurrir a la cirug\u00eda, tales como terapia manual, electroterapia, control del dolor, y otras herramientas y t\u00e9cnicas no costosas.<\/p>\n<p>La \u00faltima sesi\u00f3n educativa de la semana se enfoc\u00f3 al futuro de la atenci\u00f3n musculoesquel\u00e9tica en pacientes con hemofilia. Esa charla explor\u00f3 la manera en la que la tecnolog\u00eda \u201cpara llevarse puesta\u201d, la atenci\u00f3n m\u00e9dica a distancia, la medicina regenerativa, y el papel del cirujano ortop\u00e9dico como parte del equipo de atenci\u00f3n musculoesquel\u00e9tica marcar\u00e1n una extraordinaria diferencia en el futuro de los pacientes con hemofilia.<\/p>\n<p>Por primera vez durante un congreso MSK, los asistentes tuvieron la oportunidad de participar en una serie de talleres interactivos en torno a cuatro temas musculoesquel\u00e9ticos clave: valoraci\u00f3n cl\u00ednica, ultrasonido, terapia manual y casos cl\u00ednicos. Encabezados por l\u00edderes y moderadores expertos, cada taller se present\u00f3 en tres diferentes horarios a lo largo del d\u00eda a fin de facilitar la participaci\u00f3n de personas ubicadas en diferentes zonas horarias.<\/p>\n<p>Si no hubiera podido asistir al 17<sup>o<\/sup>\u00a0Congreso internacional de la FMH sobre temas MSK, \u00a1todav\u00eda est\u00e1 a tiempo de conocer lo que se perdi\u00f3! El contenido del Congreso estar\u00e1 disponible en l\u00ednea hasta el 18 de junio de 2021.\u00a0<a href=\"https:\/\/www.wfh.org\/msk\/es\/inicio\" target=\"_blank\" rel=\"noopener noreferrer\">Inscr\u00edbase hoy<\/a>\u00a0para tener acceso a todo el contenido educativo, registrarse a nuestros talleres, obtener sus cr\u00e9ditos de educaci\u00f3n m\u00e9dica continua, y dar un vistazo a nuestros res\u00famenes y a la galer\u00eda de posters. Nuestra plenaria y sesiones educativas, de la FMH y de presentaci\u00f3n de art\u00edculos libres tambi\u00e9n est\u00e1n disponibles en \u00e1rabe, espa\u00f1ol, franc\u00e9s y ruso.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n acerca del 17<sup>o<\/sup>\u00a0Congreso internacional de la FMH sobre temas musculoesquel\u00e9ticos (MSK) haga\u00a0<a href=\"https:\/\/www.wfh.org\/msk\/es\/inicio\" target=\"_blank\" rel=\"noopener noreferrer\">clic aqu\u00ed<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El 17o Congreso internacional de la FMH sobre temas musculoesquel\u00e9ticos (MSK) \u2013que tuvo lugar del 3 al 7 de mayo de 2021\u2013 se realiz\u00f3 de manera virtual por primera vez. El evento reuni\u00f3 a un n\u00famero r\u00e9cord de 640 participantes de m\u00e1s de 80 pa\u00edses.<\/p>\n","protected":false},"author":3,"featured_media":19564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[254,192],"tags":[],"search-category":[85],"class_list":["post-14865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wfh-msk-congress-es","category-eventos","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El 17o Congreso MSK de la FMH se realiza de manera virtual y rompe r\u00e9cord de asistencia | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El 17o Congreso MSK de la FMH se realiza de manera virtual y rompe r\u00e9cord de asistencia\" \/>\n<meta property=\"og:description\" content=\"El 17o Congreso internacional de la FMH sobre temas musculoesquel\u00e9ticos (MSK) \u2013que tuvo lugar del 3 al 7 de mayo de 2021\u2013 se realiz\u00f3 de manera virtual por primera vez. El evento reuni\u00f3 a un n\u00famero r\u00e9cord de 640 participantes de m\u00e1s de 80 pa\u00edses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-07T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-19T15:38:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/Placeholder-Result-V1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Electra Rozakis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Electra Rozakis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/\"},\"author\":{\"name\":\"Electra Rozakis\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\"},\"headline\":\"El 17o Congreso MSK de la FMH se realiza de manera virtual y rompe r\u00e9cord de asistencia\",\"datePublished\":\"2021-06-07T13:00:00+00:00\",\"dateModified\":\"2024-04-19T15:38:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/\"},\"wordCount\":722,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Placeholder-Result-V1.png\",\"articleSection\":[\"Congreso de la FMH sobre temas MSK\",\"Eventos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/\",\"name\":\"El 17o Congreso MSK de la FMH se realiza de manera virtual y rompe r\u00e9cord de asistencia | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Placeholder-Result-V1.png\",\"datePublished\":\"2021-06-07T13:00:00+00:00\",\"dateModified\":\"2024-04-19T15:38:25+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Placeholder-Result-V1.png\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Placeholder-Result-V1.png\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/622f4b0ed56b8e4a987dd20bef774887\",\"name\":\"Electra Rozakis\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El 17o Congreso MSK de la FMH se realiza de manera virtual y rompe r\u00e9cord de asistencia | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/","og_locale":"es_ES","og_type":"article","og_title":"El 17o Congreso MSK de la FMH se realiza de manera virtual y rompe r\u00e9cord de asistencia","og_description":"El 17o Congreso internacional de la FMH sobre temas musculoesquel\u00e9ticos (MSK) \u2013que tuvo lugar del 3 al 7 de mayo de 2021\u2013 se realiz\u00f3 de manera virtual por primera vez. El evento reuni\u00f3 a un n\u00famero r\u00e9cord de 640 participantes de m\u00e1s de 80 pa\u00edses.","og_url":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2021-06-07T13:00:00+00:00","article_modified_time":"2024-04-19T15:38:25+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/Placeholder-Result-V1.png","type":"image\/png"}],"author":"Electra Rozakis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Electra Rozakis","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/"},"author":{"name":"Electra Rozakis","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887"},"headline":"El 17o Congreso MSK de la FMH se realiza de manera virtual y rompe r\u00e9cord de asistencia","datePublished":"2021-06-07T13:00:00+00:00","dateModified":"2024-04-19T15:38:25+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/"},"wordCount":722,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/Placeholder-Result-V1.png","articleSection":["Congreso de la FMH sobre temas MSK","Eventos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/","url":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/","name":"El 17o Congreso MSK de la FMH se realiza de manera virtual y rompe r\u00e9cord de asistencia | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/Placeholder-Result-V1.png","datePublished":"2021-06-07T13:00:00+00:00","dateModified":"2024-04-19T15:38:25+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/el-17o-congreso-msk-de-la-fmh-se-realiza-de-manera-virtual-y-rompe-record-de-asistencia\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/Placeholder-Result-V1.png","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/Placeholder-Result-V1.png","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/622f4b0ed56b8e4a987dd20bef774887","name":"Electra Rozakis"}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/14865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=14865"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/14865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/19564"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=14865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=14865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=14865"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=14865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}