{"id":141422,"date":"2025-04-16T09:00:44","date_gmt":"2025-04-16T13:00:44","guid":{"rendered":"https:\/\/wfh.org\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/"},"modified":"2025-05-06T09:38:07","modified_gmt":"2025-05-06T13:38:07","slug":"programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/","title":{"rendered":"Programa de hermanamiento de la FMH: Tres d\u00e9cadas de impacto"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"141422\" class=\"elementor elementor-141422 elementor-141017\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab074c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab074c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c9546eb\" data-id=\"c9546eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d22cdf6 elementor-widget elementor-widget-video\" data-id=\"d22cdf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/zq0OMajnFgo&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ebe52a elementor-widget elementor-widget-text-editor\" data-id=\"4ebe52a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desde su lanzamiento, el <a href=\"https:\/\/wfh.org\/es\/solicite-becas-y-subvenciones\/programa-de-hermanamiento\/\" target=\"_blank\" rel=\"noopener\">Programa de hermanamiento de la FMH<\/a> ha facilitado 275 hermanamientos, cada uno de ellos enfocado en desarrollar capacidad, mejorar la atenci\u00f3n, y ampliar el acceso a diagn\u00f3stico y tratamiento. Estas alianzas han perfeccionado el diagn\u00f3stico y la experiencia m\u00e9dica, incrementado la participaci\u00f3n del gobierno y generado actividades de cabildeo m\u00e1s eficaces. Hay dos tipos de programas de hermanamiento: entre centros de tratamiento de hemofilia (CTH) y entre organizaciones de hemofilia. Ambos funcionan hermanando un centro u organizaci\u00f3n incipiente con una contraparte bien establecida a fin de intercambiar conocimientos y experiencias.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5c808f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c808f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f5742fc\" data-id=\"f5742fc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd65a4e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"dd65a4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-quote-left\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 256h-80v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8c-88.4 0-160 71.6-160 160v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48zm-288 0H96v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8C71.6 32 0 103.6 0 192v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2844060\" data-id=\"2844060\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e1b4d1 elementor-widget elementor-widget-heading\" data-id=\"7e1b4d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cuando [personas con hemofilia que han tenido un hijo con hemofilia observan que] alguien proveniente de un pa\u00eds desarrollado los visita, creo que les llega al coraz\u00f3n\u2026 hay personas que se ocupan de nosotros, que est\u00e1n listas para apoyar nuestros programas.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7792cc4 elementor-widget elementor-widget-heading\" data-id=\"7792cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u2014Agnes Kisakye, secretaria ejecutiva, Fundaci\u00f3n de Hemofilia de Uganda<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-12edc63 elementor-widget elementor-widget-text-editor\" data-id=\"12edc63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Al conectar a profesionales m\u00e9dicos y personas que viven con trastornos de la coagulaci\u00f3n en diferentes pa\u00edses, el programa fomenta un sentido de unidad mundial y aprendizaje mutuo. La doctora Beatrice Nolan, consultora en hematolog\u00eda pedi\u00e1trica de Salud Infantil Irlanda, comparti\u00f3 c\u00f3mo trabajar con un CTH en Am\u00e1n, Jordania, modific\u00f3 la perspectiva de su propio equipo sobre la capacidad de adaptaci\u00f3n y la atenci\u00f3n al paciente. Entre tanto, intercambios virtuales y presenciales con el CTH han ayudado a identificar brechas importantes en el tratamiento \u2013como la introducci\u00f3n de pruebas que permitieron diagnosticar inhibidores en dos ni\u00f1os con hemofilia B\u2013 y a desarrollar planes de atenci\u00f3n en respuesta a estas necesidades. Ian Winburb, director ejecutivo de asuntos m\u00e9dicos mundiales de Pfizer Specialty Care, afirma que \u201c[el hermanamiento] busca equilibrar las desigualdades que observamos en la atenci\u00f3n m\u00e9dica al reunir la experiencia de otros y compartirla con un sentido de comunidad\u201d.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d5f4117 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5f4117\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2fc1cb3\" data-id=\"2fc1cb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30bf559 elementor-widget elementor-widget-image\" data-id=\"30bf559\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-image-1-HTC-in-Uganda.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Twinning-image-1---HTC-in-Uganda\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQxMDM1LCJ1cmwiOiJodHRwczpcL1wvd2ZoLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcL1R3aW5uaW5nLWltYWdlLTEtSFRDLWluLVVnYW5kYS5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"394\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-image-1-HTC-in-Uganda.jpg\" class=\"attachment-full size-full wp-image-141035\" alt=\"A person with a bleeding disorder receiving care in Uganda.\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-image-1-HTC-in-Uganda.jpg 600w, https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-image-1-HTC-in-Uganda-164x108.jpg 164w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Una persona con un trastorno de la coagulaci\u00f3n recibe atenci\u00f3n en Uganda.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a866836\" data-id=\"a866836\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10c5451 elementor-widget elementor-widget-image\" data-id=\"10c5451\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-image-1-HTC-in-Jordan.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Twinning-image-1---HTC-in-Jordan\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQxMDI5LCJ1cmwiOiJodHRwczpcL1wvd2ZoLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcL1R3aW5uaW5nLWltYWdlLTEtSFRDLWluLUpvcmRhbi5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"536\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-image-1-HTC-in-Jordan.jpg\" class=\"attachment-full size-full wp-image-141029\" alt=\"At a hemophilia treatment centre (HTC) in Amman, Jordan\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-image-1-HTC-in-Jordan.jpg 600w, https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-image-1-HTC-in-Jordan-121x108.jpg 121w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">En un centro de tratamiento de hemofilia (CTH) en Am\u00e1n, Jordania.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-19b68b6 elementor-widget elementor-widget-spacer\" data-id=\"19b68b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d66433 elementor-widget elementor-widget-text-editor\" data-id=\"1d66433\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u00edderes como Dawn Rotellini, miembro del consejo directivo de la FMH y presidente del Comit\u00e9 de hermanamiento de organizaciones, enfatizan que el hermanamiento consiste en ayudar a los aliados en la situaci\u00f3n en la que se encuentran, y no en prescribir soluciones. Del mismo modo, el director ejecutivo de la Sociedad Irlandesa de Hemofilia, Brian O\u2019Mahony, afirm\u00f3 que \u201clo que el Programa de hermanamiento de la FMH hace es mostrar a la gente que [proporcionar atenci\u00f3n] no es labor de la FMH, sino toda nuestra labor.\u201d<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n acerca del Programa de hermanamiento de la FMH haga <a href=\"https:\/\/wfh.org\/es\/solicite-becas-y-subvenciones\/programa-de-hermanamiento\/\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a>.<\/p>\n<p><em>Desde su establecimiento, el Programa de hermanamiento de la FMH ha recibido apoyo exclusivo de Pfizer.<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Durante m\u00e1s de 30 a\u00f1os, el Programa de hermanamiento de la Federaci\u00f3n Mundial de Hemofilia (FMH) ha transformado la atenci\u00f3n para personas con trastornos de la coagulaci\u00f3n hereditarios alrededor del mundo. A trav\u00e9s de alianzas colaborativas entre organizaciones y centros de tratamiento de pa\u00edses desarrollados con sus contrapartes de pa\u00edses en v\u00edas de desarrollo, el programa ha fortalecido a centros de tratamiento, organizaciones de pacientes, y grupos juveniles en 119 pa\u00edses.<\/p>\n","protected":false},"author":13,"featured_media":141023,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[339,120],"tags":[],"search-category":[85],"class_list":["post-141422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured-3-es","category-programa-de-hermanamiento-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Programa de hermanamiento de la FMH: Tres d\u00e9cadas de impacto | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programa de hermanamiento de la FMH: Tres d\u00e9cadas de impacto\" \/>\n<meta property=\"og:description\" content=\"Durante m\u00e1s de 30 a\u00f1os, el Programa de hermanamiento de la Federaci\u00f3n Mundial de Hemofilia (FMH) ha transformado la atenci\u00f3n para personas con trastornos de la coagulaci\u00f3n hereditarios alrededor del mundo. A trav\u00e9s de alianzas colaborativas entre organizaciones y centros de tratamiento de pa\u00edses desarrollados con sus contrapartes de pa\u00edses en v\u00edas de desarrollo, el programa ha fortalecido a centros de tratamiento, organizaciones de pacientes, y grupos juveniles en 119 pa\u00edses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-16T13:00:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T13:38:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Programa de hermanamiento de la FMH: Tres d\u00e9cadas de impacto\",\"datePublished\":\"2025-04-16T13:00:44+00:00\",\"dateModified\":\"2025-05-06T13:38:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/\"},\"wordCount\":482,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Twinning-header.jpg\",\"articleSection\":[\"Featured 3 - ES\",\"Programa de hermanamiento de la FMH\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/\",\"name\":\"Programa de hermanamiento de la FMH: Tres d\u00e9cadas de impacto | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Twinning-header.jpg\",\"datePublished\":\"2025-04-16T13:00:44+00:00\",\"dateModified\":\"2025-05-06T13:38:07+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Twinning-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Twinning-header.jpg\",\"width\":1200,\"height\":627,\"caption\":\"WFH Twinning Program: three decades of impact\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Programa de hermanamiento de la FMH: Tres d\u00e9cadas de impacto | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/","og_locale":"es_ES","og_type":"article","og_title":"Programa de hermanamiento de la FMH: Tres d\u00e9cadas de impacto","og_description":"Durante m\u00e1s de 30 a\u00f1os, el Programa de hermanamiento de la Federaci\u00f3n Mundial de Hemofilia (FMH) ha transformado la atenci\u00f3n para personas con trastornos de la coagulaci\u00f3n hereditarios alrededor del mundo. A trav\u00e9s de alianzas colaborativas entre organizaciones y centros de tratamiento de pa\u00edses desarrollados con sus contrapartes de pa\u00edses en v\u00edas de desarrollo, el programa ha fortalecido a centros de tratamiento, organizaciones de pacientes, y grupos juveniles en 119 pa\u00edses.","og_url":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2025-04-16T13:00:44+00:00","article_modified_time":"2025-05-06T13:38:07+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-header.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Programa de hermanamiento de la FMH: Tres d\u00e9cadas de impacto","datePublished":"2025-04-16T13:00:44+00:00","dateModified":"2025-05-06T13:38:07+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/"},"wordCount":482,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-header.jpg","articleSection":["Featured 3 - ES","Programa de hermanamiento de la FMH"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/","url":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/","name":"Programa de hermanamiento de la FMH: Tres d\u00e9cadas de impacto | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-header.jpg","datePublished":"2025-04-16T13:00:44+00:00","dateModified":"2025-05-06T13:38:07+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/programa-de-hermanamiento-de-la-fmh-tres-decadas-de-impacto\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/04\/Twinning-header.jpg","width":1200,"height":627,"caption":"WFH Twinning Program: three decades of impact"},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/141422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=141422"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/141422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/141023"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=141422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=141422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=141422"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=141422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}