{"id":137801,"date":"2025-03-26T10:18:03","date_gmt":"2025-03-26T14:18:03","guid":{"rendered":"https:\/\/wfh.org\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/"},"modified":"2025-04-02T10:40:51","modified_gmt":"2025-04-02T14:40:51","slug":"declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/","title":{"rendered":"Declaraci\u00f3n de la FMH sobre recientes acontecimientos relativos a terapias para la hemofilia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"137801\" class=\"elementor elementor-137801 elementor-137430\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65bde93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65bde93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ea7954\" data-id=\"6ea7954\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dccc14d elementor-widget elementor-widget-text-editor\" data-id=\"dccc14d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A la Federaci\u00f3n Mundial de Hemofilia (FMH) le preocupa la reciente tendencia para suspender el desarrollo o la comercializaci\u00f3n de varias terapias para la hemofilia. Desde octubre de 2024 hemos observado los siguientes contratiempos:<\/p>\n<ul>\n<li><strong>Pfizer<\/strong> descontinu\u00f3 la comercializaci\u00f3n a escala mundial de <em>fidanacogene elaparvovec-dzkt<\/em>, una terapia g\u00e9nica para la hemofilia B.<\/li>\n<li><strong>Pfizer<\/strong> puso fin a su acuerdo de colaboraci\u00f3n y licencia con <strong>Sangamo Therapeutics<\/strong> para <em>giroctocogene fitelparvovec<\/em>, una terapia g\u00e9nica en fase de investigaci\u00f3n para la hemofilia A.<\/li>\n<li><strong>Spark Therapeutics<\/strong> detuvo la fase 3 de su ensayo cl\u00ednico con <em>dirloctocogene samoparvovec<\/em>, una terapia g\u00e9nica experimental para la hemofilia A, a favor de desarrollar la variante de un producto de FVIII.<\/li>\n<li><strong>Centessa Pharmaceuticals<\/strong> suspendi\u00f3 el desarrollo a escala mundial de <em>SerpinPC<\/em>, un inhibidor de la serina proteasa para la hemofilia B.<\/li>\n<\/ul>\n<p>Estas decisiones, basadas tanto en aspectos cient\u00edficos como en el potencial comercial, seg\u00fan las determinan las empresas farmac\u00e9uticas, retrasan los avances y dejan a las PCH con menos opciones de tratamiento. Si bien la FMH reconoce que requisitos de eficacia, seguridad, reglamentarios y de negocios gobiernan estas decisiones, la cancelaci\u00f3n de un producto nunca deber\u00eda interpretarse como debida a una falta de compromiso de parte de investigadores, profesionales m\u00e9dicos y la comunidad de pacientes en general. De hecho, todos los tratamientos potenciales son bienvenidos, siempre que sean seguros y eficaces, como un paso m\u00e1s hacia el logro de nuestra visi\u00f3n compartida de <em>Tratamiento para todos<\/em>. Por consiguiente exhortamos a empresas farmac\u00e9uticas, inversionistas, autoridades de salud y partes interesadas a lo siguiente:<\/p>\n<ol>\n<li><strong>Mantener su compromiso<\/strong> a fin de mejorar las opciones de tratamiento para la hemofilia y otros trastornos de la coagulaci\u00f3n hereditarios.<\/li>\n<li><strong>Continuar invirtiendo<\/strong> en actividades de investigaci\u00f3n y desarrollo para evitar interrupciones en los avances cient\u00edficos con miras a terapias curativas.<\/li>\n<li><strong>Preservar y compartir datos de ensayos cl\u00ednicos<\/strong> de tratamientos descontinuados, garantizando que no se pierdan conocimientos valiosos y aportaciones de pacientes, posiblemente a trav\u00e9s de una plataforma como el Registro de Terapia G\u00e9nica de la FMH.<\/li>\n<li><strong>Ser m\u00e1s creativos <\/strong>a fin de identificar formas mutuamente provechosas para proporcionar tratamiento a la mayor\u00eda del mundo.<\/li>\n<\/ol>\n<p>La industria farmac\u00e9utica y la comunidad inversionista deben reconocer su papel en el sostenimiento de los avances cient\u00edficos y el apoyo a las necesidades insatisfechas de la comunidad mundial de trastornos de la coagulaci\u00f3n hereditarios en su totalidad. Esperamos que atiendan este llamado a la acci\u00f3n con el prop\u00f3sito de mitigar mayores impactos en los tratamientos para PCH en todo el mundo.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A pesar de avances en la atenci\u00f3n, las personas con hemofilia (PCH) a\u00fan enfrentan importantes desaf\u00edos en todo el mundo. La falta de acceso a la atenci\u00f3n significa que dos tercios de la poblaci\u00f3n mundial con hemofilia carece de tratamiento. Incluso en pa\u00edses con ingresos m\u00e1s elevados, el tratamiento representa una carga pesada y se presentan hemorragias intraterap\u00e9uticas. Si bien terapias recientes han abordado algunas necesidades fundamentales, y las terapias g\u00e9nicas comercializadas para la hemofilia han mostrado resultados alentadores, aunque variables, una cura permanece lejana para la mayor\u00eda de las PCH. La innovaci\u00f3n continua es indispensable a fin de garantizar una mejor atenci\u00f3n para la comunidad mundial de trastornos de la coagulaci\u00f3n.<\/p>\n","protected":false},"author":13,"featured_media":30516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[121,339],"tags":[],"search-category":[85],"class_list":["post-137801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-declaraciones-y-notificaciones-de-la-fmh","category-featured-3-es","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Declaraci\u00f3n de la FMH sobre recientes acontecimientos relativos a terapias para la hemofilia | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Declaraci\u00f3n de la FMH sobre recientes acontecimientos relativos a terapias para la hemofilia\" \/>\n<meta property=\"og:description\" content=\"A pesar de avances en la atenci\u00f3n, las personas con hemofilia (PCH) a\u00fan enfrentan importantes desaf\u00edos en todo el mundo. La falta de acceso a la atenci\u00f3n significa que dos tercios de la poblaci\u00f3n mundial con hemofilia carece de tratamiento. Incluso en pa\u00edses con ingresos m\u00e1s elevados, el tratamiento representa una carga pesada y se presentan hemorragias intraterap\u00e9uticas. Si bien terapias recientes han abordado algunas necesidades fundamentales, y las terapias g\u00e9nicas comercializadas para la hemofilia han mostrado resultados alentadores, aunque variables, una cura permanece lejana para la mayor\u00eda de las PCH. La innovaci\u00f3n continua es indispensable a fin de garantizar una mejor atenci\u00f3n para la comunidad mundial de trastornos de la coagulaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-26T14:18:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T14:40:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2501\" \/>\n\t<meta property=\"og:image:height\" content=\"1459\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Declaraci\u00f3n de la FMH sobre recientes acontecimientos relativos a terapias para la hemofilia\",\"datePublished\":\"2025-03-26T14:18:03+00:00\",\"dateModified\":\"2025-04-02T14:40:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/\"},\"wordCount\":451,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WFH-statement-News-SP.png\",\"articleSection\":[\"Declaraciones y notificaciones de la FMH\",\"Featured 3 - ES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/\",\"name\":\"Declaraci\u00f3n de la FMH sobre recientes acontecimientos relativos a terapias para la hemofilia | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WFH-statement-News-SP.png\",\"datePublished\":\"2025-03-26T14:18:03+00:00\",\"dateModified\":\"2025-04-02T14:40:51+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WFH-statement-News-SP.png\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WFH-statement-News-SP.png\",\"width\":2501,\"height\":1459,\"caption\":\"lgoo\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Declaraci\u00f3n de la FMH sobre recientes acontecimientos relativos a terapias para la hemofilia | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/","og_locale":"es_ES","og_type":"article","og_title":"Declaraci\u00f3n de la FMH sobre recientes acontecimientos relativos a terapias para la hemofilia","og_description":"A pesar de avances en la atenci\u00f3n, las personas con hemofilia (PCH) a\u00fan enfrentan importantes desaf\u00edos en todo el mundo. La falta de acceso a la atenci\u00f3n significa que dos tercios de la poblaci\u00f3n mundial con hemofilia carece de tratamiento. Incluso en pa\u00edses con ingresos m\u00e1s elevados, el tratamiento representa una carga pesada y se presentan hemorragias intraterap\u00e9uticas. Si bien terapias recientes han abordado algunas necesidades fundamentales, y las terapias g\u00e9nicas comercializadas para la hemofilia han mostrado resultados alentadores, aunque variables, una cura permanece lejana para la mayor\u00eda de las PCH. La innovaci\u00f3n continua es indispensable a fin de garantizar una mejor atenci\u00f3n para la comunidad mundial de trastornos de la coagulaci\u00f3n.","og_url":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2025-03-26T14:18:03+00:00","article_modified_time":"2025-04-02T14:40:51+00:00","og_image":[{"width":2501,"height":1459,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","type":"image\/png"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Declaraci\u00f3n de la FMH sobre recientes acontecimientos relativos a terapias para la hemofilia","datePublished":"2025-03-26T14:18:03+00:00","dateModified":"2025-04-02T14:40:51+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/"},"wordCount":451,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","articleSection":["Declaraciones y notificaciones de la FMH","Featured 3 - ES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/","url":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/","name":"Declaraci\u00f3n de la FMH sobre recientes acontecimientos relativos a terapias para la hemofilia | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","datePublished":"2025-03-26T14:18:03+00:00","dateModified":"2025-04-02T14:40:51+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/declaracion-de-la-fmh-sobre-recientes-acontecimientos-relativos-a-terapias-para-la-hemofilia\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2022\/03\/WFH-statement-News-SP.png","width":2501,"height":1459,"caption":"lgoo"},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/137801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=137801"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/137801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/30516"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=137801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=137801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=137801"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=137801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}