{"id":131584,"date":"2025-01-20T09:00:56","date_gmt":"2025-01-20T14:00:56","guid":{"rendered":"https:\/\/wfh.org\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/"},"modified":"2025-01-21T09:52:40","modified_gmt":"2025-01-21T14:52:40","slug":"efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/","title":{"rendered":"Efectos a seis meses de la capacitaci\u00f3n mundial para ONM de la FMH: Establecimiento de organizaciones m\u00e1s s\u00f3lidas y comunidades colaborativas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"131584\" class=\"elementor elementor-131584 elementor-131176\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26074e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26074e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-287c162\" data-id=\"287c162\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dda9555 elementor-widget elementor-widget-text-editor\" data-id=\"dda9555\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La <a href=\"https:\/\/wfh.org\/es\/capacitacion\/#training-for-NMOs\" target=\"_blank\" rel=\"noopener\">capacitaci\u00f3n mundial para ONM de la FMH<\/a> de 2024 se enfoc\u00f3 en \u00e1reas clave, tales como colaboraci\u00f3n con partes interesadas, buena gobernanza, elaboraci\u00f3n de propuestas de proyectos, presupuestos e informes financieros, y monitoreo y evaluaci\u00f3n. En la capacitaci\u00f3n participaron 108 representantes de 91 pa\u00edses. Seis meses despu\u00e9s de la capacitaci\u00f3n se realiz\u00f3 una encuesta entre los participantes acerca del efecto que la capacitaci\u00f3n ha tenido en sus labores y sobre el valor de las herramientas que se pusieron a su disposici\u00f3n. Cuando se les pregunt\u00f3 sobre el impacto de la capacitaci\u00f3n en su ONM, 61% report\u00f3 un incremento en las actividades de cabildeo, 67% report\u00f3 mejor planificaci\u00f3n de proyectos, y 55% report\u00f3 mejor planeaci\u00f3n estrat\u00e9gica. En general, los comentarios fueron sumamente positivos; el 95% de los participantes consider\u00f3 que el contenido de la capacitaci\u00f3n fue relevante para su trabajo y el 79% inform\u00f3 que la capacitaci\u00f3n aument\u00f3 sus conocimientos.<\/p>\n<p>Por primera vez durante la capacitaci\u00f3n mundial para ONM de la FMH, los participantes tuvieron la oportunidad de mostrar el trabajo realizado por sus ONM a trav\u00e9s de presentaciones en posters. Esta nueva iniciativa anim\u00f3 a los participantes a aprender c\u00f3mo someter a consideraci\u00f3n res\u00famenes, presentar sus posters y compartir su trabajo con un p\u00fablico internacional. La nueva iniciativa fue un \u00e9xito; uno de los participantes coment\u00f3: \u201cMe encant\u00f3 ver los aspectos destacados [de otras ONM] para poder aprender de ellas. Esta fue una excelente iniciativa que espero contin\u00fae.\u201d<\/p>\n<p>A continuaci\u00f3n se citan algunos de los comentarios de participantes de diferentes ONM, a seis meses de haberse realizado la capacitaci\u00f3n mundial para ONM de la FMH.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d3187c elementor-widget elementor-widget-heading\" data-id=\"5d3187c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">L\u00edbano: Asociaci\u00f3n Libanesa de Hemofilia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-688267d elementor-widget elementor-widget-text-editor\" data-id=\"688267d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La ONM de L\u00edbano \u2013la asociaci\u00f3n Libanesa de Hemofilia\u2013 report\u00f3 mejores procesos de toma de decisiones que generaron mayor confianza y colaboraci\u00f3n entre los miembros. \u201cDespu\u00e9s de participar en la capacitaci\u00f3n para ONM de la FMH mejoramos la manera en la que tomamos decisiones, aclarando procesos e incluyendo a m\u00e1s miembros en las conversaciones\u201d, afirm\u00f3 uno de sus representantes. \u201cEstablecimos reuniones peri\u00f3dicas a fin de organizar mejor nuestras actividades y de garantizar la transparencia.\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c10853e elementor-widget elementor-widget-heading\" data-id=\"c10853e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Argentina: Fundaci\u00f3n de la Hemofilia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6086c59 elementor-widget elementor-widget-text-editor\" data-id=\"6086c59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un participante juvenil de la Fundaci\u00f3n de la Hemofilia, la ONM de Argentina, comparti\u00f3 con otros voluntarios lo que aprendi\u00f3 durante la capacitaci\u00f3n mundial para ONM de la FMH, luego de una capacitaci\u00f3n virtual centrada en la gesti\u00f3n de proyectos y la transferencia de conocimientos. \u201cJuntos realizamos ejercicios pr\u00e1cticos enfocados en el desarrollo de propuestas de proyectos, lo que nos permiti\u00f3 analizar el trabajo de la ONM y utilizar las herramientas adquiridas durante la capacitaci\u00f3n mundial para ONM de la FMH, como el sistema SMART para establecer objetivos\u201d, explic\u00f3.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1abffb7 elementor-widget elementor-widget-heading\" data-id=\"1abffb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bangladesh: Sociedad de Hemofilia de Bangladesh <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bee01b8 elementor-widget elementor-widget-text-editor\" data-id=\"bee01b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En el caso de la ONM de Bangladesh, la Sociedad de Hemofilia de Bangladesh, despu\u00e9s de la capacitaci\u00f3n, las pr\u00e1cticas presupuestarias y de informes financieros se tornaron m\u00e1s estructuradas y transparentes. Uno de los miembros de la ONM se\u00f1al\u00f3 que \u201cadoptamos un modelo de presupuesto detallado que clasifica los gastos para un seguimiento m\u00e1s claro. Adem\u00e1s, ahora proporcionamos informes financieros anuales a las partes interesadas, lo que mejora la rendici\u00f3n de cuentas y permite una mejor planificaci\u00f3n financiera para proyectos futuros.\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec6684e elementor-widget elementor-widget-heading\" data-id=\"ec6684e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">India: Federaci\u00f3n de Hemofilia de India<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aab436 elementor-widget elementor-widget-text-editor\" data-id=\"9aab436\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En la Federaci\u00f3n de Hemofilia de India, la ONM de la FMH en dicho pa\u00eds, despu\u00e9s de la capacitaci\u00f3n se instituyeron procesos de evaluaci\u00f3n peri\u00f3dicos que abarcan sesiones de retroalimentaci\u00f3n con los participantes luego de los eventos. \u201cDespu\u00e9s de nuestras conferencias y talleres nacionales realizamos encuestas a fin de valorar la satisfacci\u00f3n de los asistentes y recopilar sugerencias para mejorar\u201d, se\u00f1al\u00f3 un representante. Estos comentarios han sido fundamentales para perfeccionar eventos futuros con el prop\u00f3sito de satisfacer mejor las necesidades de la comunidad.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da876da elementor-widget elementor-widget-heading\" data-id=\"da876da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Togo: Asociaci\u00f3n Togolesa de Hemofilia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2bfd7 elementor-widget elementor-widget-text-editor\" data-id=\"7d2bfd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las oportunidades para establecer contactos que se presentaron durante la capacitaci\u00f3n mundial para ONM de la FMH tambi\u00e9n fueron sumamente valiosas. Un representante de la ONM de Togo \u2013la Asociaci\u00f3n Togolesa de Hemofilia\u2013 qued\u00f3 \u201cmotivado por las experiencias de otras organizaciones [que conoci\u00f3 al establecer contactos] para revitalizar actividades con el grupo juvenil y para establecer un grupo de madres.\u201d Este grupo recientemente inici\u00f3 un proyecto cuyo objetivo es incrementar la concientizaci\u00f3n e identificar nuevos pacientes, lo cual demuestra el impacto directo de la capacitaci\u00f3n en su comunidad.<\/p>\n<p>La capacitaci\u00f3n mundial para ONM de la FMH ha tenido un profundo impacto entre los participantes, equip\u00e1ndolos con habilidades y conocimientos a fin de mejorar las capacidades de sus ONM y atender mejor a sus respectivas comunidades de trastornos de la coagulaci\u00f3n hereditarios. Los comentarios positivos y las mejoras tangibles subrayan el papel fundamental de estas iniciativas de desarrollo de la capacidad con objeto de lograr atenci\u00f3n integral para todas las personas con trastornos de la coagulaci\u00f3n.<\/p>\n<p>Si desea obtener m\u00e1s informaci\u00f3n sobre la capacitaci\u00f3n para ONM de la FMH haga <a href=\"https:\/\/wfh.org\/es\/capacitacion\/#training-for-NMOs\" target=\"_blank\" rel=\"noopener\">clic aqu\u00ed<\/a>.<\/p>\n<p><em>Nuestro agradecimiento especial a Hemophilia of Georgia por su apoyo al Programa de liderazgo juvenil y a sus actividades durante la capacitaci\u00f3n mundial para ONM de la FMH realizada en 2024, en Madrid, Espa\u00f1a.\u00a0<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En abril de 2024, la Federaci\u00f3n Mundial de Hemofilia (FMH) llev\u00f3 a cabo en Madrid, Espa\u00f1a, la capacitaci\u00f3n mundial bienal para sus organizaciones nacionales miembros (ONM), la cual reuni\u00f3 a representantes de ONM de todo el mundo. Considerada a menudo como la \u201creuni\u00f3n familiar\u201d, la capacitaci\u00f3n para ONM ofrece a los participantes la oportunidad de trabajar, en grupos peque\u00f1os facilitados por expertos en la materia, temas prioritarios de desarrollo organizacional, a la vez que brinda un ambiente amigable en el que los asistentes pueden establecer contactos, compartir y aprender de las experiencias de los dem\u00e1s.<\/p>\n","protected":false},"author":13,"featured_media":131181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[330,339],"tags":[],"search-category":[85],"class_list":["post-131584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nmo-training-es","category-featured-3-es","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Efectos a seis meses de la capacitaci\u00f3n mundial para ONM de la FMH: Establecimiento de organizaciones m\u00e1s s\u00f3lidas y comunidades colaborativas | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Efectos a seis meses de la capacitaci\u00f3n mundial para ONM de la FMH: Establecimiento de organizaciones m\u00e1s s\u00f3lidas y comunidades colaborativas\" \/>\n<meta property=\"og:description\" content=\"En abril de 2024, la Federaci\u00f3n Mundial de Hemofilia (FMH) llev\u00f3 a cabo en Madrid, Espa\u00f1a, la capacitaci\u00f3n mundial bienal para sus organizaciones nacionales miembros (ONM), la cual reuni\u00f3 a representantes de ONM de todo el mundo. Considerada a menudo como la \u201creuni\u00f3n familiar\u201d, la capacitaci\u00f3n para ONM ofrece a los participantes la oportunidad de trabajar, en grupos peque\u00f1os facilitados por expertos en la materia, temas prioritarios de desarrollo organizacional, a la vez que brinda un ambiente amigable en el que los asistentes pueden establecer contactos, compartir y aprender de las experiencias de los dem\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-20T14:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-21T14:52:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2025\/01\/GNMOT-impact-article-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Efectos a seis meses de la capacitaci\u00f3n mundial para ONM de la FMH: Establecimiento de organizaciones m\u00e1s s\u00f3lidas y comunidades colaborativas\",\"datePublished\":\"2025-01-20T14:00:56+00:00\",\"dateModified\":\"2025-01-21T14:52:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/\"},\"wordCount\":928,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/GNMOT-impact-article-header.jpg\",\"articleSection\":[\"Capacitaci\u00f3n para organizaciones nacionales miembros\",\"Featured 3 - ES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/\",\"name\":\"Efectos a seis meses de la capacitaci\u00f3n mundial para ONM de la FMH: Establecimiento de organizaciones m\u00e1s s\u00f3lidas y comunidades colaborativas | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/GNMOT-impact-article-header.jpg\",\"datePublished\":\"2025-01-20T14:00:56+00:00\",\"dateModified\":\"2025-01-21T14:52:40+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/GNMOT-impact-article-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/GNMOT-impact-article-header.jpg\",\"width\":1200,\"height\":627,\"caption\":\"WFH Global NMO training six-month impact\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Efectos a seis meses de la capacitaci\u00f3n mundial para ONM de la FMH: Establecimiento de organizaciones m\u00e1s s\u00f3lidas y comunidades colaborativas | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/","og_locale":"es_ES","og_type":"article","og_title":"Efectos a seis meses de la capacitaci\u00f3n mundial para ONM de la FMH: Establecimiento de organizaciones m\u00e1s s\u00f3lidas y comunidades colaborativas","og_description":"En abril de 2024, la Federaci\u00f3n Mundial de Hemofilia (FMH) llev\u00f3 a cabo en Madrid, Espa\u00f1a, la capacitaci\u00f3n mundial bienal para sus organizaciones nacionales miembros (ONM), la cual reuni\u00f3 a representantes de ONM de todo el mundo. Considerada a menudo como la \u201creuni\u00f3n familiar\u201d, la capacitaci\u00f3n para ONM ofrece a los participantes la oportunidad de trabajar, en grupos peque\u00f1os facilitados por expertos en la materia, temas prioritarios de desarrollo organizacional, a la vez que brinda un ambiente amigable en el que los asistentes pueden establecer contactos, compartir y aprender de las experiencias de los dem\u00e1s.","og_url":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2025-01-20T14:00:56+00:00","article_modified_time":"2025-01-21T14:52:40+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/01\/GNMOT-impact-article-header.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Efectos a seis meses de la capacitaci\u00f3n mundial para ONM de la FMH: Establecimiento de organizaciones m\u00e1s s\u00f3lidas y comunidades colaborativas","datePublished":"2025-01-20T14:00:56+00:00","dateModified":"2025-01-21T14:52:40+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/"},"wordCount":928,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/01\/GNMOT-impact-article-header.jpg","articleSection":["Capacitaci\u00f3n para organizaciones nacionales miembros","Featured 3 - ES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/","url":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/","name":"Efectos a seis meses de la capacitaci\u00f3n mundial para ONM de la FMH: Establecimiento de organizaciones m\u00e1s s\u00f3lidas y comunidades colaborativas | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/01\/GNMOT-impact-article-header.jpg","datePublished":"2025-01-20T14:00:56+00:00","dateModified":"2025-01-21T14:52:40+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/efectos-a-seis-meses-de-la-capacitacion-mundial-para-onm-de-la-fmh-establecimiento-de-organizaciones-mas-solidas-y-comunidades-colaborativas\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/01\/GNMOT-impact-article-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2025\/01\/GNMOT-impact-article-header.jpg","width":1200,"height":627,"caption":"WFH Global NMO training six-month impact"},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/131584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=131584"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/131584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/131181"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=131584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=131584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=131584"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=131584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}