{"id":110138,"date":"2024-05-29T09:00:43","date_gmt":"2024-05-29T13:00:43","guid":{"rendered":"https:\/\/wfh.org\/?p=110138"},"modified":"2024-11-27T10:03:55","modified_gmt":"2024-11-27T15:03:55","slug":"un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam","status":"publish","type":"post","link":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/","title":{"rendered":"Un paso m\u00e1s cerca de la atenci\u00f3n sustentable en Vietnam"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"110138\" class=\"elementor elementor-110138 elementor-109960\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cbbde89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbbde89\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6858f2d\" data-id=\"6858f2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd69583 elementor-widget elementor-widget-video\" data-id=\"bd69583\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/V1N51QUjY4A&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-165b618 elementor-widget elementor-widget-text-editor\" data-id=\"165b618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\">La FMH ha implementado varias iniciativas en Vietnam, entre ellas el <a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\">Programa de Ayuda Humanitaria de la FMH<\/a>, y proyectos enfocados en el acceso a la atenci\u00f3n y el tratamiento y en el control de la calidad en el laboratorio, con el prop\u00f3sito de apoyar a la organizaci\u00f3n nacional miembro, a centros de tratamiento de hemofilia, a profesionales de atenci\u00f3n m\u00e9dica, y a PCTC y sus familiares. Esta estrategia ha hecho de la profilaxis una realidad para la comunidad de trastornos de la coagulaci\u00f3n en Vietnam.<\/p>\n<p class=\"\">La doctora Thi Mai Nguyen es directora del Centro de Hematolog\u00eda del Instituto Nacional de Hematolog\u00eda y Transfusi\u00f3n Sangu\u00ednea en Hanoi. Ha sido testigo de primera mano del transformador impacto que ha tenido el apoyo de la FMH, particularmente a trav\u00e9s de las donaciones de productos de tratamiento. Su equipo ha podido administrar tratamiento profil\u00e1ctico a pacientes, realizar cirug\u00edas necesarias y capacitar a especialistas sobre el tratamiento de pacientes durante emergencias y cirug\u00edas, quienes ahora proporcionan una atenci\u00f3n considerablemente mejor que la que estaba disponible anteriormente. Muchos pacientes ahora pueden autoinfundirse en casa, con lo que se reduce la necesidad de visitas frecuentes al hospital.<\/p>\n<p class=\"\">El doctor Bach Quoc Khanh, anterior director del Instituto Nacional de Hematolog\u00eda y Transfusi\u00f3n Sangu\u00ednea en Hanoi, tambi\u00e9n expresa una profunda gratitud por el apoyo de la FMH, el cual abarca donaciones de productos de factor, y actividades educativas y de capacitaci\u00f3n fundamentales. Explica que el apoyo de la FMH ha permitido a su equipo proporcionar una mejor atenci\u00f3n y est\u00e1 ayudando al pa\u00eds a avanzar en la trayectoria hacia la atenci\u00f3n sustentable.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-69943b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69943b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cc25eb6\" data-id=\"cc25eb6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a080a40 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a080a40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-quote-left\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 256h-80v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8c-88.4 0-160 71.6-160 160v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48zm-288 0H96v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8C71.6 32 0 103.6 0 192v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0fbc80c\" data-id=\"0fbc80c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d26fe8f elementor-widget elementor-widget-heading\" data-id=\"d26fe8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los pacientes que reciben profilaxis pueden llevar a casa el medicamento para su tratamiento. Los pacientes que se someten a cirug\u00eda en otros hospitales tienen acceso a factor de coagulaci\u00f3n para que puedan ser intervenidos de manera segura.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e2aa1e elementor-widget elementor-widget-heading\" data-id=\"2e2aa1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u2014Thi Mai Nguyen, directora del Centro de Hematolog\u00eda del Instituto Nacional de Hematolog\u00eda y Transfusi\u00f3n Sangu\u00ednea en Hanoi, Vietnam<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a61e52b elementor-widget elementor-widget-text-editor\" data-id=\"a61e52b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\">Una mejor atenci\u00f3n en Vietnam ha sido, literalmente, transformadora de vidas. Bao, un joven con hemofilia, presentaba hemorragias frecuentes en las rodillas, las cuales pon\u00edan en riesgo su movilidad. Gracias a las donaciones de factor pudo someterse a una cirug\u00eda de reemplazo de rodilla y, tres a\u00f1os despu\u00e9s, ahora puede caminar por su cuenta. Duy Anh Nguyen, un chico que sol\u00eda faltar a la escuela constantemente debido a sus hemorragias y que tem\u00eda jugar con sus amigos, ahora lleva una vida activa gracias al tratamiento profil\u00e1ctico hecho posible a trav\u00e9s del Programa de Ayuda Humanitaria de la FMH.<\/p>\n<p class=\"\">Desde el 2015, el Programa de Ayuda Humanitaria de la FMH ha donado a Vietnam m\u00e1s de 12.4 millones de unidades internacionales (UI) de productos de factor y m\u00e1s de 630,000 mg de terapia sin factor de reemplazo. Tan solo en 2023 se donaron m\u00e1s de 2.15 millones de UI de factor y cerca de 231,000 mg de terapia sin factor de reemplazo. Si desea obtener m\u00e1s informaci\u00f3n sobre el Programa de Ayuda Humanitaria de la FMH haga <a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\">clic aqu\u00ed<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4341679 elementor-widget elementor-widget-heading\" data-id=\"4341679\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Acerca del Programa de Ayuda Humanitaria de la FMH<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c39f95 elementor-widget elementor-widget-text-editor\" data-id=\"4c39f95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid mpc-row\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-866182d40814e51\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">El Programa de Ayuda Humanitaria de la FMH combate la falta de acceso a la atenci\u00f3n y el tratamiento ofreciendo un apoyo muy necesario a personas con trastornos de la coagulaci\u00f3n hereditarios en pa\u00edses en v\u00edas de desarrollo. Al proporcionar un flujo m\u00e1s previsible y sustentable de donaciones de ayuda humanitaria, el Programa de Ayuda Humanitaria de la FMH hace posible que los pacientes tengan acceso consistente y confiable al tratamiento y la atenci\u00f3n. Nada de esto ser\u00eda posible sin el generoso apoyo de Sanofi y Sobi, nuestras contribuyentes visionarias fundadoras; de Bayer, CSL Behring y Roche, nuestras contribuyentes visionarias; de Grifols, nuestra contribuyente de liderazgo; y de nuestras contribuyentes, Takeda y la Organizaci\u00f3n de Hemoderivados de Jap\u00f3n. Para obtener m\u00e1s informaci\u00f3n sobre el Programa de Ayuda Humanitaria de la FMH visite\u00a0<a href=\"https:\/\/wfh.org\/es\/ayuda-humanitaria\/\" target=\"_blank\" rel=\"noopener\">www.treatmentforall.org<\/a>.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fac52a elementor-widget elementor-widget-image\" data-id=\"5fac52a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"786\" height=\"343\" src=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png\" class=\"attachment-full size-full wp-image-28203\" alt=\"\" srcset=\"https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo.png 786w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-192x84.png 192w, https:\/\/wfh.org\/wp-content\/uploads\/2022\/01\/HA-logo-768x335.png 768w\" sizes=\"(max-width: 786px) 100vw, 786px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Un trastorno de la coagulaci\u00f3n puede afectar gravemente la vida de un ni\u00f1o, con frecuencia generando movilidad reducida y ausentismo escolar debidos a hemorragias articulares recurrentes. En Vietnam, la Federaci\u00f3n Mundial de Hemofilia (FMH) est\u00e1 marcando una importante diferencia en las vidas de ni\u00f1os \u2013y adultos\u2013 al proporcionar apoyo en forma de actividades de capacitaci\u00f3n y donaciones de productos de tratamiento, los cuales permiten a personas con trastornos de la coagulaci\u00f3n (PCTC) recibir tratamiento profil\u00e1ctico y llevar vidas sin hemorragias.<\/p>\n","protected":false},"author":13,"featured_media":109965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[335,186],"tags":[],"search-category":[85],"class_list":["post-110138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured-1-es","category-programa-de-ayuda-humanitaria-de-la-fmh","search-category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un paso m\u00e1s cerca de la atenci\u00f3n sustentable en Vietnam | FMH - Federaci\u00f3n Mundial de Hemofilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un paso m\u00e1s cerca de la atenci\u00f3n sustentable en Vietnam\" \/>\n<meta property=\"og:description\" content=\"Un trastorno de la coagulaci\u00f3n puede afectar gravemente la vida de un ni\u00f1o, con frecuencia generando movilidad reducida y ausentismo escolar debidos a hemorragias articulares recurrentes. En Vietnam, la Federaci\u00f3n Mundial de Hemofilia (FMH) est\u00e1 marcando una importante diferencia en las vidas de ni\u00f1os \u2013y adultos\u2013 al proporcionar apoyo en forma de actividades de capacitaci\u00f3n y donaciones de productos de tratamiento, los cuales permiten a personas con trastornos de la coagulaci\u00f3n (PCTC) recibir tratamiento profil\u00e1ctico y llevar vidas sin hemorragias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/\" \/>\n<meta property=\"og:site_name\" content=\"FMH - Federaci\u00f3n Mundial de Hemofilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wfhemophilia\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-29T13:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T15:03:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfh.org\/wp-content\/uploads\/2024\/05\/Vietnam-video-2021-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitch Semienchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch Semienchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/\"},\"author\":{\"name\":\"Mitch Semienchuk\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\"},\"headline\":\"Un paso m\u00e1s cerca de la atenci\u00f3n sustentable en Vietnam\",\"datePublished\":\"2024-05-29T13:00:43+00:00\",\"dateModified\":\"2024-11-27T15:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/\"},\"wordCount\":709,\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Vietnam-video-2021-header.jpg\",\"articleSection\":[\"Featured 1 - ES\",\"Programa de Ayuda Humanitaria de la FMH\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/\",\"name\":\"Un paso m\u00e1s cerca de la atenci\u00f3n sustentable en Vietnam | FMH - Federaci\u00f3n Mundial de Hemofilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Vietnam-video-2021-header.jpg\",\"datePublished\":\"2024-05-29T13:00:43+00:00\",\"dateModified\":\"2024-11-27T15:03:55+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/article\\\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Vietnam-video-2021-header.jpg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Vietnam-video-2021-header.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Collage de la visita a Vietnam del equipo de ayuda humanitaria de la FMH\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"name\":\"FMH - Federaci\u00f3n Mundial de Hemofilia\",\"description\":\"WFH - World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#organization\",\"name\":\"World Federation of Hemophilia\",\"url\":\"https:\\\/\\\/wfh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"contentUrl\":\"https:\\\/\\\/wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WFH-LOGO-ENGLISH.svg\",\"width\":210,\"height\":63,\"caption\":\"World Federation of Hemophilia\"},\"image\":{\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wfhemophilia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wfh.org\\\/es\\\/#\\\/schema\\\/person\\\/4aea5b13c1966452a640eef39423925b\",\"name\":\"Mitch Semienchuk\",\"sameAs\":[\"analytics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un paso m\u00e1s cerca de la atenci\u00f3n sustentable en Vietnam | FMH - Federaci\u00f3n Mundial de Hemofilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/","og_locale":"es_ES","og_type":"article","og_title":"Un paso m\u00e1s cerca de la atenci\u00f3n sustentable en Vietnam","og_description":"Un trastorno de la coagulaci\u00f3n puede afectar gravemente la vida de un ni\u00f1o, con frecuencia generando movilidad reducida y ausentismo escolar debidos a hemorragias articulares recurrentes. En Vietnam, la Federaci\u00f3n Mundial de Hemofilia (FMH) est\u00e1 marcando una importante diferencia en las vidas de ni\u00f1os \u2013y adultos\u2013 al proporcionar apoyo en forma de actividades de capacitaci\u00f3n y donaciones de productos de tratamiento, los cuales permiten a personas con trastornos de la coagulaci\u00f3n (PCTC) recibir tratamiento profil\u00e1ctico y llevar vidas sin hemorragias.","og_url":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/","og_site_name":"FMH - Federaci\u00f3n Mundial de Hemofilia","article_publisher":"https:\/\/www.facebook.com\/wfhemophilia\/","article_published_time":"2024-05-29T13:00:43+00:00","article_modified_time":"2024-11-27T15:03:55+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/05\/Vietnam-video-2021-header.jpg","type":"image\/jpeg"}],"author":"Mitch Semienchuk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitch Semienchuk","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/#article","isPartOf":{"@id":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/"},"author":{"name":"Mitch Semienchuk","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b"},"headline":"Un paso m\u00e1s cerca de la atenci\u00f3n sustentable en Vietnam","datePublished":"2024-05-29T13:00:43+00:00","dateModified":"2024-11-27T15:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/"},"wordCount":709,"publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/05\/Vietnam-video-2021-header.jpg","articleSection":["Featured 1 - ES","Programa de Ayuda Humanitaria de la FMH"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/","url":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/","name":"Un paso m\u00e1s cerca de la atenci\u00f3n sustentable en Vietnam | FMH - Federaci\u00f3n Mundial de Hemofilia","isPartOf":{"@id":"https:\/\/wfh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/#primaryimage"},"image":{"@id":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/#primaryimage"},"thumbnailUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/05\/Vietnam-video-2021-header.jpg","datePublished":"2024-05-29T13:00:43+00:00","dateModified":"2024-11-27T15:03:55+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/article\/un-paso-mas-cerca-de-la-atencion-sustentable-en-vietnam\/#primaryimage","url":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/05\/Vietnam-video-2021-header.jpg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2024\/05\/Vietnam-video-2021-header.jpg","width":1200,"height":627,"caption":"Collage de la visita a Vietnam del equipo de ayuda humanitaria de la FMH"},{"@type":"WebSite","@id":"https:\/\/wfh.org\/es\/#website","url":"https:\/\/wfh.org\/es\/","name":"FMH - Federaci\u00f3n Mundial de Hemofilia","description":"WFH - World Federation of Hemophilia","publisher":{"@id":"https:\/\/wfh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wfh.org\/es\/#organization","name":"World Federation of Hemophilia","url":"https:\/\/wfh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","contentUrl":"https:\/\/wfh.org\/wp-content\/uploads\/2021\/10\/WFH-LOGO-ENGLISH.svg","width":210,"height":63,"caption":"World Federation of Hemophilia"},"image":{"@id":"https:\/\/wfh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wfhemophilia\/"]},{"@type":"Person","@id":"https:\/\/wfh.org\/es\/#\/schema\/person\/4aea5b13c1966452a640eef39423925b","name":"Mitch Semienchuk","sameAs":["analytics"]}]}},"_links":{"self":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/110138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/comments?post=110138"}],"version-history":[{"count":0,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/posts\/110138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media\/109965"}],"wp:attachment":[{"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/media?parent=110138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/categories?post=110138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/tags?post=110138"},{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/wfh.org\/es\/wp-json\/wp\/v2\/search-category?post=110138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}